{"id":160208,"date":"2014-04-03T23:10:10","date_gmt":"2014-04-04T06:10:10","guid":{"rendered":"https:\/\/travelnevada.com\/business\/deposito-historico-de-lovelock\/"},"modified":"2014-04-03T23:10:10","modified_gmt":"2014-04-04T06:10:10","slug":"deposito-historico-de-lovelock","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/","title":{"rendered":"Dep\u00f3sito hist\u00f3rico de Lovelock"},"content":{"rendered":"<p>Construida en 1880, es la \u00fanica estaci\u00f3n que queda de una serie de casas residenciales de dos pisos, estilo n\u00famero 2, construidas a lo largo del ferrocarril Southern Pacific. El edificio es propiedad de la ciudad de Lovelock y alberga varios negocios comerciales. A\u00f1adido al Registro Nacional el 14 de abril de 2004.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Construida en 1880, es la \u00fanica estaci\u00f3n que queda de una serie de casas residenciales de dos pisos, estilo n\u00famero 2, construidas a lo largo del ferrocarril Southern Pacific.<\/p>\n","protected":false},"featured_media":113399,"menu_order":0,"template":"","meta":{"biz_address_line_1":"1005 W. Broadway Ave.","biz_address_line_2":"","biz_attached_media":[{"ID":113399,"id":113399,"title":"original-20140120lovelock2000120lrr.jpg","filename":"original-20140120lovelock2000120lrr.jpg","filesize":56913,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","link":"https:\/\/travelnevada.com\/es\/trains-railroads\/lovelock-depot\/attachment\/original-20140120lovelock2000120lrr-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"original-20140120lovelock2000120lrr-jpg-2","status":"inherit","uploaded_to":20014,"date":"2020-04-23 21:01:15","modified":"2020-04-23 21:01:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}}],"biz_city":"Lovelock","biz_country":"United States","biz_latitude":"40.179230","biz_longitude":"-118.47386","biz_phone_number":"(775) 273-7213","biz_postal_code":"89419","biz_state":"NV","biz_website":"http:\/\/loverslock.com\/points-of-interest-and-amenities\/lovelocks-historical-sites\/","biz_desktop_image":{"ID":113399,"id":113399,"title":"original-20140120lovelock2000120lrr.jpg","filename":"original-20140120lovelock2000120lrr.jpg","filesize":56913,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","link":"https:\/\/travelnevada.com\/es\/trains-railroads\/lovelock-depot\/attachment\/original-20140120lovelock2000120lrr-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"original-20140120lovelock2000120lrr-jpg-2","status":"inherit","uploaded_to":20014,"date":"2020-04-23 21:01:15","modified":"2020-04-23 21:01:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},"biz_image_link":{"title":"","url":"","target":"","0":""},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":113399,"id":113399,"title":"original-20140120lovelock2000120lrr.jpg","filename":"original-20140120lovelock2000120lrr.jpg","filesize":56913,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","link":"https:\/\/travelnevada.com\/es\/trains-railroads\/lovelock-depot\/attachment\/original-20140120lovelock2000120lrr-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"original-20140120lovelock2000120lrr-jpg-2","status":"inherit","uploaded_to":20014,"date":"2020-04-23 21:01:15","modified":"2020-04-23 21:01:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},"biz_map_use_custom_map_link":false},"categories":[42],"tn-amenities":[],"tn-regions":[45],"silos":[660],"class_list":["post-160208","business","type-business","status-publish","has-post-thumbnail","hentry","category-historical-interests"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dep\u00f3sito Lovelock<\/title>\n<meta name=\"description\" content=\"Construida en 1880, es la \u00fanica estaci\u00f3n que queda de una serie de casas residenciales de dos pisos, estilo n\u00famero 2, construidas a lo largo del ferrocarril Southern Pacific.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dep\u00f3sito Lovelock\" \/>\n<meta property=\"og:description\" content=\"Construida en 1880, es la \u00fanica estaci\u00f3n que queda de una serie de casas residenciales de dos pisos, estilo n\u00famero 2, construidas a lo largo del ferrocarril Southern Pacific.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"772\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dep\u00f3sito Lovelock","description":"Construida en 1880, es la \u00fanica estaci\u00f3n que queda de una serie de casas residenciales de dos pisos, estilo n\u00famero 2, construidas a lo largo del ferrocarril Southern Pacific.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/","og_locale":"es_ES","og_type":"article","og_title":"Dep\u00f3sito Lovelock","og_description":"Construida en 1880, es la \u00fanica estaci\u00f3n que queda de una serie de casas residenciales de dos pisos, estilo n\u00famero 2, construidas a lo largo del ferrocarril Southern Pacific.","og_url":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","og_image":[{"width":772,"height":434,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/","url":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/","name":"Dep\u00f3sito Lovelock","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","datePublished":"2014-04-04T06:10:10+00:00","description":"Construida en 1880, es la \u00fanica estaci\u00f3n que queda de una serie de casas residenciales de dos pisos, estilo n\u00famero 2, construidas a lo largo del ferrocarril Southern Pacific.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","width":772,"height":434},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/trenes-ferrocarriles\/deposito-historico-de-lovelock\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Dep\u00f3sito hist\u00f3rico de Lovelock"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":113399,"id":113399,"title":"original-20140120lovelock2000120lrr.jpg","filename":"original-20140120lovelock2000120lrr.jpg","filesize":56913,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","link":"https:\/\/travelnevada.com\/es\/trains-railroads\/lovelock-depot\/attachment\/original-20140120lovelock2000120lrr-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"original-20140120lovelock2000120lrr-jpg-2","status":"inherit","uploaded_to":20014,"date":"2020-04-23 21:01:15","modified":"2020-04-23 21:01:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}}],"primary_category":{"term_id":42,"name":"Historical Interests","slug":"historical-interests","term_group":0,"term_taxonomy_id":42,"taxonomy":"category","description":"","parent":240,"count":138,"filter":"raw"},"silo_name":"Trenes&amp; Ferrocarriles","is_rural":"true","category_slugs":"historical-interests","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/original-20140120lovelock2000120lrr.jpg"},"featured_image_alt":"","friendly_post_date":"April 03, 2014","selected_region":[{"term_id":45,"name":"Lovelock","slug":"lovelock","term_group":0,"term_taxonomy_id":45,"taxonomy":"tn-regions","description":"","parent":12,"count":51,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":0,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/113399"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=160208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=160208"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=160208"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=160208"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=160208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}