{"id":160454,"date":"2014-04-03T23:10:50","date_gmt":"2014-04-04T06:10:50","guid":{"rendered":"https:\/\/travelnevada.com\/business\/canon-eldorado-y-mina-techatticup\/"},"modified":"2025-08-04T17:37:43","modified_gmt":"2025-08-05T00:37:43","slug":"canon-eldorado-y-mina-techatticup","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/","title":{"rendered":"Ca\u00f1\u00f3n Eldorado y mina Techatticup"},"content":{"rendered":"\n<p>A medida que se desarrollaban los grandes auges del oro y la plata del siglo XIX, el sur de Nevada cosech\u00f3 su parte de la cosecha de lingotes. Para experimentarlo usted mismo, no busque m\u00e1s all\u00e1 del peque\u00f1o pueblo de Nelson, donde los pintorescos <a href=\"https:\/\/travelnevada.com\/es\/explorando-el-canon-eldorado\/\">Ca\u00f1\u00f3n Eldorado<\/a> y su hist\u00f3rica mina Techatticup sigue siendo la joya de la corona.<\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La mina de oro m\u00e1s antigua, m\u00e1s rica y m\u00e1s famosa del sur de Nevada, la mina Techatticup, espera a fot\u00f3grafos y aficionados a la historia en el impresionante y pintoresco Ca\u00f1\u00f3n Eldorado, a solo 45 minutos de Las Vegas.<\/p><\/blockquote><\/figure>\n\n<h2 class=\"wp-block-heading\">Historia minera del Ca\u00f1\u00f3n Eldorado<\/h2>\n\n<p>Primero que todo, \u00bfqu\u00e9 hay en un nombre? Aqu\u00ed unas cuantas cosas. Esta zona, ahora mencionada en el mapa como la \u201cciudad\u201d de Nelson, fue originalmente llamada Eldorado en 1775 por los espa\u00f1oles que descubrieron oro en esta regi\u00f3n, especialmente dentro de la mina Techatticup. Avanzamos cien a\u00f1os hasta mediados de la d\u00e9cada de 1880, cuando los buscadores y mineros inundaron el oeste de los Estados Unidos. Tras inundar completamente el ca\u00f1\u00f3n, estos buscadores se hicieron cargo de la mina Techatticup, ya establecida. Con raz\u00f3n, hubo algunos desacuerdos radicales sobre la propiedad, la gesti\u00f3n y la mano de obra, que convirtieron la zona en un aut\u00e9ntico Salvaje Oeste.<\/p>\n\n<p>Aunque es dif\u00edcil interpretar la peque\u00f1a comunidad de ritmo lento que vemos ahora como un municipio que alguna vez fue libertino, bullicioso y violento, los tiroteos y asesinatos eran tan frecuentes durante la d\u00e9cada de 1880 que se asum\u00eda que era parte de la vida cotidiana, tal como lo era en otros puestos avanzados de Nevada como <a href=\"https:\/\/travelnevada.com\/cities\/pioche\/\">Pioche<\/a>, que podr\u00e1s encontrar a pocas horas de camino. Lo que es a\u00fan m\u00e1s sorprendente es que mientras ocurr\u00eda esta anarqu\u00eda, la mina segu\u00eda produciendo millones de d\u00f3lares en oro, plata, cobre y plomo.<\/p>\n\n<p>Al igual que muchas de las primeras minas de oro de Nevada, el primer gran yacimiento de oro de Nevada fue fundado por desertores de la Guerra Civil, y la miner\u00eda estuvo activa desde 1858 hasta 1945. Durante este tiempo, tanto los soldados de la Uni\u00f3n como los de la Confederaci\u00f3n acamparon aqu\u00ed, asumiendo que un lugar tan aislado ser\u00eda el \u00faltimo lugar donde las autoridades militares los buscar\u00edan.<\/p>\n\n<p>Lamentablemente, las inundaciones repentinas en esta zona no son poco comunes y en 1974 se produjo un desastre. Con un muro de agua y escombros que se elev\u00f3 a casi 40 pies de altura, nueve personas murieron y gran parte del pueblo qued\u00f3 destruido.<\/p>\n\n<p>Los fot\u00f3grafos se sienten atra\u00eddos por esta zona debido a las incre\u00edbles oportunidades fotogr\u00e1ficas que ofrece este ca\u00f1\u00f3n, adem\u00e1s de estar en un sitio que parece un escenario de pel\u00edcula. De hecho, <a href=\"https:\/\/travelnevada.com\/es\/el-estado-plateado-en-la-pantalla-plateada\/\">varias pel\u00edculas<\/a> En la mina Techatticup se han realizado programas de televisi\u00f3n y sesiones fotogr\u00e1ficas para revistas. Algunos de estos incluyen el videojuego \u201cFallout: \u201cNew Las Vegas\u201d y una escena ic\u00f3nica de la pel\u00edcula de 2001, un fracaso de taquilla (y un cl\u00e1sico de culto repleto de estrellas con Kevin Costner), \u201c3.000 millas a Graceland\u201d.\u00a0<\/p>\n\n<div class=\"pro-tip --pro-tip\">\n    <div class=\"pro-tip__container\">\n        <div class=\"pro-tip__highlight-container\">\n                            <div class=\"pro-tip__background-text --spanish\"><\/div>\n                <p class=\"screen-reader-text\">Consejo experto de Travel Nevada<\/p>\n                \n            \n        <\/div>\n        <div class=\"pro-tip__star-divider star-divider --blue\">\n            <div class=\"side\"><\/div>\n            <div class=\"star\"><\/div>\n            <div class=\"side\"><\/div>\n        <\/div>\n        <div class=\"pro-tip__content-container\">\n            <div class=\"pro-tip__content\"><p><span style=\"font-weight: 400;\">Los visitantes de este sitio emblem\u00e1tico pueden ver los restos de un avi\u00f3n de combate de la era de Vietnam estrellado, con su cola sobresaliendo del suelo. Afortunadamente no es un lugar de accidente real, sino un objeto de la pel\u00edcula \u201c3.000 millas a Graceland\u201d. <\/span><\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n            <div class=\"pro-tip__star star1\"><\/div>\n            <div class=\"pro-tip__star star2\"><\/div>\n            <div class=\"pro-tip__star star3\"><\/div>\n            <div class=\"pro-tip__star star4\"><\/div>\n    <\/div>\n\n<p>Al visitar la zona, la visita guiada lo llevar\u00e1 por encima y por debajo de la tierra a trav\u00e9s de la mina y a la rica historia de la zona. Con temperaturas agradables de 70 grados durante todo el a\u00f1o, este fascinante recorrido lo llevar\u00e1 al interior de Techatticup Millsite y la mina Savage. Tambi\u00e9n se ofrecen excursiones a calas hist\u00f3ricas de aguas azules, donde los visitantes pueden alquilar una canoa o un kayak para dos personas para remar por las cercanas. <a href=\"https:\/\/travelnevada.com\/water-sports\/black-canyon-water-trail\/\">R\u00edo Colorado<\/a> en el ca\u00f1\u00f3n de abajo. \u00bfTe sientes un poco menos aventurero? Los visitantes tambi\u00e9n pueden alquilar la zona de barbacoa digna de Instagram en este pueblo fantasma para organizar su propia fiesta, boda o sesi\u00f3n de fotos al m\u00e1s puro estilo del Viejo Oeste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mina de oro m\u00e1s antigua, m\u00e1s rica y m\u00e1s famosa del sur de Nevada, la mina Techatticup, espera a fot\u00f3grafos y aficionados a la historia en el impresionante Ca\u00f1\u00f3n Eldorado, a solo 45 minutos de Las Vegas.<\/p>\n","protected":false},"featured_media":145155,"menu_order":0,"template":"","meta":{"biz_address_line_1":"16880 State Highway 165","biz_address_line_2":"","biz_city":"Nelson","biz_country":"United States","biz_latitude":"35.708042","biz_longitude":"-114.82470","biz_phone_number":"(702) 291-0026","biz_postal_code":"89046","biz_state":"NV","biz_website":"http:\/\/www.eldoradocanyonminetours.com\/","biz_desktop_image":{"ID":145155,"id":145155,"title":"","filename":"eldorado-canyon-techatticup-mine.jpg","filesize":220523,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/eldorado-canyon-techatticup-mine-2\/","alt":"","author":"3","description":"","caption":"","name":"eldorado-canyon-techatticup-mine-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:31","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":145155,"id":145155,"title":"","filename":"eldorado-canyon-techatticup-mine.jpg","filesize":220523,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/eldorado-canyon-techatticup-mine-2\/","alt":"","author":"3","description":"","caption":"","name":"eldorado-canyon-techatticup-mine-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:31","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_map_use_custom_map_link":false,"biz_admission":"<p><span style=\"font-weight: 400;\">Visita a la mina Techatticup<\/span><span style=\"font-weight: 400;\">Los boletos cuestan $20 para adultos (de 13 a\u00f1os en adelante) y $12.50 para ni\u00f1os de 5 a 12 a\u00f1os. Los ni\u00f1os menores de 5 a\u00f1os son gratis con un adulto. Reservaciones obligatorias.<\/span><\/p>\n","biz_hours":"<p><span style=\"font-weight: 400;\">Los recorridos por la mina Eldorado Canyon se realizan diariamente a las 9 a. m., a las 12 p. m. y a las 2 p. m. cuando hay cuatro o m\u00e1s adultos presentes con reserva. La propiedad est\u00e1 cerrada durante Pascua, Acci\u00f3n de Gracias, Nochebuena (al mediod\u00eda) y Navidad. El recorrido a pie es de aproximadamente un cuarto de milla y dura poco menos de 90 minutos. V\u00edstase para condiciones de fr\u00edo dentro de la mina en todas las \u00e9pocas del a\u00f1o. <\/span><\/p>\n","biz_attached_media":[{"ID":145155,"id":145155,"title":"","filename":"eldorado-canyon-techatticup-mine.jpg","filesize":220523,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/eldorado-canyon-techatticup-mine-2\/","alt":"","author":"3","description":"","caption":"","name":"eldorado-canyon-techatticup-mine-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:31","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":145149,"id":145149,"title":"","filename":"3000-miles-graceland-prop.jpg","filesize":234612,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/3000-miles-graceland-prop-2\/","alt":"","author":"3","description":"","caption":"","name":"3000-miles-graceland-prop-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:22","modified":"2025-08-05 00:37:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":145151,"id":145151,"title":"","filename":"abandoned-canyon-eldorado-canyon.jpg","filesize":51609,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/abandoned-canyon-eldorado-canyon-2\/","alt":"","author":"3","description":"","caption":"","name":"abandoned-canyon-eldorado-canyon-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:26","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},{"ID":145156,"id":145156,"title":"","filename":"general-store-eldorado-canyon.jpg","filesize":57402,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/general-store-eldorado-canyon-2\/","alt":"","author":"3","description":"","caption":"","name":"general-store-eldorado-canyon-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:34","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/general-store-eldorado-canyon.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},{"ID":145163,"id":145163,"title":"","filename":"store-interior-techatticup-mine.jpg","filesize":56393,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/store-interior-techatticup-mine-2\/","alt":"","author":"3","description":"","caption":"","name":"store-interior-techatticup-mine-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:44","modified":"2025-08-05 00:37:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/store-interior-techatticup-mine.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},{"ID":145158,"id":145158,"title":"","filename":"lean-to-eldorado-canyon.jpg","filesize":67419,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/lean-to-eldorado-canyon-2\/","alt":"","author":"3","description":"","caption":"","name":"lean-to-eldorado-canyon-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:38","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/lean-to-eldorado-canyon.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},{"ID":145166,"id":145166,"title":"","filename":"techatticup-mine-tour.jpg","filesize":53535,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/techatticup-mine-tour-3\/","alt":"","author":"3","description":"","caption":"","name":"techatticup-mine-tour-3","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:50","modified":"2025-08-05 00:37:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/techatticup-mine-tour.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},{"ID":145153,"id":145153,"title":"","filename":"building-front-edlorado-canyon.jpg","filesize":49894,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/building-front-edlorado-canyon-2\/","alt":"","author":"3","description":"","caption":"","name":"building-front-edlorado-canyon-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:28","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/building-front-edlorado-canyon.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},{"ID":145165,"id":145165,"title":"","filename":"structure-eldorado-canyon.jpg","filesize":202275,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/structure-eldorado-canyon-2\/","alt":"","author":"3","description":"","caption":"","name":"structure-eldorado-canyon-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:46","modified":"2025-08-05 00:37:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/structure-eldorado-canyon.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":145161,"id":145161,"title":"","filename":"skulls-techatticup-mine.jpg","filesize":197507,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/skulls-techatticup-mine-2\/","alt":"","author":"3","description":"","caption":"","name":"skulls-techatticup-mine-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:41","modified":"2025-08-05 00:37:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/skulls-techatticup-mine.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_image_link":{"title":"","url":"","target":"","0":""}},"categories":[241,83,118],"tn-amenities":[],"tn-regions":[104],"silos":[631],"class_list":["post-160454","business","type-business","status-publish","has-post-thumbnail","hentry","category-rockhounding-mining","category-shopping-and-leisure","category-ghost-town"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Explora Eldorado Canyon y la mina Techatticup en Nevada<\/title>\n<meta name=\"description\" content=\"La mina Eldorado Canyon y la mina Techatticup ofrecen a los visitantes la oportunidad de experimentar minas de oro abandonadas del siglo XIX. Ubicado a 45 minutos de Las Vegas, Eldorado Canyon y el recorrido por la mina Techatticup son perfectos tanto para fot\u00f3grafos como para amantes de la historia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Explora Eldorado Canyon y la mina Techatticup en Nevada\" \/>\n<meta property=\"og:description\" content=\"La mina Eldorado Canyon y la mina Techatticup ofrecen a los visitantes la oportunidad de experimentar minas de oro abandonadas del siglo XIX. Ubicado a 45 minutos de Las Vegas, Eldorado Canyon y el recorrido por la mina Techatticup son perfectos tanto para fot\u00f3grafos como para amantes de la historia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T00:37:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Explora Eldorado Canyon y la mina Techatticup en Nevada","description":"La mina Eldorado Canyon y la mina Techatticup ofrecen a los visitantes la oportunidad de experimentar minas de oro abandonadas del siglo XIX. Ubicado a 45 minutos de Las Vegas, Eldorado Canyon y el recorrido por la mina Techatticup son perfectos tanto para fot\u00f3grafos como para amantes de la historia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/","og_locale":"es_ES","og_type":"article","og_title":"Explora Eldorado Canyon y la mina Techatticup en Nevada","og_description":"La mina Eldorado Canyon y la mina Techatticup ofrecen a los visitantes la oportunidad de experimentar minas de oro abandonadas del siglo XIX. Ubicado a 45 minutos de Las Vegas, Eldorado Canyon y el recorrido por la mina Techatticup son perfectos tanto para fot\u00f3grafos como para amantes de la historia.","og_url":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","article_modified_time":"2025-08-05T00:37:43+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/","url":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/","name":"Explora Eldorado Canyon y la mina Techatticup en Nevada","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","datePublished":"2014-04-04T06:10:50+00:00","dateModified":"2025-08-05T00:37:43+00:00","description":"La mina Eldorado Canyon y la mina Techatticup ofrecen a los visitantes la oportunidad de experimentar minas de oro abandonadas del siglo XIX. Ubicado a 45 minutos de Las Vegas, Eldorado Canyon y el recorrido por la mina Techatticup son perfectos tanto para fot\u00f3grafos como para amantes de la historia.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ca\u00f1\u00f3n Eldorado y mina Techatticup"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":145155,"id":145155,"title":"","filename":"eldorado-canyon-techatticup-mine.jpg","filesize":220523,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/eldorado-canyon-techatticup-mine-2\/","alt":"","author":"3","description":"","caption":"","name":"eldorado-canyon-techatticup-mine-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:31","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":145149,"id":145149,"title":"","filename":"3000-miles-graceland-prop.jpg","filesize":234612,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/3000-miles-graceland-prop-2\/","alt":"","author":"3","description":"","caption":"","name":"3000-miles-graceland-prop-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:22","modified":"2025-08-05 00:37:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/3000-miles-graceland-prop.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":145151,"id":145151,"title":"","filename":"abandoned-canyon-eldorado-canyon.jpg","filesize":51609,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","link":"https:\/\/travelnevada.com\/es\/minas-prospeccion\/canon-eldorado-y-mina-techatticup\/attachment\/abandoned-canyon-eldorado-canyon-2\/","alt":"","author":"3","description":"","caption":"","name":"abandoned-canyon-eldorado-canyon-2","status":"inherit","uploaded_to":160454,"date":"2022-11-30 22:23:26","modified":"2025-08-05 00:37:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":772,"height":434,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","large-width":772,"large-height":434,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","1536x1536-width":772,"1536x1536-height":434,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","2048x2048-width":772,"2048x2048-height":434,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/abandoned-canyon-eldorado-canyon.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}}],"primary_category":{"term_id":241,"name":"Rockhounding &amp; Mining","slug":"rockhounding-mining","term_group":0,"term_taxonomy_id":241,"taxonomy":"category","description":"","parent":237,"count":25,"filter":"raw"},"silo_name":"Minas&amp; Prospecci\u00f3n","is_rural":"true","category_slugs":"rockhounding-mining,shopping-and-leisure,ghost-town","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine-1536x864.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/eldorado-canyon-techatticup-mine.jpg"},"featured_image_alt":"","friendly_post_date":"April 03, 2014","selected_region":[{"term_id":104,"name":"Boulder City","slug":"boulder-city","term_group":0,"term_taxonomy_id":104,"taxonomy":"tn-regions","description":"","parent":8,"count":103,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":1,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160454\/revisions"}],"predecessor-version":[{"id":160461,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160454\/revisions\/160461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/145155"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=160454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=160454"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=160454"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=160454"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=160454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}