{"id":160664,"date":"2014-04-03T23:14:05","date_gmt":"2014-04-04T06:14:05","guid":{"rendered":"https:\/\/travelnevada.com\/business\/complejo-turistico-cold-springs-station\/"},"modified":"2014-04-03T23:14:05","modified_gmt":"2014-04-04T06:14:05","slug":"complejo-turistico-cold-springs-station","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/","title":{"rendered":"Complejo tur\u00edstico Cold Springs Station"},"content":{"rendered":"<p><strong>El complejo tur\u00edstico Cold Springs Station&nbsp;Caracter\u00edsticas del destino: &nbsp;<\/strong>Un restaurante, bar, tienda de regalos, parque de casas rodantes, caba\u00f1as.&amp; motel <strong>Abierto los 7 d\u00edas de la semana&nbsp;&#8211;&nbsp;<\/strong>Rel\u00e1jese en una de nuestras habitaciones de motel, caba\u00f1as bien equipadas o al\u00f3jese en nuestro parque de casas rodantes con conexiones completas. <strong>Restaurante <\/strong> &#8211; sirve desayuno, almuerzo&amp; Cena con platos del d\u00eda. <strong><em>\u00a1La gran belleza del centro de Nevada espera al viajero!<\/em>. .. <\/strong>Apto para veh\u00edculos todo terreno y una escala perfecta para ciclistas o conductores de campo traviesa. <strong>. ..<\/strong> Las monta\u00f1as que rodean el Cold Springs Station Resort alcanzan altitudes de m\u00e1s de 9.000 pies y son f\u00e1cilmente accesibles en veh\u00edculos 4&#215;4 o todoterreno. <strong>. .. <\/strong>Los cazadores y observadores de la naturaleza tambi\u00e9n son bienvenidos a venir a ver la abundante vida silvestre, ya que las cadenas monta\u00f1osas albergan ant\u00edlopes, ciervos y borregos cimarrones. <strong>Visita nuestra tienda de regalos &#8211;&nbsp;<\/strong>Mercanc\u00eda de Nevada disponible para conmemorar su viaje por The Loneliest Road. <strong>Hay gu\u00edas gratuitas de la autopista 50 disponibles: <\/strong>No dejes pasar la oportunidad de recorrer El Camino M\u00e1s Solitario, y sellar la gu\u00eda a lo largo del camino para recibir un certificado, firmado por el Gobernador,&nbsp;y un pin de la autopista 50. <em>Cold Spring Station Resort ha cambiado de manos despu\u00e9s de 17 a\u00f1os. Los nuevos propietarios son nativos de Nevada y hu\u00e9spedes del complejo desde hace mucho tiempo. &nbsp;Habiendo crecido &nbsp;En Nevada est\u00e1n muy emocionados de comenzar su nueva aventura.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Establecido cerca del sitio original de la estaci\u00f3n Cold Springs del Pony Express de 1860 en la carretera m\u00e1s solitaria de la autopista 50&nbsp;en Am\u00e9rica.<\/p>\n","protected":false},"featured_media":114723,"menu_order":0,"template":"","meta":{"biz_address_line_1":"52300 Austin Highway","biz_address_line_2":"","biz_attached_media":[{"ID":114723,"id":114723,"title":"lass-id-original-1517013681-5a6bcab1144c7.jpg","filename":"lass-id-original-1517013681-5a6bcab1144c7.jpg","filesize":209272,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","link":"https:\/\/travelnevada.com\/es\/rv-parks\/cold-springs-station-resort\/attachment\/lass-id-original-1517013681-5a6bcab1144c7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013681-5a6bcab1144c7-jpg-2","status":"inherit","uploaded_to":20544,"date":"2020-04-23 21:35:12","modified":"2020-04-23 21:35:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114724,"id":114724,"title":"lass-id-original-1517013681-5a6bcab1985bc.jpg","filename":"lass-id-original-1517013681-5a6bcab1985bc.jpg","filesize":192813,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114724","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013681-5a6bcab1985bc-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:13","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114725,"id":114725,"title":"lass-id-original-1517013680-5a6bcab0de7b0.jpg","filename":"lass-id-original-1517013680-5a6bcab0de7b0.jpg","filesize":178449,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114725","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013680-5a6bcab0de7b0-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:14","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114726,"id":114726,"title":"lass-id-original-1517013681-5a6bcab19a2d9.jpg","filename":"lass-id-original-1517013681-5a6bcab19a2d9.jpg","filesize":224656,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114726","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013681-5a6bcab19a2d9-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:15","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab19a2d9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114727,"id":114727,"title":"lass-id-original-1517013682-5a6bcab247382.jpg","filename":"lass-id-original-1517013682-5a6bcab247382.jpg","filesize":340327,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114727","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013682-5a6bcab247382-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:16","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab247382.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114728,"id":114728,"title":"lass-id-original-1517013680-5a6bcab057bd7.jpg","filename":"lass-id-original-1517013680-5a6bcab057bd7.jpg","filesize":177987,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114728","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013680-5a6bcab057bd7-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:17","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab057bd7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114729,"id":114729,"title":"lass-id-original-1517013682-5a6bcab285a21.jpg","filename":"lass-id-original-1517013682-5a6bcab285a21.jpg","filesize":291715,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114729","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013682-5a6bcab285a21-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:18","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab285a21.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114730,"id":114730,"title":"lass-id-original-1517013681-5a6bcab1b510c.jpg","filename":"lass-id-original-1517013681-5a6bcab1b510c.jpg","filesize":199256,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114730","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013681-5a6bcab1b510c-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:19","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1b510c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114731,"id":114731,"title":"lass-id-original-1517013682-5a6bcab21d544.jpg","filename":"lass-id-original-1517013682-5a6bcab21d544.jpg","filesize":189076,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114731","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013682-5a6bcab21d544-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:20","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab21d544.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114732,"id":114732,"title":"lass-id-original-1517013682-5a6bcab24684b.jpg","filename":"lass-id-original-1517013682-5a6bcab24684b.jpg","filesize":206742,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114732","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013682-5a6bcab24684b-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:21","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013682-5a6bcab24684b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_city":"Fallon","biz_country":"United States","biz_latitude":"39.413800","biz_longitude":"-117.84064","biz_phone_number":"(775) 423-1233","biz_postal_code":"89406","biz_state":"NV","biz_website":"http:\/\/www.cssresort.com\/","biz_desktop_image":{"ID":114723,"id":114723,"title":"lass-id-original-1517013681-5a6bcab1144c7.jpg","filename":"lass-id-original-1517013681-5a6bcab1144c7.jpg","filesize":209272,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","link":"https:\/\/travelnevada.com\/es\/rv-parks\/cold-springs-station-resort\/attachment\/lass-id-original-1517013681-5a6bcab1144c7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013681-5a6bcab1144c7-jpg-2","status":"inherit","uploaded_to":20544,"date":"2020-04-23 21:35:12","modified":"2020-04-23 21:35:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_image_link":{"title":"","url":"","target":"","0":""},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":114723,"id":114723,"title":"lass-id-original-1517013681-5a6bcab1144c7.jpg","filename":"lass-id-original-1517013681-5a6bcab1144c7.jpg","filesize":209272,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","link":"https:\/\/travelnevada.com\/es\/rv-parks\/cold-springs-station-resort\/attachment\/lass-id-original-1517013681-5a6bcab1144c7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013681-5a6bcab1144c7-jpg-2","status":"inherit","uploaded_to":20544,"date":"2020-04-23 21:35:12","modified":"2020-04-23 21:35:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}},"categories":[199,170,172,56,52],"tn-amenities":[],"tn-regions":[15],"silos":[679],"class_list":["post-160664","business","type-business","status-publish","has-post-thumbnail","hentry","category-hotels-lodging","category-motels","category-rv-parks","category-restaurants","category-food-and-drink"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Disfrute de su estancia en Cold Springs Station Resort<\/title>\n<meta name=\"description\" content=\"El Cold Springs Station Resort cuenta con un restaurante, bar, tienda de regalos, parque de casas rodantes y caba\u00f1as.&amp; motel. Abierto los 7 d\u00edas de la semana y cuenta con un restaurante que sirve desayuno, almuerzo y cena. Establecido cerca del sitio original de la estaci\u00f3n Cold Springs del Pony Express de 1860 en la carretera m\u00e1s solitaria de Estados Unidos, la Hwy 50.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disfrute de su estancia en Cold Springs Station Resort\" \/>\n<meta property=\"og:description\" content=\"El Cold Springs Station Resort cuenta con un restaurante, bar, tienda de regalos, parque de casas rodantes y caba\u00f1as.&amp; motel. Abierto los 7 d\u00edas de la semana y cuenta con un restaurante que sirve desayuno, almuerzo y cena. Establecido cerca del sitio original de la estaci\u00f3n Cold Springs del Pony Express de 1860 en la carretera m\u00e1s solitaria de Estados Unidos, la Hwy 50.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disfrute de su estancia en Cold Springs Station Resort","description":"El Cold Springs Station Resort cuenta con un restaurante, bar, tienda de regalos, parque de casas rodantes y caba\u00f1as.& motel. Abierto los 7 d\u00edas de la semana y cuenta con un restaurante que sirve desayuno, almuerzo y cena. Establecido cerca del sitio original de la estaci\u00f3n Cold Springs del Pony Express de 1860 en la carretera m\u00e1s solitaria de Estados Unidos, la Hwy 50.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/","og_locale":"es_ES","og_type":"article","og_title":"Disfrute de su estancia en Cold Springs Station Resort","og_description":"El Cold Springs Station Resort cuenta con un restaurante, bar, tienda de regalos, parque de casas rodantes y caba\u00f1as.& motel. Abierto los 7 d\u00edas de la semana y cuenta con un restaurante que sirve desayuno, almuerzo y cena. Establecido cerca del sitio original de la estaci\u00f3n Cold Springs del Pony Express de 1860 en la carretera m\u00e1s solitaria de Estados Unidos, la Hwy 50.","og_url":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","og_image":[{"width":1000,"height":563,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/","url":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/","name":"Disfrute de su estancia en Cold Springs Station Resort","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","datePublished":"2014-04-04T06:14:05+00:00","description":"El Cold Springs Station Resort cuenta con un restaurante, bar, tienda de regalos, parque de casas rodantes y caba\u00f1as.& motel. Abierto los 7 d\u00edas de la semana y cuenta con un restaurante que sirve desayuno, almuerzo y cena. Establecido cerca del sitio original de la estaci\u00f3n Cold Springs del Pony Express de 1860 en la carretera m\u00e1s solitaria de Estados Unidos, la Hwy 50.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","width":1000,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/complejo-turistico-cold-springs-station\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Complejo tur\u00edstico Cold Springs Station"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":114723,"id":114723,"title":"lass-id-original-1517013681-5a6bcab1144c7.jpg","filename":"lass-id-original-1517013681-5a6bcab1144c7.jpg","filesize":209272,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","link":"https:\/\/travelnevada.com\/es\/rv-parks\/cold-springs-station-resort\/attachment\/lass-id-original-1517013681-5a6bcab1144c7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013681-5a6bcab1144c7-jpg-2","status":"inherit","uploaded_to":20544,"date":"2020-04-23 21:35:12","modified":"2020-04-23 21:35:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114724,"id":114724,"title":"lass-id-original-1517013681-5a6bcab1985bc.jpg","filename":"lass-id-original-1517013681-5a6bcab1985bc.jpg","filesize":192813,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114724","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013681-5a6bcab1985bc-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:13","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1985bc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":114725,"id":114725,"title":"lass-id-original-1517013680-5a6bcab0de7b0.jpg","filename":"lass-id-original-1517013680-5a6bcab0de7b0.jpg","filesize":178449,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=114725","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1517013680-5a6bcab0de7b0-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 21:35:14","modified":"2026-06-25 01:28:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1000,"height":563,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","large-width":1000,"large-height":563,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","1536x1536-width":1000,"1536x1536-height":563,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","2048x2048-width":1000,"2048x2048-height":563,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013680-5a6bcab0de7b0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"primary_category":{"term_id":199,"name":"Hotels &amp; Lodging","slug":"hotels-lodging","term_group":0,"term_taxonomy_id":199,"taxonomy":"category","description":"","parent":0,"count":94,"filter":"raw"},"silo_name":"Parques para RV","is_rural":"true","category_slugs":"hotels-lodging,motels,rv-parks,restaurants,food-and-drink","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1517013681-5a6bcab1144c7.jpg"},"featured_image_alt":"","friendly_post_date":"April 03, 2014","selected_region":[{"term_id":15,"name":"Austin","slug":"austin","term_group":0,"term_taxonomy_id":15,"taxonomy":"tn-regions","description":"","parent":16,"count":73,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":0,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/114723"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=160664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=160664"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=160664"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=160664"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=160664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}