{"id":160669,"date":"2014-04-03T23:14:02","date_gmt":"2014-04-04T06:14:02","guid":{"rendered":"https:\/\/travelnevada.com\/business\/parque-de-casas-rodantes-bonanza-casino\/"},"modified":"2014-04-03T23:14:02","modified_gmt":"2014-04-04T06:14:02","slug":"parque-de-casas-rodantes-bonanza-casino","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/","title":{"rendered":"Parque de casas rodantes Bonanza&#038; Casino"},"content":{"rendered":"<p>El golf, la pesca y la nataci\u00f3n est\u00e1n a la vuelta de la esquina del Bonanza Inn and Casino y del RV Park en la cercana \u00e1rea recreativa estatal de Lahontan. Las temperaturas normalmente rondan los 90 grados durante los meses de verano, pero una vez que se pone el sol bajan a los 60 grados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El golf, la pesca y la nataci\u00f3n est\u00e1n a la vuelta de la esquina del Bonanza Inn and Casino y del RV Park en la cercana \u00e1rea recreativa estatal de [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"biz_address_line_1":"855 West Williams","biz_address_line_2":"","biz_attached_media":false,"biz_city":"Fallon","biz_country":"United States","biz_latitude":"39.474820","biz_longitude":"-118.78685","biz_phone_number":"(775) 423-6031","biz_postal_code":"89406","biz_state":"NV","biz_website":"","biz_desktop_image":false,"biz_mobile_image":false},"categories":[172,163],"tn-amenities":[],"tn-regions":[39],"silos":[679],"class_list":["post-160669","business","type-business","status-publish","hentry","category-rv-parks","category-resorts-casinos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parque de casas rodantes Bonanza&amp; Casino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parque de casas rodantes Bonanza&amp; Casino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2026\/05\/Sand-Harbor-Beach-Family-Feat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parque de casas rodantes Bonanza& Casino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/","og_locale":"es_ES","og_type":"article","og_title":"Parque de casas rodantes Bonanza& Casino","og_url":"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","og_image":[{"width":1200,"height":675,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2026\/05\/Sand-Harbor-Beach-Family-Feat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/","url":"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/","name":"Parque de casas rodantes Bonanza& Casino","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"datePublished":"2014-04-04T06:14:02+00:00","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/parques-para-rv\/parque-de-casas-rodantes-bonanza-casino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Parque de casas rodantes Bonanza&#038; Casino"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":false,"primary_category":{"term_id":172,"name":"RV Parks","slug":"rv-parks","term_group":0,"term_taxonomy_id":172,"taxonomy":"category","description":"","parent":199,"count":95,"filter":"raw"},"silo_name":"Parques para RV","is_rural":"true","category_slugs":"rv-parks,resorts-casinos","featured_image_url":"","featured_image_url_sizes":{"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"featured_image_alt":"","friendly_post_date":"April 03, 2014","selected_region":[{"term_id":39,"name":"Fallon","slug":"fallon","term_group":0,"term_taxonomy_id":39,"taxonomy":"tn-regions","description":"","parent":16,"count":83,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":0,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160669\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=160669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=160669"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=160669"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=160669"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=160669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}