{"id":160938,"date":"2014-05-12T17:19:45","date_gmt":"2014-05-13T00:19:45","guid":{"rendered":"https:\/\/travelnevada.com\/business\/tuscarora\/"},"modified":"2025-08-05T11:31:27","modified_gmt":"2025-08-05T18:31:27","slug":"tuscarora","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/","title":{"rendered":"Tuscarora"},"content":{"rendered":"\n<p>Tuscarora se fund\u00f3 en 1867 despu\u00e9s de que los hermanos John y Steven Beard descubrieran oro a unas pocas millas del valle desde el sitio actual de la ciudad. Cerca de su reclamo, establecieron una comunidad minera en su mayor\u00eda desafortunada a la que llamaron Tuscarora en honor a un barco ca\u00f1onero estadounidense, que a su vez recibi\u00f3 el nombre de un pueblo ind\u00edgena de lo que hoy es Carolina del Norte. La ciudad est\u00e1 ubicada a mitad de la ladera del monte Blitzen porque all\u00ed se produjo un hallazgo masivo de plata en 1871, despu\u00e9s de lo cual Tuscarora se traslad\u00f3 a donde est\u00e1 hoy.<\/p>\n\n<p>Los visitantes que viajan durante los meses c\u00e1lidos pueden esperar ruinas pintorescas cubiertas de vegetaci\u00f3n e innumerables artefactos para inspeccionar. Haga una parada en la ciudad para dar un paseo por su deteriorada cuadr\u00edcula de calles y luego camine hasta el cementerio. O camine hasta la colina hasta la gran chimenea para disfrutar de la impresionante vista. Mientras est\u00e9s en ello, env\u00eda una carta por correo. El \u00fanico negocio del pueblo es una oficina de correos que todav\u00eda funciona (con personal a diario) y que presta servicio a los ranchos repartidos por todo el valle.<\/p>\n\n<p>Y, por supuesto,\u00a0pasa por el <a href=\"https:\/\/travelnevada.com\/arts-culture\/tuscarora-pottery-school\/\">Escuela de Cer\u00e1mica Tuscarora<\/a>, que ofrece cada verano una variedad de talleres de cer\u00e1mica. Dependiendo de cu\u00e1ndo visites esta ciudad escasamente poblada, podr\u00eda haber alguien disponible para mostrarte la hist\u00f3rica pensi\u00f3n o el estudio. Tambi\u00e9n hay una galer\u00eda y una tienda de regalos que ofrece una hermosa colecci\u00f3n de cer\u00e1mica creada por instructores y amigos de la escuela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los visitantes que viajan durante los meses c\u00e1lidos pueden esperar ruinas pintorescas cubiertas de vegetaci\u00f3n e innumerables artefactos para inspeccionar. Pase por la Escuela de Cer\u00e1mica Tuscarora, que ofrece una variedad de talleres de cer\u00e1mica cada verano.<\/p>\n","protected":false},"featured_media":115748,"menu_order":0,"template":"","meta":{"biz_address_line_1":"56 Miles Outside Elko","biz_address_line_2":"","biz_attached_media":[{"ID":115748,"id":115748,"title":"lass-id-original-1515087956-5a4e68541ee9c.jpg","filename":"lass-id-original-1515087956-5a4e68541ee9c.jpg","filesize":406848,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/attachment\/lass-id-original-1515087956-5a4e68541ee9c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515087956-5a4e68541ee9c-jpg-2","status":"inherit","uploaded_to":160938,"date":"2020-04-23 22:02:49","modified":"2025-08-05 18:31:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115749,"id":115749,"title":"lass-id-original-1515087974-5a4e6866ab0ab.jpg","filename":"lass-id-original-1515087974-5a4e6866ab0ab.jpg","filesize":287432,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115749","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515087974-5a4e6866ab0ab-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:02:51","modified":"2026-06-25 01:29:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115750,"id":115750,"title":"lass-id-original-1515088008-5a4e68889f169.jpg","filename":"lass-id-original-1515088008-5a4e68889f169.jpg","filesize":424963,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115750","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515088008-5a4e68889f169-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:02:52","modified":"2026-06-25 01:29:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115751,"id":115751,"title":"lass-id-original-1515088019-5a4e6893aefd5.jpg","filename":"lass-id-original-1515088019-5a4e6893aefd5.jpg","filesize":421523,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115751","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515088019-5a4e6893aefd5-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:02:54","modified":"2026-06-25 01:29:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088019-5a4e6893aefd5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115752,"id":115752,"title":"lass-id-original-1515088034-5a4e68a27ef48.jpg","filename":"lass-id-original-1515088034-5a4e68a27ef48.jpg","filesize":425754,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115752","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515088034-5a4e68a27ef48-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:02:56","modified":"2026-06-25 01:29:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088034-5a4e68a27ef48.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115753,"id":115753,"title":"lass-id-original-1515088047-5a4e68afd8186.jpg","filename":"lass-id-original-1515088047-5a4e68afd8186.jpg","filesize":401144,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115753","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515088047-5a4e68afd8186-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:02:58","modified":"2026-06-25 01:29:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088047-5a4e68afd8186.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115754,"id":115754,"title":"lass-id-original-1515088055-5a4e68b77a96e.jpg","filename":"lass-id-original-1515088055-5a4e68b77a96e.jpg","filesize":382785,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115754","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515088055-5a4e68b77a96e-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:03:00","modified":"2026-06-25 01:29:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088055-5a4e68b77a96e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_city":"Elko","biz_country":"United States","biz_latitude":"41.314595","biz_longitude":"-116.22346","biz_phone_number":"","biz_postal_code":"89834","biz_state":"NV","biz_website":"http:\/\/www.ghosttowns.com\/states\/nv\/tuscarora.html","biz_desktop_image":{"ID":115748,"id":115748,"title":"lass-id-original-1515087956-5a4e68541ee9c.jpg","filename":"lass-id-original-1515087956-5a4e68541ee9c.jpg","filesize":406848,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/attachment\/lass-id-original-1515087956-5a4e68541ee9c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515087956-5a4e68541ee9c-jpg-2","status":"inherit","uploaded_to":160938,"date":"2020-04-23 22:02:49","modified":"2025-08-05 18:31:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_image_link":{"title":"","url":"","target":"","0":""},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":115748,"id":115748,"title":"lass-id-original-1515087956-5a4e68541ee9c.jpg","filename":"lass-id-original-1515087956-5a4e68541ee9c.jpg","filesize":406848,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/attachment\/lass-id-original-1515087956-5a4e68541ee9c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515087956-5a4e68541ee9c-jpg-2","status":"inherit","uploaded_to":160938,"date":"2020-04-23 22:02:49","modified":"2025-08-05 18:31:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_map_use_custom_map_link":false},"categories":[551],"tn-amenities":[],"tn-regions":[209],"silos":[633],"class_list":["post-160938","business","type-business","status-publish","has-post-thumbnail","hentry","category-pueblo-fantasma"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tuscarora | Tuscarora, Nevada | Condado de Elko<\/title>\n<meta name=\"description\" content=\"Los visitantes que viajan hasta Tuscarora durante los meses c\u00e1lidos pueden esperar ruinas pintorescas cubiertas de vegetaci\u00f3n e innumerables artefactos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tuscarora | Tuscarora, Nevada | Condado de Elko\" \/>\n<meta property=\"og:description\" content=\"Los visitantes que viajan hasta Tuscarora durante los meses c\u00e1lidos pueden esperar ruinas pintorescas cubiertas de vegetaci\u00f3n e innumerables artefactos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T18:31:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tuscarora | Tuscarora, Nevada | Condado de Elko","description":"Los visitantes que viajan hasta Tuscarora durante los meses c\u00e1lidos pueden esperar ruinas pintorescas cubiertas de vegetaci\u00f3n e innumerables artefactos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/","og_locale":"es_ES","og_type":"article","og_title":"Tuscarora | Tuscarora, Nevada | Condado de Elko","og_description":"Los visitantes que viajan hasta Tuscarora durante los meses c\u00e1lidos pueden esperar ruinas pintorescas cubiertas de vegetaci\u00f3n e innumerables artefactos.","og_url":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","article_modified_time":"2025-08-05T18:31:27+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/","url":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/","name":"Tuscarora | Tuscarora, Nevada | Condado de Elko","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","datePublished":"2014-05-13T00:19:45+00:00","dateModified":"2025-08-05T18:31:27+00:00","description":"Los visitantes que viajan hasta Tuscarora durante los meses c\u00e1lidos pueden esperar ruinas pintorescas cubiertas de vegetaci\u00f3n e innumerables artefactos.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tuscarora"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":115748,"id":115748,"title":"lass-id-original-1515087956-5a4e68541ee9c.jpg","filename":"lass-id-original-1515087956-5a4e68541ee9c.jpg","filesize":406848,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/tuscarora\/attachment\/lass-id-original-1515087956-5a4e68541ee9c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515087956-5a4e68541ee9c-jpg-2","status":"inherit","uploaded_to":160938,"date":"2020-04-23 22:02:49","modified":"2025-08-05 18:31:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115749,"id":115749,"title":"lass-id-original-1515087974-5a4e6866ab0ab.jpg","filename":"lass-id-original-1515087974-5a4e6866ab0ab.jpg","filesize":287432,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115749","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515087974-5a4e6866ab0ab-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:02:51","modified":"2026-06-25 01:29:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087974-5a4e6866ab0ab.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115750,"id":115750,"title":"lass-id-original-1515088008-5a4e68889f169.jpg","filename":"lass-id-original-1515088008-5a4e68889f169.jpg","filesize":424963,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115750","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1515088008-5a4e68889f169-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:02:52","modified":"2026-06-25 01:29:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2000,"height":1125,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","2048x2048-width":2000,"2048x2048-height":1125,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515088008-5a4e68889f169.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"primary_category":{"term_id":551,"name":"Pueblo fantasma","slug":"pueblo-fantasma","term_group":0,"term_taxonomy_id":551,"taxonomy":"category","description":"","parent":623,"count":35,"filter":"raw"},"silo_name":"Puntos de inter\u00e9s hist\u00f3rico","is_rural":"true","category_slugs":"pueblo-fantasma","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c-1536x864.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1515087956-5a4e68541ee9c.jpg"},"featured_image_alt":"","friendly_post_date":"May 12, 2014","selected_region":[{"term_id":209,"name":"Elko","slug":"elko","term_group":0,"term_taxonomy_id":209,"taxonomy":"tn-regions","description":"","parent":12,"count":184,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":1,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160938\/revisions"}],"predecessor-version":[{"id":160939,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160938\/revisions\/160939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/115748"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=160938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=160938"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=160938"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=160938"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=160938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}