{"id":160957,"date":"2014-04-03T23:23:01","date_gmt":"2014-04-04T06:23:01","guid":{"rendered":"https:\/\/travelnevada.com\/business\/centro-cultural-de-san-agustin\/"},"modified":"2014-04-03T23:23:01","modified_gmt":"2014-04-04T06:23:01","slug":"centro-cultural-de-san-agustin","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/","title":{"rendered":"Centro Cultural de San Agust\u00edn"},"content":{"rendered":"<p>Construida en 1856, la iglesia cuenta con bancos de madera veteada, confesionarios g\u00f3ticos y un \u00f3rgano de tubos Henry C. Kilgen de nueve rangos pintado decorativamente en una caja g\u00f3tica. Con el tiempo, San Agust\u00edn albergar\u00e1 un centro cultural y art\u00edstico para la comunidad de Austin y el centro de Nevada. Las actividades incluir\u00e1n talleres de artistas, presentaciones y dramas hist\u00f3ricos, visitas guiadas, muestras de arte local, presentaciones musicales y colecciones y exhibiciones permanentes de Austin y el centro de Nevada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Construida en 1856, la iglesia cuenta con bancos de madera veteada, confesionarios g\u00f3ticos y un \u00f3rgano de tubos Henry C. Kilgen de nueve rangos pintado decorativamente en una caja g\u00f3tica.<\/p>\n","protected":false},"featured_media":115716,"menu_order":0,"template":"","meta":{"biz_address_line_1":"113 Virginia Street","biz_address_line_2":"","biz_attached_media":[{"ID":115716,"id":115716,"title":"lass-id-original-1525305101-5aea4f0d2be50.jpg","filename":"lass-id-original-1525305101-5aea4f0d2be50.jpg","filesize":179234,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/attachment\/lass-id-original-1525305101-5aea4f0d2be50-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1525305101-5aea4f0d2be50-jpg-2","status":"inherit","uploaded_to":160957,"date":"2020-04-23 22:01:15","modified":"2025-08-05 18:31:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115717,"id":115717,"title":"lass-id-original-1525305056-5aea4ee0bbec3.jpg","filename":"lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","filesize":366014,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115717","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1525305056-5aea4ee0bbec3-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:01:17","modified":"2026-06-25 01:29:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_city":"Austin","biz_country":"United States","biz_latitude":"39.493178","biz_longitude":"-117.07070","biz_phone_number":"(775) 964-2200","biz_postal_code":"89310","biz_state":"NV","biz_website":"https:\/\/www.facebook.com\/StAugustinesCCenter\/","biz_desktop_image":{"ID":115716,"id":115716,"title":"lass-id-original-1525305101-5aea4f0d2be50.jpg","filename":"lass-id-original-1525305101-5aea4f0d2be50.jpg","filesize":179234,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/attachment\/lass-id-original-1525305101-5aea4f0d2be50-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1525305101-5aea4f0d2be50-jpg-2","status":"inherit","uploaded_to":160957,"date":"2020-04-23 22:01:15","modified":"2025-08-05 18:31:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_image_link":{"title":"","url":"","target":"","0":""},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":115716,"id":115716,"title":"lass-id-original-1525305101-5aea4f0d2be50.jpg","filename":"lass-id-original-1525305101-5aea4f0d2be50.jpg","filesize":179234,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/attachment\/lass-id-original-1525305101-5aea4f0d2be50-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1525305101-5aea4f0d2be50-jpg-2","status":"inherit","uploaded_to":160957,"date":"2020-04-23 22:01:15","modified":"2025-08-05 18:31:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}},"categories":[617,545],"tn-amenities":[],"tn-regions":[15],"silos":[633],"class_list":["post-160957","business","type-business","status-publish","has-post-thumbnail","hentry","category-galerias-de-arte","category-puntos-de-interes-historico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro Cultural de San Agust\u00edn<\/title>\n<meta name=\"description\" content=\"Construida en 1856, la iglesia cuenta con bancos de madera veteada, confesionarios g\u00f3ticos y un \u00f3rgano de tubos Henry C. Kilgen de nueve rangos pintado decorativamente en una caja g\u00f3tica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro Cultural de San Agust\u00edn\" \/>\n<meta property=\"og:description\" content=\"Construida en 1856, la iglesia cuenta con bancos de madera veteada, confesionarios g\u00f3ticos y un \u00f3rgano de tubos Henry C. Kilgen de nueve rangos pintado decorativamente en una caja g\u00f3tica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"og:image\" content=\"http:\/\/live-travel-nevada.pantheonsite.io\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro Cultural de San Agust\u00edn","description":"Construida en 1856, la iglesia cuenta con bancos de madera veteada, confesionarios g\u00f3ticos y un \u00f3rgano de tubos Henry C. Kilgen de nueve rangos pintado decorativamente en una caja g\u00f3tica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/","og_locale":"es_ES","og_type":"article","og_title":"Centro Cultural de San Agust\u00edn","og_description":"Construida en 1856, la iglesia cuenta con bancos de madera veteada, confesionarios g\u00f3ticos y un \u00f3rgano de tubos Henry C. Kilgen de nueve rangos pintado decorativamente en una caja g\u00f3tica.","og_url":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","og_image":[{"width":1500,"height":844,"url":"http:\/\/live-travel-nevada.pantheonsite.io\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/","url":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/","name":"Centro Cultural de San Agust\u00edn","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","datePublished":"2014-04-04T06:23:01+00:00","description":"Construida en 1856, la iglesia cuenta con bancos de madera veteada, confesionarios g\u00f3ticos y un \u00f3rgano de tubos Henry C. Kilgen de nueve rangos pintado decorativamente en una caja g\u00f3tica.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Centro Cultural de San Agust\u00edn"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":115716,"id":115716,"title":"lass-id-original-1525305101-5aea4f0d2be50.jpg","filename":"lass-id-original-1525305101-5aea4f0d2be50.jpg","filesize":179234,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/centro-cultural-de-san-agustin\/attachment\/lass-id-original-1525305101-5aea4f0d2be50-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1525305101-5aea4f0d2be50-jpg-2","status":"inherit","uploaded_to":160957,"date":"2020-04-23 22:01:15","modified":"2025-08-05 18:31:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":115717,"id":115717,"title":"lass-id-original-1525305056-5aea4ee0bbec3.jpg","filename":"lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","filesize":366014,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=115717","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1525305056-5aea4ee0bbec3-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 22:01:17","modified":"2026-06-25 01:29:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305056-5aea4ee0bbec3-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"primary_category":{"term_id":545,"name":"Puntos de inter\u00e9s hist\u00f3rico","slug":"puntos-de-interes-historico","term_group":0,"term_taxonomy_id":545,"taxonomy":"category","description":"","parent":548,"count":115,"filter":"raw"},"silo_name":"Puntos de inter\u00e9s hist\u00f3rico","is_rural":"true","category_slugs":"galerias-de-arte,puntos-de-interes-historico","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1525305101-5aea4f0d2be50.jpg"},"featured_image_alt":"","friendly_post_date":"April 03, 2014","selected_region":[{"term_id":15,"name":"Austin","slug":"austin","term_group":0,"term_taxonomy_id":15,"taxonomy":"tn-regions","description":"","parent":16,"count":73,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":0,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/160957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/115716"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=160957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=160957"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=160957"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=160957"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=160957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}