{"id":161387,"date":"2018-05-17T18:48:24","date_gmt":"2018-05-18T01:48:24","guid":{"rendered":"https:\/\/travelnevada.com\/business\/estacion-de-bomberos-historica-de-goldfield\/"},"modified":"2018-05-17T18:48:24","modified_gmt":"2018-05-18T01:48:24","slug":"estacion-de-bomberos-historica-de-goldfield","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/","title":{"rendered":"Estaci\u00f3n de bomberos hist\u00f3rica de Goldfield"},"content":{"rendered":"<p>Otro hallazgo hist\u00f3rico notable en el centro de la ciudad. <a href=\"https:\/\/travelnevada.com\/regions\/central\/goldfield\"><strong>Yacimiento aur\u00edfero<\/strong><\/a> es la estaci\u00f3n de bomberos hist\u00f3rica de Goldfield. Originalmente construida en 1908, la estaci\u00f3n de bomberos se construy\u00f3 durante los infames a\u00f1os de auge de Goldfield, cuando la poblaci\u00f3n se catapult\u00f3 de unos pocos miles a m\u00e1s de 20.000, gan\u00e1ndose el estatus de la ciudad m\u00e1s grande de Nevada en unos pocos a\u00f1os. Construido en el centro de la ciudad, justo al lado de la calle principal (o Crook Street), el edificio es uno de los mejores ejemplos de construcci\u00f3n con piedra de sillar extra\u00edda localmente en Goldfield y, milagrosamente, dur\u00f3 m\u00e1s de 100 a\u00f1os a pesar de varios desastres naturales catastr\u00f3ficos. Curiosamente, la estaci\u00f3n de bomberos se construy\u00f3 en el coraz\u00f3n de Goldfield. Aunque se podr\u00eda suponer que esto significar\u00eda una proximidad cercana a casi todo en la zona, la poblaci\u00f3n creci\u00f3 de maneras que los funcionarios locales no pudieron anticipar. Para empeorar las cosas, la estaci\u00f3n de bomberos de Goldfield estaba atendida exclusivamente por voluntarios. Si eres un aficionado a la historia de Nevada, sabr\u00e1s lo que viene a continuaci\u00f3n&#8230; fiel a su estilo, Goldfield no pudo escapar de una serie de incendios devastadores (y m\u00e1s tarde, una inundaci\u00f3n) que arrasaron con la mayor parte de la ciudad. El incendio comenz\u00f3 el 6 de julio de 1923 en una residencia particular y arras\u00f3 unas 25 manzanas de la ciudad dif\u00edciles de imaginar, destruyendo todo a su paso. Pero eso no prepar\u00f3 a Goldfield para un regreso desalentador: un segundo incendio arras\u00f3 la ciudad el 29 de septiembre de 1924 y acab\u00f3 con casi todo lo que quedaba. Lo que se ve hoy en Goldfield son todos los edificios que sobrevivieron milagrosamente a esta serie de incendios, lo que hace que la visita sea a\u00fan m\u00e1s merecida. Aunque los bomberos voluntarios no pudieron salvar la mayor parte de la infraestructura de Goldfield, la estaci\u00f3n de bomberos permanece. La iron\u00eda, \u00bfverdad? Explora el hist\u00f3rico <a href=\"https:\/\/travelnevada.com\/discover\/26194\/goldfield-courthouse\"><strong>Palacio de justicia del condado de Esmeralda<\/strong><\/a> Al otro lado de la calle, visite la hist\u00f3rica estaci\u00f3n de bomberos que alberga varios camiones de bomberos restaurados de manera impresionante, incluido un remolque de escalera Seagraves de 1907, un tractor American LaFrance de 1917 y varios otros camiones de bomberos y ambulancias hist\u00f3ricos. Hoy en d\u00eda, el Departamento de Bomberos Hist\u00f3rico de Goldfield es parte del Distrito Hist\u00f3rico de Goldfield y est\u00e1 incluido en el Registro Nacional de Lugares Hist\u00f3ricos.<\/p>\n<h2><strong>HORAS<\/strong><\/h2>\n<p>La estaci\u00f3n de bomberos hist\u00f3rica de Goldfield est\u00e1 abierta solo con cita previa. Para consultar sobre disponibilidad y programar un recorrido, llame al (775) 485-3560.<\/p>\n<h2><strong>ADMISI\u00d3N<\/strong><\/h2>\n<p>Aunque la entrada a la estaci\u00f3n de bomberos hist\u00f3rica de Goldfield es gratuita, este museo magistralmente conservado depende de donaciones para continuar con los esfuerzos de preservaci\u00f3n. Como una ventana al pasado del Salvaje Oeste de Nevada y a los d\u00edas del poderoso auge del oro, considere hacer una donaci\u00f3n cuando nos visite. Estas contribuciones ayudan a establecer y preservar exhibiciones y respaldan futuras ampliaciones a la propiedad. Cuando visite este valioso recurso hist\u00f3rico, considere hacer una donaci\u00f3n o, para convertirse en miembro de la Sociedad Hist\u00f3rica de Goldfield, haga clic en <a href=\"http:\/\/www.goldfieldhistoricalsociety.com\/donate.html\"><em><strong>aqu\u00ed<\/strong><\/em><\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de albergar una gran cantidad de incre\u00edbles camiones de bomberos y ambulancias antiguas, la estaci\u00f3n de bomberos de Goldfield es importante para la historia de Goldfield debido a su conexi\u00f3n con la historia del departamento de bomberos voluntarios y el desarrollo de instalaciones p\u00fablicas en Goldfield durante su auge.<\/p>\n","protected":false},"featured_media":125015,"menu_order":0,"template":"","meta":{"biz_address_line_1":"403 Crook Street","biz_address_line_2":"(directly Across The Street From Courthouse)","biz_attached_media":[{"ID":125015,"id":125015,"title":"lass-id-original-1526597361-5afe06f1274c3.jpg","filename":"lass-id-original-1526597361-5afe06f1274c3.jpg","filesize":294887,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/attachment\/lass-id-original-1526597361-5afe06f1274c3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597361-5afe06f1274c3-jpg-2","status":"inherit","uploaded_to":161387,"date":"2020-05-05 00:56:32","modified":"2025-08-05 18:46:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":125017,"id":125017,"title":"lass-id-original-1526597355-5afe06eb5ef98.jpg","filename":"lass-id-original-1526597355-5afe06eb5ef98.jpg","filesize":406415,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1526597355-5afe06eb5ef98-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597355-5afe06eb5ef98-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 00:56:34","modified":"2020-05-05 00:56:34","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":125019,"id":125019,"title":"lass-id-original-1526597372-5afe06fcc106f.jpg","filename":"lass-id-original-1526597372-5afe06fcc106f.jpg","filesize":314272,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1526597372-5afe06fcc106f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597372-5afe06fcc106f-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 00:56:36","modified":"2020-05-05 00:56:36","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":854,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f-300x171.jpg","medium-width":300,"medium-height":171,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f-768x437.jpg","medium_large-width":768,"medium_large-height":437,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f-1024x583.jpg","large-width":1024,"large-height":583,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","1536x1536-width":1500,"1536x1536-height":854,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","2048x2048-width":1500,"2048x2048-height":854,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":171,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":228,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":342}},{"ID":125021,"id":125021,"title":"lass-id-original-1526597369-5afe06f9cfbdf.jpg","filename":"lass-id-original-1526597369-5afe06f9cfbdf.jpg","filesize":271257,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1526597369-5afe06f9cfbdf-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597369-5afe06f9cfbdf-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 00:56:37","modified":"2020-05-05 00:56:37","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597369-5afe06f9cfbdf.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":125024,"id":125024,"title":"lass-id-original-1526597376-5afe0700a5bd2.jpg","filename":"lass-id-original-1526597376-5afe0700a5bd2.jpg","filesize":249672,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1526597376-5afe0700a5bd2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597376-5afe0700a5bd2-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 00:56:38","modified":"2020-05-05 00:56:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597376-5afe0700a5bd2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":125026,"id":125026,"title":"lass-id-original-1526597379-5afe0703af424.jpg","filename":"lass-id-original-1526597379-5afe0703af424.jpg","filesize":322951,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1526597379-5afe0703af424-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597379-5afe0703af424-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 00:56:40","modified":"2020-05-05 00:56:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597379-5afe0703af424.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":125029,"id":125029,"title":"lass-id-original-1526597384-5afe070873b13.jpg","filename":"lass-id-original-1526597384-5afe070873b13.jpg","filesize":264878,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1526597384-5afe070873b13-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597384-5afe070873b13-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 00:56:41","modified":"2020-05-05 00:56:41","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597384-5afe070873b13.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_city":"Goldfield","biz_country":"United States","biz_latitude":"37.7072321","biz_longitude":"-117.23261","biz_phone_number":"(775) 485-3560","biz_postal_code":"89013","biz_state":"NV","biz_website":"http:\/\/www.goldfieldhistoricalsociety.com\/","biz_desktop_image":{"ID":125015,"id":125015,"title":"lass-id-original-1526597361-5afe06f1274c3.jpg","filename":"lass-id-original-1526597361-5afe06f1274c3.jpg","filesize":294887,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/attachment\/lass-id-original-1526597361-5afe06f1274c3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597361-5afe06f1274c3-jpg-2","status":"inherit","uploaded_to":161387,"date":"2020-05-05 00:56:32","modified":"2025-08-05 18:46:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_image_link":{"title":"","url":"","target":"","0":""},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":125015,"id":125015,"title":"lass-id-original-1526597361-5afe06f1274c3.jpg","filename":"lass-id-original-1526597361-5afe06f1274c3.jpg","filesize":294887,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/attachment\/lass-id-original-1526597361-5afe06f1274c3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597361-5afe06f1274c3-jpg-2","status":"inherit","uploaded_to":161387,"date":"2020-05-05 00:56:32","modified":"2025-08-05 18:46:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}},"categories":[546,593,545],"tn-amenities":[],"tn-regions":[152],"silos":[633],"class_list":["post-161387","business","type-business","status-publish","has-post-thumbnail","hentry","category-actividades-en-familia","category-museos","category-puntos-de-interes-historico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estaci\u00f3n de bomberos hist\u00f3rica de Goldfield<\/title>\n<meta name=\"description\" content=\"Adem\u00e1s de albergar una gran cantidad de incre\u00edbles camiones de bomberos y ambulancias antiguas, la estaci\u00f3n de bomberos de Goldfield es importante para la historia de Goldfield debido a su conexi\u00f3n con la historia de los bomberos voluntarios...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estaci\u00f3n de bomberos hist\u00f3rica de Goldfield\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s de albergar una gran cantidad de incre\u00edbles camiones de bomberos y ambulancias antiguas, la estaci\u00f3n de bomberos de Goldfield es importante para la historia de Goldfield debido a su conexi\u00f3n con la historia de los bomberos voluntarios...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estaci\u00f3n de bomberos hist\u00f3rica de Goldfield","description":"Adem\u00e1s de albergar una gran cantidad de incre\u00edbles camiones de bomberos y ambulancias antiguas, la estaci\u00f3n de bomberos de Goldfield es importante para la historia de Goldfield debido a su conexi\u00f3n con la historia de los bomberos voluntarios...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/","og_locale":"es_ES","og_type":"article","og_title":"Estaci\u00f3n de bomberos hist\u00f3rica de Goldfield","og_description":"Adem\u00e1s de albergar una gran cantidad de incre\u00edbles camiones de bomberos y ambulancias antiguas, la estaci\u00f3n de bomberos de Goldfield es importante para la historia de Goldfield debido a su conexi\u00f3n con la historia de los bomberos voluntarios...","og_url":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","og_image":[{"width":1500,"height":844,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/","url":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/","name":"Estaci\u00f3n de bomberos hist\u00f3rica de Goldfield","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","datePublished":"2018-05-18T01:48:24+00:00","description":"Adem\u00e1s de albergar una gran cantidad de incre\u00edbles camiones de bomberos y ambulancias antiguas, la estaci\u00f3n de bomberos de Goldfield es importante para la historia de Goldfield debido a su conexi\u00f3n con la historia de los bomberos voluntarios...","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Estaci\u00f3n de bomberos hist\u00f3rica de Goldfield"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":125015,"id":125015,"title":"lass-id-original-1526597361-5afe06f1274c3.jpg","filename":"lass-id-original-1526597361-5afe06f1274c3.jpg","filesize":294887,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","link":"https:\/\/travelnevada.com\/es\/puntos-de-interes-historico\/estacion-de-bomberos-historica-de-goldfield\/attachment\/lass-id-original-1526597361-5afe06f1274c3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597361-5afe06f1274c3-jpg-2","status":"inherit","uploaded_to":161387,"date":"2020-05-05 00:56:32","modified":"2025-08-05 18:46:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":125017,"id":125017,"title":"lass-id-original-1526597355-5afe06eb5ef98.jpg","filename":"lass-id-original-1526597355-5afe06eb5ef98.jpg","filesize":406415,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1526597355-5afe06eb5ef98-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597355-5afe06eb5ef98-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 00:56:34","modified":"2020-05-05 00:56:34","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597355-5afe06eb5ef98.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":125019,"id":125019,"title":"lass-id-original-1526597372-5afe06fcc106f.jpg","filename":"lass-id-original-1526597372-5afe06fcc106f.jpg","filesize":314272,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1526597372-5afe06fcc106f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1526597372-5afe06fcc106f-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 00:56:36","modified":"2020-05-05 00:56:36","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":854,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f-300x171.jpg","medium-width":300,"medium-height":171,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f-768x437.jpg","medium_large-width":768,"medium_large-height":437,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f-1024x583.jpg","large-width":1024,"large-height":583,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","1536x1536-width":1500,"1536x1536-height":854,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","2048x2048-width":1500,"2048x2048-height":854,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":171,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":228,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597372-5afe06fcc106f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":342}}],"primary_category":{"term_id":546,"name":"Actividades en familia","slug":"actividades-en-familia","term_group":0,"term_taxonomy_id":546,"taxonomy":"category","description":"","parent":590,"count":209,"filter":"raw"},"silo_name":"Puntos de inter\u00e9s hist\u00f3rico","is_rural":"true","category_slugs":"actividades-en-familia,museos,puntos-de-interes-historico","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1526597361-5afe06f1274c3.jpg"},"featured_image_alt":"","friendly_post_date":"May 17, 2018","selected_region":[{"term_id":152,"name":"Goldfield","slug":"goldfield","term_group":0,"term_taxonomy_id":152,"taxonomy":"tn-regions","description":"","parent":21,"count":54,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":0,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/125015"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=161387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=161387"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=161387"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=161387"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=161387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}