{"id":161489,"date":"2017-06-18T17:52:32","date_gmt":"2017-06-19T00:52:32","guid":{"rendered":"https:\/\/travelnevada.com\/business\/amigos-de-black-rock-high-rock\/"},"modified":"2025-08-07T12:28:01","modified_gmt":"2025-08-07T19:28:01","slug":"amigos-de-black-rock-high-rock","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/","title":{"rendered":"Amigos de Black Rock-High Rock"},"content":{"rendered":"\n<p>\u201cLos lugares especiales merecen una protecci\u00f3n especial\u201d. As\u00ed es como Friends of Black Rock-High Rock resume perfectamente su misi\u00f3n de preservar y promover el \u00c1rea de Conservaci\u00f3n Nacional de Emigrantes del Ca\u00f1\u00f3n Black Rock Desert-High Rock. La organizaci\u00f3n, que administra un centro de visitantes en <a href=\"https:\/\/travelnevada.com\/es\/gerlach\/\">Gerlach<\/a>\u2014ofrece de todo, desde oportunidades de voluntariado y eventos especiales hasta recomendaciones para casi todo tipo de recreaci\u00f3n al aire libre en el \u00e1rea de Black Rock-High Rock.<\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Con \u00e9nfasis en la educaci\u00f3n, la conservaci\u00f3n y la recreaci\u00f3n responsable, Friends of Black Rock-High Rock trabaja para preservar la belleza natural y la integridad de lugares como el <a href=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/desierto-black-rock\/\">Desierto de Black Rock<\/a> y <a href=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/high-rock-canyon\/\">Ca\u00f1\u00f3n High Rock<\/a> para las generaciones futuras.<\/p><\/blockquote><\/figure>\n\n<h2 class=\"wp-block-heading\">Explorando la regi\u00f3n de Black Rock-High Rock<\/h2>\n\n<p>El <a href=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/desierto-black-rock\/\">Desierto de Black Rock<\/a> y sus tierras p\u00fablicas circundantes son conocidas por ser accidentadas y remotas. Friends of Black Rock-High Rock tiene muchos consejos de seguridad y recomendaciones de viaje para exploradores de todos los niveles de experiencia. Haga una parada en el centro de visitantes de Gerlach para obtener mapas y folletos gratuitos, adem\u00e1s de informaci\u00f3n en tiempo real sobre el clima local y las condiciones de las carreteras y la playa.<\/p>\n\n<p>Friends of Black Rock-High Rock tambi\u00e9n ofrece una gran cantidad de pautas y recomendaciones de recreaci\u00f3n. Aprenda sobre caminatas, ciclismo, campamentos, b\u00fasqueda de rocas, aguas termales, uso de veh\u00edculos todo terreno y m\u00e1s en el centro de visitantes o a trav\u00e9s de Friends of Black Rock-High Rock. <a href=\"https:\/\/www.blackrockdesert.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">sitio web s\u00faper informativo<\/a>. <\/p>\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2023\/09\/High-Rock-Canyon-Camping-1500x844-samwbrockway-1024x576.jpg\" alt=\"Ca&#xF1;&#xF3;n High Rock, Nevada\" class=\"wp-image-88742\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2023\/09\/High-Rock-Canyon-Camping-1500x844-samwbrockway-1024x576.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2023\/09\/High-Rock-Canyon-Camping-1500x844-samwbrockway-300x169.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2023\/09\/High-Rock-Canyon-Camping-1500x844-samwbrockway-768x432.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2023\/09\/High-Rock-Canyon-Camping-1500x844-samwbrockway.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/high-rock-canyon\/\">High Rock Canyon<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/11\/Fly-Geyser-bemytravelmuse-Desktop-1024x575.jpg\" alt=\"G&#xE9;iser Fly cerca de Gerlach, Nevada\" class=\"wp-image-156418\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/11\/Fly-Geyser-bemytravelmuse-Desktop-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/11\/Fly-Geyser-bemytravelmuse-Desktop-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/11\/Fly-Geyser-bemytravelmuse-Desktop-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/11\/Fly-Geyser-bemytravelmuse-Desktop.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/geiser-fly\/\">G\u00e9iser Fly<\/a><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading\">Paseos por la naturaleza en Fly Ranch<\/h2>\n\n<p>S\u00f3lo hay una manera de experimentar la belleza sobrenatural de <a href=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/geiser-fly\/\">G\u00e9iser Fly<\/a>: a trav\u00e9s del programa estacional de Friends of Black Rock-High Rock <a href=\"https:\/\/travelnevada.com\/es\/event\/paseos-por-la-naturaleza-en-fly-ranch\/\">Paseos por la naturaleza en Fly Ranch<\/a>.  En estas excursiones de tres horas, los asistentes obtienen acceso a todo tipo de maravillas dentro de Fly Ranch (propiedad del proyecto sin fines de lucro Burning Man). Esto incluye arte de Burning Man, exuberantes humedales, tres caracter\u00edsticas geot\u00e9rmicas y avistamientos rutinarios de caballos salvajes, coyotes y liebres.<\/p>\n\n<p>Friends of Black Rock-High Rock tambi\u00e9n organiza eventos de administraci\u00f3n del sitio, programas educativos, caminatas guiadas y campamentos nocturnos. Comprueba sus <a href=\"https:\/\/www.blackrockdesert.org\/events\" target=\"_blank\" rel=\"noreferrer noopener\">calendario de eventos<\/a> para conocer las \u00faltimas ofertas o considere convertirse en un <a href=\"https:\/\/www.blackrockdesert.org\/volunteer\" target=\"_blank\" rel=\"noreferrer noopener\">voluntario<\/a> o <a href=\"https:\/\/www.blackrockdesert.org\/becomeamember\" target=\"_blank\" rel=\"noreferrer noopener\">miembro<\/a> para apoyar a\u00fan m\u00e1s estos paisajes \u00fanicos y preciados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Friends of Black Rock-High Rock, que administra un centro de visitantes en Gerlach, ofrece de todo, desde oportunidades de voluntariado y caminatas por la naturaleza hasta recomendaciones para casi todo tipo de recreaci\u00f3n al aire libre en las \u00e1reas del desierto de Black Rock y el ca\u00f1\u00f3n High Rock.<\/p>\n","protected":false},"featured_media":156445,"menu_order":0,"template":"","meta":{"biz_address_line_1":"320 Main Street","biz_address_line_2":"P.O. Box 224","biz_attached_media":false,"biz_city":"Gerlach","biz_country":"United States","biz_latitude":"40.6517824","biz_longitude":"-119.35778","biz_phone_number":"(775) 625-7848","biz_postal_code":"89412","biz_state":"NV","biz_website":"https:\/\/www.blackrockdesert.org\/","biz_desktop_image":{"ID":156443,"id":156443,"title":"Friends-of-Black-Rock-High-Rock-Desktop","filename":"Friends-of-Black-Rock-High-Rock-Desktop.jpg","filesize":255489,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop.jpg","link":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/attachment\/friends-of-black-rock-high-rock-desktop-2\/","alt":"friends of black rock high rock visitor center in gerlach nevada","author":"27","description":"","caption":"","name":"friends-of-black-rock-high-rock-desktop-2","status":"inherit","uploaded_to":161489,"date":"2025-06-04 00:13:42","modified":"2025-08-05 18:47:24","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1140,"height":640,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop-300x168.jpg","medium-width":300,"medium-height":168,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop-768x431.jpg","medium_large-width":768,"medium_large-height":431,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop-1024x575.jpg","large-width":1024,"large-height":575,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop.jpg","1536x1536-width":1140,"1536x1536-height":640,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop.jpg","2048x2048-width":1140,"2048x2048-height":640,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":168,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Desktop.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},"biz_image_link":{"title":"","url":"","target":"","0":""},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":156447,"id":156447,"title":"Friends-of-Black-Rock-High-Rock-Mobile","filename":"Friends-of-Black-Rock-High-Rock-Mobile.jpg","filesize":205785,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile.jpg","link":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/attachment\/friends-of-black-rock-high-rock-mobile-2\/","alt":"friends of black rock high rock visitor center in gerlach nevada","author":"27","description":"","caption":"","name":"friends-of-black-rock-high-rock-mobile-2","status":"inherit","uploaded_to":161489,"date":"2025-06-04 00:13:51","modified":"2025-08-05 18:47:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":700,"height":900,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile-233x300.jpg","medium-width":233,"medium-height":300,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile.jpg","medium_large-width":700,"medium_large-height":900,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile.jpg","large-width":700,"large-height":900,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile.jpg","1536x1536-width":700,"1536x1536-height":900,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile.jpg","2048x2048-width":700,"2048x2048-height":900,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile.jpg","gform-image-choice-sm-width":233,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile.jpg","gform-image-choice-md-width":311,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Mobile.jpg","gform-image-choice-lg-width":467,"gform-image-choice-lg-height":600}},"biz_map_use_custom_map_link":false},"categories":[2,235],"tn-amenities":[],"tn-regions":[126],"silos":[560],"class_list":["post-161489","business","type-business","status-publish","has-post-thumbnail","hentry","category-outdoor-recreation","category-things-to-do"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amigos de Black Rock-High Rock | Administraci\u00f3n del desierto de Black Rock<\/title>\n<meta name=\"description\" content=\"Friends of Black Rock-High Rock ofrece asesoramiento experto en viajes y recomendaciones de recreaci\u00f3n al aire libre para las \u00e1reas del desierto de Black Rock y el ca\u00f1\u00f3n High Rock de Nevada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amigos de Black Rock-High Rock | Administraci\u00f3n del desierto de Black Rock\" \/>\n<meta property=\"og:description\" content=\"Friends of Black Rock-High Rock ofrece asesoramiento experto en viajes y recomendaciones de recreaci\u00f3n al aire libre para las \u00e1reas del desierto de Black Rock y el ca\u00f1\u00f3n High Rock de Nevada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-07T19:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amigos de Black Rock-High Rock | Administraci\u00f3n del desierto de Black Rock","description":"Friends of Black Rock-High Rock ofrece asesoramiento experto en viajes y recomendaciones de recreaci\u00f3n al aire libre para las \u00e1reas del desierto de Black Rock y el ca\u00f1\u00f3n High Rock de Nevada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/","og_locale":"es_ES","og_type":"article","og_title":"Amigos de Black Rock-High Rock | Administraci\u00f3n del desierto de Black Rock","og_description":"Friends of Black Rock-High Rock ofrece asesoramiento experto en viajes y recomendaciones de recreaci\u00f3n al aire libre para las \u00e1reas del desierto de Black Rock y el ca\u00f1\u00f3n High Rock de Nevada.","og_url":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","article_modified_time":"2025-08-07T19:28:01+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/","url":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/","name":"Amigos de Black Rock-High Rock | Administraci\u00f3n del desierto de Black Rock","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat.jpg","datePublished":"2017-06-19T00:52:32+00:00","dateModified":"2025-08-07T19:28:01+00:00","description":"Friends of Black Rock-High Rock ofrece asesoramiento experto en viajes y recomendaciones de recreaci\u00f3n al aire libre para las \u00e1reas del desierto de Black Rock y el ca\u00f1\u00f3n High Rock de Nevada.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat.jpg","width":1200,"height":675,"caption":"friends of black rock high rock visitor center in gerlach nevada"},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/amigos-de-black-rock-high-rock\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Amigos de Black Rock-High Rock"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":false,"primary_category":{"term_id":2,"name":"Outdoor Recreation","slug":"outdoor-recreation","term_group":0,"term_taxonomy_id":2,"taxonomy":"category","description":"","parent":243,"count":299,"filter":"raw"},"silo_name":"Diversi\u00f3n al aire libre","is_rural":"true","category_slugs":"outdoor-recreation,things-to-do","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/06\/Friends-of-Black-Rock-High-Rock-Feat.jpg"},"featured_image_alt":"","friendly_post_date":"June 18, 2017","selected_region":[{"term_id":126,"name":"Gerlach","slug":"gerlach","term_group":0,"term_taxonomy_id":126,"taxonomy":"tn-regions","description":"","parent":12,"count":46,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":3,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161489\/revisions"}],"predecessor-version":[{"id":162709,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161489\/revisions\/162709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/156445"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=161489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=161489"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=161489"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=161489"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=161489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}