{"id":161679,"date":"2019-07-22T13:09:55","date_gmt":"2019-07-22T20:09:55","guid":{"rendered":"https:\/\/travelnevada.com\/business\/pueblo-fantasma-de-belmont-mill\/"},"modified":"2019-07-22T13:09:55","modified_gmt":"2019-07-22T20:09:55","slug":"pueblo-fantasma-de-belmont-mill","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/","title":{"rendered":"Pueblo fantasma de Belmont Mill"},"content":{"rendered":"<p>Como hogar de m\u00e1s pueblos fantasmas que ciudades realmente pobladas, no deber\u00eda sorprender que haya restos asombrosos de la era minera hist\u00f3rica de Nevada detr\u00e1s de casi cada curva. Algunos son m\u00e1s f\u00e1ciles de acceder, lo que los convierte en los m\u00e1s visitados y comentados. Otros est\u00e1n protegidos por la proximidad, lo que, junto con los elementos \u00e1ridos del alto desierto, contribuye a una perfecta conservaci\u00f3n. Por suerte para usted, Belmont Mill ha permanecido en silencio entre los pi\u00f1ones y enebros durante m\u00e1s de cien a\u00f1os y es un ejemplo perfecto de un campamento minero de Nevada de principios del siglo XX que ha logrado sobrevivir mejor que la mayor\u00eda.<\/p>\n<h2><strong>LA GRAN ERA MINERA DE 1868-1870<\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" style=\"width: 100%;\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg\" alt=\"pueblo fantasma de Belmont\" width=\"1500\" height=\"844\"\/> Ubicado aproximadamente a una hora al oeste de Ely, en la carretera m\u00e1s solitaria de Estados Unidos, los amantes de los pueblos fantasmas estar\u00e1n encantados con esta aventura por carreteras secundarias porque no solo promete acceso a un pueblo fantasma de Nevada, sino a tres. No debe confundirse con <a href=\"https:\/\/travelnevada.com\/discover\/26442\/belmont-ghost-town\"><strong>Pueblo fantasma de Belmont<\/strong><\/a> Belmont Mill es un remanente del prestigioso auge minero de la zona que atrajo a los pioneros del oeste a regresar al este para apoderarse de su pedazo del sue\u00f1o americano. En este rinc\u00f3n de paisaje des\u00e9rtico de gran altitud, los visitantes encontrar\u00e1n los sitios hist\u00f3ricos de <a href=\"https:\/\/travelnevada.com\/discover\/44048\/hamilton-ghost-town\"><strong>Hamilton, Ciudad del Tesoro<\/strong><\/a>, Shermantown y Belmont Mill. Considerada como uno de los yacimientos de plata m\u00e1s puros que Nevada haya visto jam\u00e1s, la carrera para reclamar su lugar en estas laderas comenz\u00f3 a fines de la d\u00e9cada de 1860, especialmente despu\u00e9s de que <a href=\"https:\/\/travelnevada.com\/adventures\/33032\/transcontinental-railroad-fan-make-a-visit-to-these-train-museums-your-loco-motive\"><strong>Ferrocarril Transcontinental<\/strong><\/a> estaba completo Hamilton, Treasure City y Shermantown experimentaron un verdadero auge durante estos a\u00f1os, mientras que Belmont Mill no apareci\u00f3 en escena hasta principios del siglo XX, cuando Tonopah-Belmont Development Company comenz\u00f3 a desarrollar el \u00e1rea una vez m\u00e1s con la esperanza de extraer metales preciosos perdidos, esta vez con t\u00e9cnicas de miner\u00eda m\u00e1s sofisticadas. Se construy\u00f3 una ciudad empresarial con un importante respaldo financiero, pero a pesar de tantos esfuerzos, las minas simplemente no eran tan rentables como esperaban. En cuesti\u00f3n de unos pocos a\u00f1os, toda la operaci\u00f3n se cerr\u00f3 y, afortunadamente para usted, la mayor\u00eda de estas ruinas a\u00fan permanecen intactas hoy en d\u00eda.<\/p>\n<h2><strong>VISITA EL PUEBLO FANTASMA DE BELMONT MILL HOY<\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17941 size-large\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187-1024x576.jpg\" alt=\"Recorrido por el pueblo fantasma de Belmont Mill\" width=\"1024\" height=\"576\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187-1024x576.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187-300x169.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187-768x432.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> Aunque la mina Belmont original se encuentra m\u00e1s arriba del ca\u00f1\u00f3n que este sitio de molienda fue dise\u00f1ado para procesar, no queda mucho all\u00ed. Sin embargo, la historia no podr\u00eda ser m\u00e1s diferente cuando se trata de este sitio hist\u00f3rico del molino impresionantemente intacto. Originalmente, el mineral se transportaba desde la mina hasta este sitio del molino mediante un tranv\u00eda a\u00e9reo y, aunque esto era bastante com\u00fan en la \u00e9poca, muy pocos pueblos fantasmas conservan los cables o los carros de mineral todav\u00eda colgados. Aunque los carros de mineral desaparecieron hace tiempo, est\u00e9 atento a lo alto para ver la hist\u00f3rica l\u00ednea de tranv\u00eda de la que alguna vez dependi\u00f3 esta operaci\u00f3n, junto con toneladas de edificios que a\u00fan siguen en pie y que son importantes para la operaci\u00f3n. La oficina del molino, la casa del superintendente y la pensi\u00f3n a\u00fan siguen en pie, junto con un molino original de cuatro pisos, sorprendentemente intacto. Quiz\u00e1s lo m\u00e1s impresionante es esto: un carro de mineral, lleno de mineral a la espera de ser procesado, todav\u00eda est\u00e1 intacto y suspendido como si hubieran apagado la planta una tarde con la intenci\u00f3n de regresar, pero nunca lo hicieron. Aunque nunca se desarroll\u00f3 un verdadero distrito comercial en Belmont Mill, se construyeron algunas estructuras que a\u00fan se pueden ver detr\u00e1s del molino en las laderas circundantes. Est\u00e9 atento a las caba\u00f1as mineras hist\u00f3ricas, la maquinaria e incluso un pu\u00f1ado de autom\u00f3viles antiguos. <strong>Consejo profesional para viajar a Nevada:<\/strong> Una de las cosas m\u00e1s especiales de visitar pueblos fantasmas como Belmont Mill es el hecho de que est\u00e1n sorprendentemente intactos. Incluso si acabas de &amp;quot;descubrir&amp;quot; las reliquias mineras antiguas m\u00e1s geniales, la mejor regla general es esta: \u00a1an\u00edmate por haber encontrado un artefacto tan genial e importante para la historia del Estado de Plata! Toma algunas fotograf\u00edas, est\u00fadialas, intenta imaginar qui\u00e9n las habr\u00e1 usado y c\u00f3mo eran sus vidas. \u00bfEntonces? Deja a ese chico malo justo donde lo encontraste y sigue adelante. No s\u00f3lo es extremadamente desagradable tomar estas reliquias, sino que tambi\u00e9n es ilegal. Haz tu parte en <a href=\"https:\/\/travelnevada.com\/adventures\/33035\/beyond-the-asphalt-19-ways-to-live-by-the-dirt-road-code\"><strong>Avanzando la historia de Nevada<\/strong><\/a> para que el pr\u00f3ximo explorador de un pueblo fantasma pueda experimentar la misma incre\u00edble tarde fuera de la red que usted acaba de vivir.<\/p>\n<h3><strong>C\u00d3MO LLEGAR&nbsp;<\/strong><\/h3>\n<p>Belmont Mill est\u00e1 a solo una hora al oeste de Ely, por la autopista US 50. Hay algunas formas de acceder a este conjunto hist\u00f3rico de pueblos fantasmas, pero la forma m\u00e1s f\u00e1cil es directamente desde 50. El desv\u00edo est\u00e1 bien se\u00f1alizado, as\u00ed que est\u00e9 atento a una se\u00f1al verde que indica un giro a la izquierda al sur de la autopista 50. Siga este camino de tierra bien mantenido durante aproximadamente 10 millas. En la bifurcaci\u00f3n, mant\u00e9ngase a la derecha y siga unos kil\u00f3metros dentro del ca\u00f1\u00f3n hasta el sitio del molino. Hamilton Ghost Town est\u00e1 a s\u00f3lo 7 millas de Belmont Mill, pero acceder a \u00e9l es una historia completamente diferente. Belmont Mill es mucho m\u00e1s accesible durante todo el a\u00f1o porque no se requiere subir una gran elevaci\u00f3n y el camino es recto. Entonces, si est\u00e1s en la zona y no puedes acceder a Hamilton y Treasure City, Belmont Mill es un excelente plan B y vale cada minuto. <a href=\"https:\/\/travelnevada.com\/adventures\/33035\/beyond-the-asphalt-19-ways-to-live-by-the-dirt-road-code\"><strong>desv\u00edo de asfalto<\/strong><\/a>.  Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo explorar los pueblos fantasmas del \u00e1rea de Ely y las condiciones de las carreteras, llame directamente al Centro de Visitantes de Ely al (775) 289-3720.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como ejemplo perfecto de los campamentos mineros de Nevada de principios del siglo XX, este #NVGhostTown ha logrado sobrevivir mejor que otros gracias a su remota proximidad. Viva seg\u00fan el C\u00f3digo de caminos de tierra y explore este hist\u00f3rico molino de cuatro pisos y las estructuras circundantes que forman parte de este hist\u00f3rico pueblo fantasma de Nevada.<\/p>\n","protected":false},"featured_media":126305,"menu_order":0,"template":"","meta":{"biz_address_line_1":"50 Miles West Of Ely On US Highway 50","biz_address_line_2":"","biz_city":"Ely","biz_country":"United States","biz_latitude":"39.1635","biz_longitude":"-115.3052","biz_phone_number":"(775) 289-3720","biz_postal_code":"89301","biz_state":"NV","biz_website":"http:\/\/elynevada.net\/","biz_desktop_image":{"ID":126305,"id":126305,"title":"lass-id-original-1563815553-5d35ee81c9219.jpg","filename":"lass-id-original-1563815553-5d35ee81c9219.jpg","filesize":390336,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","link":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/attachment\/lass-id-original-1563815553-5d35ee81c9219-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815553-5d35ee81c9219-jpg-2","status":"inherit","uploaded_to":161679,"date":"2020-05-05 01:27:39","modified":"2025-08-05 18:51:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":126305,"id":126305,"title":"lass-id-original-1563815553-5d35ee81c9219.jpg","filename":"lass-id-original-1563815553-5d35ee81c9219.jpg","filesize":390336,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","link":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/attachment\/lass-id-original-1563815553-5d35ee81c9219-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815553-5d35ee81c9219-jpg-2","status":"inherit","uploaded_to":161679,"date":"2020-05-05 01:27:39","modified":"2025-08-05 18:51:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_attached_media":[{"ID":126305,"id":126305,"title":"lass-id-original-1563815553-5d35ee81c9219.jpg","filename":"lass-id-original-1563815553-5d35ee81c9219.jpg","filesize":390336,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","link":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/attachment\/lass-id-original-1563815553-5d35ee81c9219-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815553-5d35ee81c9219-jpg-2","status":"inherit","uploaded_to":161679,"date":"2020-05-05 01:27:39","modified":"2025-08-05 18:51:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126302,"id":126302,"title":"lass-id-original-1563815620-5d35eec4e067e.jpg","filename":"lass-id-original-1563815620-5d35eec4e067e.jpg","filesize":255318,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815620-5d35eec4e067e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815620-5d35eec4e067e-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:35","modified":"2020-05-05 01:27:35","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126300,"id":126300,"title":"lass-id-original-1563815572-5d35ee94a2802.jpg","filename":"lass-id-original-1563815572-5d35ee94a2802.jpg","filesize":564812,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815572-5d35ee94a2802-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815572-5d35ee94a2802-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:33","modified":"2020-05-05 01:27:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126307,"id":126307,"title":"lass-id-original-1563815523-5d35ee6361e64.jpg","filename":"lass-id-original-1563815523-5d35ee6361e64.jpg","filesize":433791,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815523-5d35ee6361e64-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815523-5d35ee6361e64-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:40","modified":"2020-05-05 01:27:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815523-5d35ee6361e64.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126304,"id":126304,"title":"lass-id-original-1563815529-5d35ee69c9187.jpg","filename":"lass-id-original-1563815529-5d35ee69c9187.jpg","filesize":442466,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187.jpg","link":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/attachment\/lass-id-original-1563815529-5d35ee69c9187-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815529-5d35ee69c9187-jpg-2","status":"inherit","uploaded_to":161679,"date":"2020-05-05 01:27:37","modified":"2025-08-05 18:51:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815529-5d35ee69c9187.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126309,"id":126309,"title":"lass-id-original-1563815536-5d35ee70b6fb8.jpg","filename":"lass-id-original-1563815536-5d35ee70b6fb8.jpg","filesize":485462,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815536-5d35ee70b6fb8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815536-5d35ee70b6fb8-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:42","modified":"2020-05-05 01:27:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815536-5d35ee70b6fb8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126311,"id":126311,"title":"lass-id-original-1563815607-5d35eeb764930.jpg","filename":"lass-id-original-1563815607-5d35eeb764930.jpg","filesize":311775,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815607-5d35eeb764930-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815607-5d35eeb764930-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:43","modified":"2020-05-05 01:27:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815607-5d35eeb764930.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126313,"id":126313,"title":"lass-id-original-1563815545-5d35ee794a43c.jpg","filename":"lass-id-original-1563815545-5d35ee794a43c.jpg","filesize":426317,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815545-5d35ee794a43c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815545-5d35ee794a43c-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:45","modified":"2020-05-05 01:27:45","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815545-5d35ee794a43c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126315,"id":126315,"title":"lass-id-original-1563815563-5d35ee8c00817.jpg","filename":"lass-id-original-1563815563-5d35ee8c00817.jpg","filesize":440017,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815563-5d35ee8c00817-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815563-5d35ee8c00817-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:47","modified":"2020-05-05 01:27:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815563-5d35ee8c00817.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126317,"id":126317,"title":"lass-id-original-1563815614-5d35eebed0d4c.jpg","filename":"lass-id-original-1563815614-5d35eebed0d4c.jpg","filesize":297308,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815614-5d35eebed0d4c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815614-5d35eebed0d4c-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:49","modified":"2020-05-05 01:27:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":851,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c-300x170.jpg","medium-width":300,"medium-height":170,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c-768x436.jpg","medium_large-width":768,"medium_large-height":436,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c-1024x581.jpg","large-width":1024,"large-height":581,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c.jpg","1536x1536-width":1500,"1536x1536-height":851,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c.jpg","2048x2048-width":1500,"2048x2048-height":851,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":170,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":227,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815614-5d35eebed0d4c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":340}},{"ID":126318,"id":126318,"title":"lass-id-original-1563815581-5d35ee9da1600.jpg","filename":"lass-id-original-1563815581-5d35ee9da1600.jpg","filesize":612293,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815581-5d35ee9da1600-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815581-5d35ee9da1600-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:50","modified":"2020-05-05 01:27:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815581-5d35ee9da1600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126319,"id":126319,"title":"lass-id-original-1563815593-5d35eea90ef4f.jpg","filename":"lass-id-original-1563815593-5d35eea90ef4f.jpg","filesize":381216,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815593-5d35eea90ef4f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815593-5d35eea90ef4f-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:52","modified":"2020-05-05 01:27:52","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815593-5d35eea90ef4f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_image_link":{"title":"","url":"","target":"","0":""},"biz_map_use_custom_map_link":false},"categories":[549,551],"tn-amenities":[],"tn-regions":[94],"silos":[571],"class_list":["post-161679","business","type-business","status-publish","has-post-thumbnail","hentry","category-atracciones","category-pueblo-fantasma"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pueblo fantasma de Belmont Mill<\/title>\n<meta name=\"description\" content=\"Como ejemplo perfecto de los campamentos mineros de Nevada de principios del siglo XX, este #NVGhostTown ha logrado sobrevivir mejor que otros gracias a su remota proximidad. Viva seg\u00fan el C\u00f3digo de caminos de tierra y explore este hist\u00f3rico molino de cuatro pisos y las estructuras circundantes que forman parte de este hist\u00f3rico pueblo fantasma de Nevada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pueblo fantasma de Belmont Mill\" \/>\n<meta property=\"og:description\" content=\"Como ejemplo perfecto de los campamentos mineros de Nevada de principios del siglo XX, este #NVGhostTown ha logrado sobrevivir mejor que otros gracias a su remota proximidad. Viva seg\u00fan el C\u00f3digo de caminos de tierra y explore este hist\u00f3rico molino de cuatro pisos y las estructuras circundantes que forman parte de este hist\u00f3rico pueblo fantasma de Nevada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pueblo fantasma de Belmont Mill","description":"Como ejemplo perfecto de los campamentos mineros de Nevada de principios del siglo XX, este #NVGhostTown ha logrado sobrevivir mejor que otros gracias a su remota proximidad. Viva seg\u00fan el C\u00f3digo de caminos de tierra y explore este hist\u00f3rico molino de cuatro pisos y las estructuras circundantes que forman parte de este hist\u00f3rico pueblo fantasma de Nevada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/","og_locale":"es_ES","og_type":"article","og_title":"Pueblo fantasma de Belmont Mill","og_description":"Como ejemplo perfecto de los campamentos mineros de Nevada de principios del siglo XX, este #NVGhostTown ha logrado sobrevivir mejor que otros gracias a su remota proximidad. Viva seg\u00fan el C\u00f3digo de caminos de tierra y explore este hist\u00f3rico molino de cuatro pisos y las estructuras circundantes que forman parte de este hist\u00f3rico pueblo fantasma de Nevada.","og_url":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","og_image":[{"width":1500,"height":844,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/","url":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/","name":"Pueblo fantasma de Belmont Mill","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","datePublished":"2019-07-22T20:09:55+00:00","description":"Como ejemplo perfecto de los campamentos mineros de Nevada de principios del siglo XX, este #NVGhostTown ha logrado sobrevivir mejor que otros gracias a su remota proximidad. Viva seg\u00fan el C\u00f3digo de caminos de tierra y explore este hist\u00f3rico molino de cuatro pisos y las estructuras circundantes que forman parte de este hist\u00f3rico pueblo fantasma de Nevada.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pueblo fantasma de Belmont Mill"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":126305,"id":126305,"title":"lass-id-original-1563815553-5d35ee81c9219.jpg","filename":"lass-id-original-1563815553-5d35ee81c9219.jpg","filesize":390336,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","link":"https:\/\/travelnevada.com\/es\/pueblo-fantasma\/pueblo-fantasma-de-belmont-mill\/attachment\/lass-id-original-1563815553-5d35ee81c9219-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815553-5d35ee81c9219-jpg-2","status":"inherit","uploaded_to":161679,"date":"2020-05-05 01:27:39","modified":"2025-08-05 18:51:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126302,"id":126302,"title":"lass-id-original-1563815620-5d35eec4e067e.jpg","filename":"lass-id-original-1563815620-5d35eec4e067e.jpg","filesize":255318,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815620-5d35eec4e067e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815620-5d35eec4e067e-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:35","modified":"2020-05-05 01:27:35","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815620-5d35eec4e067e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126300,"id":126300,"title":"lass-id-original-1563815572-5d35ee94a2802.jpg","filename":"lass-id-original-1563815572-5d35ee94a2802.jpg","filesize":564812,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563815572-5d35ee94a2802-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563815572-5d35ee94a2802-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:27:33","modified":"2020-05-05 01:27:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815572-5d35ee94a2802.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"primary_category":{"term_id":549,"name":"Atracciones","slug":"atracciones","term_group":0,"term_taxonomy_id":549,"taxonomy":"category","description":"","parent":0,"count":112,"filter":"raw"},"silo_name":"Pueblo fantasma","is_rural":"true","category_slugs":"atracciones,pueblo-fantasma","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563815553-5d35ee81c9219.jpg"},"featured_image_alt":"","friendly_post_date":"July 22, 2019","selected_region":[{"term_id":94,"name":"Ely","slug":"ely","term_group":0,"term_taxonomy_id":94,"taxonomy":"tn-regions","description":"","parent":16,"count":105,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":0,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/126305"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=161679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=161679"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=161679"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=161679"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=161679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}