{"id":161717,"date":"2019-07-02T15:35:31","date_gmt":"2019-07-02T22:35:31","guid":{"rendered":"https:\/\/travelnevada.com\/business\/sendero-de-la-costa-este-de-tahoe\/"},"modified":"2019-07-02T15:35:31","modified_gmt":"2019-07-02T22:35:31","slug":"sendero-de-la-costa-este-de-tahoe","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/","title":{"rendered":"Sendero de la costa este de Tahoe"},"content":{"rendered":"<p>Conocido como \u201cel carril bici m\u00e1s hermoso de Estados Unidos\u201d, el tan esperado Tahoe East Shore Trail no solo es una forma espectacular de recrearse en el lago alpino m\u00e1s grande de Am\u00e9rica del Norte, sino tambi\u00e9n&nbsp;Proporciona acceso directo a playas p\u00fablicas, calas y senderos a lo largo de la pintoresca costa de Nevada. Ubicado en North Lake Tahoe, el m\u00e1s cercano <a href=\"https:\/\/travelnevada.com\/discover\/31562\/incline-village\"><strong>Pueblo inclinado<\/strong><\/a> Este nuevo sistema de senderos se encuentra debajo de la carretera que bordea la costa este del lago Tahoe, lo que proporciona vistas sin filtro y un acceso incomparable al lago Tahoe.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/zz6b2nau408\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Abierto a partir de junio de 2019, este sistema de senderos pavimentados de 3 millas conecta Incline Village al sur con Sand Harbor State Park, uno de los cuatro <a href=\"https:\/\/travelnevada.com\/discover\/25963\/lake-tahoe-nevada-state-park\"><strong>Parques estatales del lago Tahoe, Nevada<\/strong><\/a>.  A pesar de tener solo tres millas de largo, este proyecto llev\u00f3 d\u00e9cadas para llevarse a cabo (requiriendo la integraci\u00f3n de m\u00faltiples gobiernos federales, estatales y locales), allanando el camino para el futuro desarrollo recreativo que eventualmente se extender\u00e1 por toda la costa del Lago Tahoe. Antes del Tahoe East Shore Trail, acceder a cualquier l\u00ednea de playa en este tramo de North Lake Tahoe no solo era dif\u00edcil, sino tambi\u00e9n peligroso. <img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" style=\"width: 100%;\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg\" alt=\"Sendero de la costa este de Tahoe\" width=\"1500\" height=\"844\"\/>Abierto desde el amanecer hasta el atardecer, tanto los visitantes como los locales pueden caminar o andar en bicicleta desde Incline Village hasta Sand Harbor. Se admiten bicicletas el\u00e9ctricas con asistencia de pedaleo, pero deje los veh\u00edculos motorizados o scooters en casa. Se admiten perros en el camino, pero deben estar atados.<\/p>\n<h2><strong>C\u00d3MO LLEGAR<\/strong><\/h2>\n<p>M\u00e1s cercana al North Lake Tahoe de Incline Village, esta comunidad se encuentra a unos 45 minutos del centro de Reno. Desde Reno, dir\u00edjase hacia el sur por la I-580 sur y salga en Mount Rose Highway. Siga la autopista Mount Rose o la ruta estatal 431 durante aproximadamente 22 millas hasta Incline Village. Una vez que haya llegado a Incline, dir\u00edjase a Ponderosa Ranch Road, donde podr\u00e1 estacionar su veh\u00edculo y acceder al comienzo del sendero. Para obtener informaci\u00f3n sobre el acceso a los senderos y otras cosas para ver y hacer en North Lake Tahoe, llame a la Oficina de visitantes de Incline Village y Crystal Bay al (775) 832-1606.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sendero para bicicletas m\u00e1s nuevo del lago Tahoe lleva a los visitantes a la pr\u00edstina costa este del norte del lago Tahoe, con acceso directo a playas p\u00fablicas, calas y senderos para caminatas.&nbsp;<\/p>\n","protected":false},"featured_media":178375,"menu_order":0,"template":"","meta":{"biz_address_line_2":"","biz_city":"Incline Village","biz_country":"United States","biz_latitude":"39.2476504","biz_longitude":"-119.94167","biz_phone_number":"(775) 832-1606","biz_postal_code":"89451","biz_state":"NV","biz_map_type":"address-page-title","biz_map_use_custom_map_link":false,"biz_admission":"<p>Hay noventa nuevos lugares de estacionamiento con acceso directo al sendero disponibles en tres nuevos estacionamientos ubicados a lo largo de la Ruta Estatal 28 en Incline Village, cerca de Ponderosa Ranch Road. Se requiere estacionamiento pago propio y la mayor\u00eda de las ganancias se destinar\u00e1n al mantenimiento del sendero. East Shore Express del Distrito de Transporte de Tahoe y Tahoe Truckee Area Regional Transit (TART) ofrecer\u00e1n servicio de autob\u00fas hasta el nuevo sendero durante los meses de verano.<\/p>\n","biz_address_line_1":"1924 Tahoe Boulevard","biz_website":"https:\/\/laketahoetravel.com\/the-tahoe-east-shore-trail\/","biz_mobile_image":{"ID":178377,"id":178377,"title":"family-walking-tahoe-east-shore-trail","filename":"family-walking-tahoe-east-shore-trail.jpg","filesize":165105,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail.jpg","link":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/attachment\/family-walking-tahoe-east-shore-trail-2\/","alt":"family walking tahoe east shore trail","author":"3","description":"","caption":"","name":"family-walking-tahoe-east-shore-trail-2","status":"inherit","uploaded_to":161717,"date":"2026-05-14 21:25:49","modified":"2026-05-14 21:27:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1140,"height":640,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-300x168.jpg","medium-width":300,"medium-height":168,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-768x431.jpg","medium_large-width":768,"medium_large-height":431,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-1024x575.jpg","large-width":1024,"large-height":575,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail.jpg","1536x1536-width":1140,"1536x1536-height":640,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail.jpg","2048x2048-width":1140,"2048x2048-height":640,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":168,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},"biz_desktop_image":{"ID":178375,"id":178375,"title":"family-walking-tahoe-east-shore-trail-Feat","filename":"family-walking-tahoe-east-shore-trail-Feat.jpg","filesize":127057,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","link":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/attachment\/family-walking-tahoe-east-shore-trail-feat-2\/","alt":"family walking tahoe east shore trail","author":"3","description":"","caption":"","name":"family-walking-tahoe-east-shore-trail-feat-2","status":"inherit","uploaded_to":161717,"date":"2026-05-14 21:25:09","modified":"2026-05-14 21:25:22","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1200,"height":675,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","1536x1536-width":1200,"1536x1536-height":675,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","2048x2048-width":1200,"2048x2048-height":675,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_attached_media":[{"ID":126206,"id":126206,"title":"lass-id-original-1562096265-5d1bb28953fd2.jpg","filename":"lass-id-original-1562096265-5d1bb28953fd2.jpg","filesize":421794,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1562096265-5d1bb28953fd2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1562096265-5d1bb28953fd2-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:26:03","modified":"2020-05-05 01:26:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126208,"id":126208,"title":"lass-id-original-1562096265-5d1bb28953ed5.jpg","filename":"lass-id-original-1562096265-5d1bb28953ed5.jpg","filesize":304141,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","link":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/attachment\/lass-id-original-1562096265-5d1bb28953ed5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1562096265-5d1bb28953ed5-jpg-2","status":"inherit","uploaded_to":161717,"date":"2020-05-05 01:26:04","modified":"2025-08-05 18:52:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_image_link":{"title":"","url":"","target":"","0":""}},"categories":[288,3,2],"tn-amenities":[],"tn-regions":[47],"silos":[560],"class_list":["post-161717","business","type-business","status-publish","has-post-thumbnail","hentry","category-attraction","category-cycling-and-biking","category-outdoor-recreation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sendero de la costa este de Tahoe<\/title>\n<meta name=\"description\" content=\"El sendero para bicicletas m\u00e1s nuevo del lago Tahoe lleva a los visitantes a la pr\u00edstina costa este del norte del lago Tahoe, con acceso directo a playas p\u00fablicas, calas y senderos para caminatas.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sendero de la costa este de Tahoe\" \/>\n<meta property=\"og:description\" content=\"El sendero para bicicletas m\u00e1s nuevo del lago Tahoe lleva a los visitantes a la pr\u00edstina costa este del norte del lago Tahoe, con acceso directo a playas p\u00fablicas, calas y senderos para caminatas.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sendero de la costa este de Tahoe","description":"El sendero para bicicletas m\u00e1s nuevo del lago Tahoe lleva a los visitantes a la pr\u00edstina costa este del norte del lago Tahoe, con acceso directo a playas p\u00fablicas, calas y senderos para caminatas.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/","og_locale":"es_ES","og_type":"article","og_title":"Sendero de la costa este de Tahoe","og_description":"El sendero para bicicletas m\u00e1s nuevo del lago Tahoe lleva a los visitantes a la pr\u00edstina costa este del norte del lago Tahoe, con acceso directo a playas p\u00fablicas, calas y senderos para caminatas.\u00a0","og_url":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","og_image":[{"width":1200,"height":675,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/","url":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/","name":"Sendero de la costa este de Tahoe","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","datePublished":"2019-07-02T22:35:31+00:00","description":"El sendero para bicicletas m\u00e1s nuevo del lago Tahoe lleva a los visitantes a la pr\u00edstina costa este del norte del lago Tahoe, con acceso directo a playas p\u00fablicas, calas y senderos para caminatas.\u00a0","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","width":1200,"height":675,"caption":"family walking tahoe east shore trail"},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sendero de la costa este de Tahoe"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":126206,"id":126206,"title":"lass-id-original-1562096265-5d1bb28953fd2.jpg","filename":"lass-id-original-1562096265-5d1bb28953fd2.jpg","filesize":421794,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1562096265-5d1bb28953fd2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1562096265-5d1bb28953fd2-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-05 01:26:03","modified":"2020-05-05 01:26:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953fd2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":126208,"id":126208,"title":"lass-id-original-1562096265-5d1bb28953ed5.jpg","filename":"lass-id-original-1562096265-5d1bb28953ed5.jpg","filesize":304141,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","link":"https:\/\/travelnevada.com\/es\/diversion-al-aire-libre\/sendero-de-la-costa-este-de-tahoe\/attachment\/lass-id-original-1562096265-5d1bb28953ed5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1562096265-5d1bb28953ed5-jpg-2","status":"inherit","uploaded_to":161717,"date":"2020-05-05 01:26:04","modified":"2025-08-05 18:52:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1562096265-5d1bb28953ed5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"primary_category":{"term_id":288,"name":"Attractions","slug":"attraction","term_group":0,"term_taxonomy_id":288,"taxonomy":"category","description":"","parent":0,"count":126,"filter":"raw"},"silo_name":"Diversi\u00f3n al aire libre","is_rural":"true","category_slugs":"attraction,cycling-and-biking,outdoor-recreation","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2019\/07\/family-walking-tahoe-east-shore-trail-Feat.jpg"},"featured_image_alt":"","friendly_post_date":"July 02, 2019","selected_region":[{"term_id":47,"name":"North Lake Tahoe","slug":"north-lake-tahoe","term_group":0,"term_taxonomy_id":47,"taxonomy":"tn-regions","description":"","parent":6,"count":92,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":0,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/161717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/178375"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=161717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=161717"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=161717"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=161717"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=161717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}