{"id":162950,"date":"2014-04-03T23:09:47","date_gmt":"2014-04-04T06:09:47","guid":{"rendered":"https:\/\/travelnevada.com\/business\/virgin-valley-heritage-museum\/"},"modified":"2014-04-03T23:09:47","modified_gmt":"2014-04-04T06:09:47","slug":"virgin-valley-heritage-museum","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/","title":{"rendered":"Virgin Valley Heritage Museum"},"content":{"rendered":"<p>Con sede en la encantadora comunidad de Mesquite, en el sureste de Nevada, el Virgin Valley Heritage Museum no solo cuenta la fascinante historia de la zona, sino que tambi\u00e9n est\u00e1 ubicado en un pedazo de historia en s\u00ed mismo. Hoy en d\u00eda, este aut\u00e9ntico edificio de estilo pueblo se utiliza como museo, pero el edificio fue construido originalmente gracias a los esfuerzos de los <a href=\"https:\/\/travelnevada.com\/adventures\/32876\/ccc-in-nevada\"><strong>Cuerpo Civil de Conservaci\u00f3n<\/strong><\/a>.  Aunque no pudieron terminar la estructura antes de que se disolviera este programa nacional, los ganaderos locales intervinieron para asegurar la finalizaci\u00f3n del edificio. En 1940, el edificio abri\u00f3 sus puertas como biblioteca y m\u00e1s tarde se transform\u00f3 en una sucursal del Southern Nevada Memorial Hospital, que funcion\u00f3 como consultorio m\u00e9dico local durante d\u00e9cadas. Antes de convertirse en la sede del museo, el edificio tambi\u00e9n sirvi\u00f3 a los Boy Scouts of America. Hoy en d\u00eda, este fascinante edificio de estilo neopueblo es <a href=\"https:\/\/travelnevada.com\/discover\/25974\/lost-city-museum-overton\"><strong>Uno de los dos \u00fanicos en Nevada<\/strong><\/a>, y est\u00e1 incluido en el Registro Nacional de Lugares Hist\u00f3ricos. El Museo del Patrimonio de Virgin Valley alberga una variedad de colecciones interesantes, que est\u00e1n dedicadas a preservar el rico patrimonio cultural de la regi\u00f3n mientras comparten las historias de los primeros habitantes ind\u00edgenas americanos del \u00e1rea y los primeros pioneros colonizadores. Antes de ingresar a este enriquecedor centro cultural, los visitantes son recibidos por un marcador hist\u00f3rico del Antiguo Sendero Espa\u00f1ol. Las exhibiciones y muestras dentro del Museo del Patrimonio de Virgin Valley presentan artefactos que datan de 1875 a 1935, incluyendo artefactos invaluables como la primera m\u00e1quina tragamonedas del valle, una impresionante colecci\u00f3n de colchas antiguas hechas a mano, vestidos de novia antiguos y un telar hist\u00f3rico. Durante su visita, no olvide ver los primeros tel\u00e9fonos y proyectores de pel\u00edculas, un televisor de 1949 y una completa colecci\u00f3n de fotograf\u00edas hist\u00f3ricas. Adem\u00e1s de los artefactos en s\u00ed, los visitantes pueden explorar el centro de medios del museo, una sala de estar de la d\u00e9cada de 1920 con una Victrola en funcionamiento, una biblioteca hist\u00f3rica y un recorrido a pie por los crecientes archivos fotogr\u00e1ficos del museo. Las exhibiciones permanentes y rotativas del Museo hacen un maravilloso trabajo al ofrecer una perspectiva interesante de las experiencias de la vida diaria de los primeros habitantes de la regi\u00f3n, detallando un hilo importante de la historia de Nevada que no se encuentra en ning\u00fan otro lugar del estado.<\/p>\n<h2><strong>ADMISI\u00d3N<\/strong><\/h2>\n<p>La entrada al Museo del Patrimonio del Valle Virgen de Mesquite es gratuita, aunque este enriquecedor centro cultural depende de donaciones. Estas contribuciones ayudan a establecer y preservar las exhibiciones del museo y respaldan futuras ampliaciones de la propiedad. Cuando visite este valioso recurso hist\u00f3rico, \u00a1considere hacer una donaci\u00f3n!<\/p>\n<h2><strong>HORAS<\/strong><\/h2>\n<p>Abierto de martes a s\u00e1bado de 10:00 a 16:00 horas. Se ofrecen visitas grupales que se pueden organizar f\u00e1cilmente con cita previa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Museo del Patrimonio de Virgin Valley en Mesquite est\u00e1 ubicado en un edificio hist\u00f3rico que ha desempe\u00f1ado muchas funciones a lo largo de sus casi 70 a\u00f1os de historia.<\/p>\n","protected":false},"featured_media":113045,"menu_order":0,"template":"","meta":{"biz_address_line_1":"35 W. Mesquite Boulevard","biz_address_line_2":"","biz_attached_media":[{"ID":113045,"id":113045,"title":"lass-id-original-1533167050-5b6245ca771f0.jpg","filename":"lass-id-original-1533167050-5b6245ca771f0.jpg","filesize":317542,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","link":"https:\/\/travelnevada.com\/es\/museums\/virgin-valley-heritage-museum\/attachment\/lass-id-original-1533167050-5b6245ca771f0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167050-5b6245ca771f0-jpg-2","status":"inherit","uploaded_to":19919,"date":"2020-04-23 20:51:53","modified":"2020-04-23 20:51:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113046,"id":113046,"title":"lass-id-original-1533167206-5b624666e6da6.jpg","filename":"lass-id-original-1533167206-5b624666e6da6.jpg","filesize":246693,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113046","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167206-5b624666e6da6-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:51:55","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113047,"id":113047,"title":"lass-id-original-1533167213-5b62466dcb560.jpg","filename":"lass-id-original-1533167213-5b62466dcb560.jpg","filesize":193384,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113047","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167213-5b62466dcb560-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:51:56","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113048,"id":113048,"title":"lass-id-original-1533167106-5b624602a876d.jpg","filename":"lass-id-original-1533167106-5b624602a876d.jpg","filesize":201200,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113048","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167106-5b624602a876d-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:51:57","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167106-5b624602a876d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113049,"id":113049,"title":"lass-id-original-1533167256-5b6246981cb1e.jpg","filename":"lass-id-original-1533167256-5b6246981cb1e.jpg","filesize":162712,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113049","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167256-5b6246981cb1e-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:51:59","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167256-5b6246981cb1e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113050,"id":113050,"title":"lass-id-original-1533167066-5b6245da437e6.jpg","filename":"lass-id-original-1533167066-5b6245da437e6.jpg","filesize":217188,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113050","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167066-5b6245da437e6-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:00","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167066-5b6245da437e6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},{"ID":113051,"id":113051,"title":"lass-id-original-1533167269-5b6246a5d7c74.jpg","filename":"lass-id-original-1533167269-5b6246a5d7c74.jpg","filesize":247695,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113051","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167269-5b6246a5d7c74-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:01","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167269-5b6246a5d7c74.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113052,"id":113052,"title":"lass-id-original-1533167250-5b6246920aa90.jpg","filename":"lass-id-original-1533167250-5b6246920aa90.jpg","filesize":329462,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113052","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167250-5b6246920aa90-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:02","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167250-5b6246920aa90.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113053,"id":113053,"title":"lass-id-original-1533167227-5b62467b16a8e.jpg","filename":"lass-id-original-1533167227-5b62467b16a8e-scaled.jpg","filesize":475640,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-scaled.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113053","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167227-5b62467b16a8e-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:04","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167227-5b62467b16a8e-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113054,"id":113054,"title":"lass-id-original-1533167121-5b624611d1782.jpg","filename":"lass-id-original-1533167121-5b624611d1782.jpg","filesize":239452,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113054","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167121-5b624611d1782-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:09","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167121-5b624611d1782.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113055,"id":113055,"title":"lass-id-original-1533167103-5b6245ff7569a.jpg","filename":"lass-id-original-1533167103-5b6245ff7569a.jpg","filesize":295447,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113055","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167103-5b6245ff7569a-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:11","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167103-5b6245ff7569a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113056,"id":113056,"title":"lass-id-original-1533167113-5b6246096d2eb.jpg","filename":"lass-id-original-1533167113-5b6246096d2eb.jpg","filesize":206329,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113056","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167113-5b6246096d2eb-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:12","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167113-5b6246096d2eb.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113057,"id":113057,"title":"lass-id-original-1533167117-5b62460dd4158.jpg","filename":"lass-id-original-1533167117-5b62460dd4158.jpg","filesize":175008,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113057","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167117-5b62460dd4158-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:13","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167117-5b62460dd4158.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113058,"id":113058,"title":"lass-id-original-1533167127-5b624617042c9.jpg","filename":"lass-id-original-1533167127-5b624617042c9.jpg","filesize":256881,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113058","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167127-5b624617042c9-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:15","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167127-5b624617042c9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113059,"id":113059,"title":"lass-id-original-1533167156-5b62463446825.jpg","filename":"lass-id-original-1533167156-5b62463446825.jpg","filesize":203574,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113059","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167156-5b62463446825-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:16","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167156-5b62463446825.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113060,"id":113060,"title":"lass-id-original-1533167159-5b624637cbf7e.jpg","filename":"lass-id-original-1533167159-5b624637cbf7e.jpg","filesize":157114,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113060","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167159-5b624637cbf7e-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:17","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167159-5b624637cbf7e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113061,"id":113061,"title":"lass-id-original-1533167171-5b624643c8937.jpg","filename":"lass-id-original-1533167171-5b624643c8937.jpg","filesize":166135,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113061","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167171-5b624643c8937-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:18","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167171-5b624643c8937.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113062,"id":113062,"title":"lass-id-original-1533167179-5b62464b7158d.jpg","filename":"lass-id-original-1533167179-5b62464b7158d.jpg","filesize":278419,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113062","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167179-5b62464b7158d-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:20","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167179-5b62464b7158d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113063,"id":113063,"title":"lass-id-original-1533167231-5b62467fd77f1.jpg","filename":"lass-id-original-1533167231-5b62467fd77f1.jpg","filesize":278075,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113063","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167231-5b62467fd77f1-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:21","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167231-5b62467fd77f1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113064,"id":113064,"title":"lass-id-original-1533167187-5b624653ac5ff.jpg","filename":"lass-id-original-1533167187-5b624653ac5ff.jpg","filesize":288248,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113064","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167187-5b624653ac5ff-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:22","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167187-5b624653ac5ff.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113065,"id":113065,"title":"lass-id-original-1533167056-5b6245d0d38ae.jpg","filename":"lass-id-original-1533167056-5b6245d0d38ae.jpg","filesize":284645,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113065","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167056-5b6245d0d38ae-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:52:24","modified":"2026-06-25 01:27:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167056-5b6245d0d38ae.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_city":"Mesquite","biz_country":"United States","biz_latitude":"36.804140","biz_longitude":"-114.06872","biz_phone_number":"(702) 346-5705","biz_postal_code":"89027","biz_state":"NV","biz_website":"https:\/\/www.facebook.com\/MesquiteNVMuseum\/","biz_desktop_image":{"ID":113045,"id":113045,"title":"lass-id-original-1533167050-5b6245ca771f0.jpg","filename":"lass-id-original-1533167050-5b6245ca771f0.jpg","filesize":317542,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","link":"https:\/\/travelnevada.com\/es\/museums\/virgin-valley-heritage-museum\/attachment\/lass-id-original-1533167050-5b6245ca771f0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167050-5b6245ca771f0-jpg-2","status":"inherit","uploaded_to":19919,"date":"2020-04-23 20:51:53","modified":"2020-04-23 20:51:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_image_link":{"title":"","url":"","target":"","0":""},"biz_map_type":"address-page-title","biz_mobile_image":{"ID":113045,"id":113045,"title":"lass-id-original-1533167050-5b6245ca771f0.jpg","filename":"lass-id-original-1533167050-5b6245ca771f0.jpg","filesize":317542,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","link":"https:\/\/travelnevada.com\/es\/museums\/virgin-valley-heritage-museum\/attachment\/lass-id-original-1533167050-5b6245ca771f0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167050-5b6245ca771f0-jpg-2","status":"inherit","uploaded_to":19919,"date":"2020-04-23 20:51:53","modified":"2020-04-23 20:51:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}},"categories":[63],"tn-amenities":[],"tn-regions":[105],"silos":[607],"class_list":["post-162950","business","type-business","status-publish","has-post-thumbnail","hentry","category-museums"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virgin Valley Heritage Museum<\/title>\n<meta name=\"description\" content=\"El Museo del Patrimonio de Virgin Valley en Mesquite est\u00e1 ubicado en un edificio hist\u00f3rico que ha desempe\u00f1ado muchas funciones a lo largo de sus casi 70 a\u00f1os de historia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virgin Valley Heritage Museum\" \/>\n<meta property=\"og:description\" content=\"El Museo del Patrimonio de Virgin Valley en Mesquite est\u00e1 ubicado en un edificio hist\u00f3rico que ha desempe\u00f1ado muchas funciones a lo largo de sus casi 70 a\u00f1os de historia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virgin Valley Heritage Museum","description":"El Museo del Patrimonio de Virgin Valley en Mesquite est\u00e1 ubicado en un edificio hist\u00f3rico que ha desempe\u00f1ado muchas funciones a lo largo de sus casi 70 a\u00f1os de historia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/","og_locale":"es_ES","og_type":"article","og_title":"Virgin Valley Heritage Museum","og_description":"El Museo del Patrimonio de Virgin Valley en Mesquite est\u00e1 ubicado en un edificio hist\u00f3rico que ha desempe\u00f1ado muchas funciones a lo largo de sus casi 70 a\u00f1os de historia.","og_url":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","og_image":[{"width":1500,"height":844,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/","url":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/","name":"Virgin Valley Heritage Museum","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","datePublished":"2014-04-04T06:09:47+00:00","description":"El Museo del Patrimonio de Virgin Valley en Mesquite est\u00e1 ubicado en un edificio hist\u00f3rico que ha desempe\u00f1ado muchas funciones a lo largo de sus casi 70 a\u00f1os de historia.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/museos\/virgin-valley-heritage-museum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Virgin Valley Heritage Museum"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":113045,"id":113045,"title":"lass-id-original-1533167050-5b6245ca771f0.jpg","filename":"lass-id-original-1533167050-5b6245ca771f0.jpg","filesize":317542,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","link":"https:\/\/travelnevada.com\/es\/museums\/virgin-valley-heritage-museum\/attachment\/lass-id-original-1533167050-5b6245ca771f0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167050-5b6245ca771f0-jpg-2","status":"inherit","uploaded_to":19919,"date":"2020-04-23 20:51:53","modified":"2020-04-23 20:51:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113046,"id":113046,"title":"lass-id-original-1533167206-5b624666e6da6.jpg","filename":"lass-id-original-1533167206-5b624666e6da6.jpg","filesize":246693,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113046","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167206-5b624666e6da6-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:51:55","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167206-5b624666e6da6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":113047,"id":113047,"title":"lass-id-original-1533167213-5b62466dcb560.jpg","filename":"lass-id-original-1533167213-5b62466dcb560.jpg","filesize":193384,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","link":"https:\/\/travelnevada.com\/es\/?attachment_id=113047","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1533167213-5b62466dcb560-jpg-2","status":"inherit","uploaded_to":180438,"date":"2020-04-23 20:51:56","modified":"2026-06-25 01:27:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167213-5b62466dcb560.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"primary_category":{"term_id":63,"name":"Museums","slug":"museums","term_group":0,"term_taxonomy_id":63,"taxonomy":"category","description":"","parent":235,"count":98,"filter":"raw"},"silo_name":"Museos","is_rural":"true","category_slugs":"museums","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1533167050-5b6245ca771f0.jpg"},"featured_image_alt":"","friendly_post_date":"April 03, 2014","selected_region":[{"term_id":105,"name":"Mesquite","slug":"mesquite","term_group":0,"term_taxonomy_id":105,"taxonomy":"tn-regions","description":"","parent":8,"count":56,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/162950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":0,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/162950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/113045"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=162950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=162950"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=162950"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=162950"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=162950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}