{"id":163008,"date":"2014-04-03T23:09:41","date_gmt":"2014-04-04T06:09:41","guid":{"rendered":"https:\/\/travelnevada.com\/business\/area-recreativa-estatal-wild-horse\/"},"modified":"2025-08-11T10:51:22","modified_gmt":"2025-08-11T17:51:22","slug":"area-recreativa-estatal-wild-horse","status":"publish","type":"business","link":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/","title":{"rendered":"\u00c1rea recreativa estatal Wild Horse"},"content":{"rendered":"\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"pro-tip --travel-alert\">\n    <div class=\"pro-tip__container\">\n        <div class=\"pro-tip__highlight-container\">\n                            <div class=\"pro-tip__heading --hl-s\">Alertas <br>de viaje<\/div>\n                            \n        <\/div>\n        <div class=\"pro-tip__star-divider star-divider --blue\">\n            <div class=\"side\"><\/div>\n            <div class=\"star\"><\/div>\n            <div class=\"side\"><\/div>\n        <\/div>\n        <div class=\"pro-tip__content-container\">\n            <div class=\"pro-tip__content\"><p>Until further notice, no boating is allowed at Wild Horse Reservoir due to nearby firefighting efforts. All other park facilities are open. Get the most up-to-date information before you visit.<\/p>\n<\/div>\n                            <a class=\"pro-tip__cta\" target=\"_blank\" href=\"https:\/\/parks.nv.gov\/parks\/wild-horse\">Latest Updates<\/a>\n                    <\/div>\n    <\/div>\n            <div class=\"pro-tip__mountain mountain1\"><\/div>\n            <div class=\"pro-tip__mountain mountain2\"><\/div>\n            <div class=\"pro-tip__mountain mountain3\"><\/div>\n            <div class=\"pro-tip__mountain mountain4\"><\/div>\n    <\/div>\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Remoto y extraordinario, este parque estatal en el alto desierto de Nevada ofrece incre\u00edbles oportunidades de pesca, campamentos y observaci\u00f3n de vida silvestre durante todo el a\u00f1o. Durante los meses de verano, el cielo es el l\u00edmite cuando se trata de aventuras acu\u00e1ticas. En invierno, tanto los lugare\u00f1os como los viajeros se dirigen a Wild Horse para disfrutar de una pesca en el hielo incre\u00edblemente satisfactoria. Visite Wild Horse Reservoir durante la primavera y el verano para disfrutar de una espectacular variedad de flores silvestres que no querr\u00e1 perderse.<\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00bfEst\u00e1s buscando una escapada a gran altura hacia alg\u00fan hermoso paisaje rural de Nevada? Acabas de encontrar tu parque. Repleto de aventuras invernales y delicias veraniegas, este parque estatal de gran altitud de Nevada sorprende en todas las estaciones.<\/p><\/blockquote><\/figure>\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312818-5d2e42b25cfae-1024x576.jpg\" alt=\"flores silvestres en wildhorse\" class=\"wp-image-72243\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312818-5d2e42b25cfae-1024x576.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312818-5d2e42b25cfae-300x169.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312818-5d2e42b25cfae-768x432.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312818-5d2e42b25cfae.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Las flores silvestres de primavera florecen en Wild Horse<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312839-5d2e42c7c8d7c-1024x576.jpg\" alt=\"Motos de nieve en la monta&#xF1;a Wild Horse\" class=\"wp-image-72244\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312839-5d2e42c7c8d7c-1024x576.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312839-5d2e42c7c8d7c-300x169.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312839-5d2e42c7c8d7c-768x432.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/05\/lass-id-original-1563312839-5d2e42c7c8d7c.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Invierno en Wild Horse<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading\"><strong>Los primeros d\u00edas en Wild Horse Reservoir<\/strong><\/h2>\n\n<p>Junto con <a href=\"https:\/\/travelnevada.com\/es\/business\/area-recreativa-estatal-de-south-fork\/\">\u00c1rea recreativa estatal de South Fork<\/a> El embalse Wild Horse se construy\u00f3 a fines de la d\u00e9cada de 1930 como parte de la Ley Nacional de Control de Inundaciones. Anteriormente conocido como Owyhee Meadows, este nuevo embalse recibi\u00f3 su nombre en honor a las manadas de caballos salvajes que vagaban libremente por la zona durante esa \u00e9poca. Desde la construcci\u00f3n de la presa, no es tan com\u00fan encontrar caballos salvajes en la zona, pero se pueden avistar hacia el oeste, en todo el desierto de Owyhee. El embalse duplic\u00f3 su tama\u00f1o en 1969, cuando se consider\u00f3 que la presa original ten\u00eda una estructura deficiente. En la actualidad, el \u00c1rea Recreativa Estatal Wild Horse tiene una superficie de 2,830 acres, est\u00e1 equipada para contener unos asombrosos 73,500 acres-pies de agua y est\u00e1 a su disposici\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Visitando el Parque Estatal Wild Horse hoy<\/strong><\/h2>\n\n<p>Situado a unos impresionantes 6.200 pies, la misma elevaci\u00f3n que <a href=\"https:\/\/travelnevada.com\/es\/business\/lago-tahoe\/\">Lago Tahoe<\/a>\u2014Wild Horse Reservoir suele ostentar las temperaturas invernales m\u00e1s bajas de Nevada, lo que hace que la zona sea perfectamente ideal para la pesca en hielo. Este embalse se congela a principios de los meses de oto\u00f1o, lo que lo hace m\u00e1s r\u00e1pido que otros lagos de la zona y permanece congelado durante m\u00e1s tiempo. Repleta de truchas arco\u00edris y truchas marrones alemanas, lubinas de boca chica, percas amarillas y bagres, el embalse ofrece una pesca durante el verano igualmente satisfactoria. Aunque no se permite la caza dentro de los l\u00edmites del parque, Wild Horse Reservoir es un campamento base popular para los cazadores que buscan llenar sus etiquetas. El <a href=\"https:\/\/travelnevada.com\/road-trips\/rubies-route\/\">esquina noreste de Nevada<\/a> Por lo general, es el hogar de algunos de los animales de caza mayor de Nevada, como el ant\u00edlope berrendo, el venado mulo, el borrego cimarr\u00f3n del desierto y el alce de las Monta\u00f1as Rocosas. Por supuesto, tambi\u00e9n es divertido fotografiar a estos animales a trav\u00e9s de la lente de una c\u00e1mara.<\/p>\n\n<p>Si planea visitar Wild Horse durante los meses de verano, prep\u00e1rese para pasar un d\u00eda en el agua: Wild Horse es un lugar popular y favorito para algunos de los mejores paseos en bote, nataci\u00f3n, campamentos y caminatas en el \u00e1rea. Hay una rampa para embarcaciones ubicada justo al lado de la playa de uso diurno. Lo mejor de todo es que m\u00e1s de varias docenas de especies de flores silvestres cubren el parque durante los meses de primavera y verano, lo que hace dif\u00edcil tomar una mala fotograf\u00eda del lugar.\u00a0<\/p>\n\n<h3 class=\"wp-block-heading\"><strong><strong>\u00a0Camping en el embalse Wild Horse<\/strong><\/strong><\/h3>\n\n<p>Wild Horse ofrece 34 sitios para acampar con sombra, mesa, fogata y plataforma para acampar en cada uno. Los sitios de paso pueden acomodar veh\u00edculos recreativos grandes. No hay conexiones, pero los ba\u00f1os y las duchas est\u00e1n disponibles todo el a\u00f1o. Los grifos de agua y una estaci\u00f3n de descarga solo est\u00e1n disponibles durante los meses de verano. <a href=\"https:\/\/parks.nv.gov\/about\/reservations\">Reservas de campings<\/a> Se pueden hacer con antelaci\u00f3n pero no son obligatorios.<\/p>\n\n<p>Tambi\u00e9n hay tres caba\u00f1as disponibles para alquilar durante todo el a\u00f1o en Wild Horse. Los tres cuentan con terraza frontal cubierta, sala de estar con sof\u00e1 cama, comedor con mesa y sillas, mini-nevera, microondas, ba\u00f1o (inodoro y lavabo), calefacci\u00f3n y aire acondicionado. Dos de las caba\u00f1as cuentan con una habitaci\u00f3n con literas adicional y pueden albergar hasta seis ocupantes. La otra cabina es accesible para personas con discapacidad y puede albergar hasta cuatro ocupantes. Ninguna de las caba\u00f1as tiene duchas, pero hay un edificio con duchas a unos 300 metros de distancia. Las reservas de caba\u00f1as se pueden realizar a trav\u00e9s de <a href=\"https:\/\/parks.nv.gov\/about\/reservations\">Reserva Nevada<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEst\u00e1s buscando una escapada a gran altura hacia alg\u00fan hermoso paisaje rural de Nevada? Acabas de encontrar tu parque. Repleto de aventuras invernales y delicias veraniegas, este parque estatal de gran altitud de Nevada sorprende en todas las estaciones.<\/p>\n","protected":false},"featured_media":121978,"menu_order":0,"template":"","meta":{"biz_address_line_1":"65 Miles \/ 1 Hour North of Elko","biz_address_line_2":"","biz_city":"Elko","biz_country":"United States","biz_latitude":"41.672298","biz_longitude":"-115.800342","biz_phone_number":"(775) 385-5939","biz_postal_code":"89801","biz_state":"NV","biz_website":"http:\/\/parks.nv.gov\/parks\/wild-horse","biz_desktop_image":{"ID":121978,"id":121978,"title":"wild-horse-state-recreation-area.jpg","filename":"lass-id-original-1563312830-5d2e42be50509.jpg","filesize":399084,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","link":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/attachment\/lass-id-original-1563312830-5d2e42be50509-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312830-5d2e42be50509-jpg-2","status":"inherit","uploaded_to":163008,"date":"2020-05-04 23:56:27","modified":"2025-08-11 17:50:59","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"biz_map_type":"lat-lng","biz_mobile_image":{"ID":142462,"id":142462,"title":"WildHorse_Mobile","filename":"WildHorse_Mobile.jpg","filesize":121394,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile.jpg","link":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/attachment\/wildhorse_mobile-2\/","alt":"","author":"6","description":"","caption":"","name":"wildhorse_mobile-2","status":"inherit","uploaded_to":163008,"date":"2022-05-23 17:27:01","modified":"2025-08-11 17:50:59","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":656,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile-233x300.jpg","medium-width":233,"medium-height":300,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile.jpg","medium_large-width":656,"medium_large-height":844,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile.jpg","large-width":656,"large-height":844,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile.jpg","1536x1536-width":656,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile.jpg","2048x2048-width":656,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile.jpg","gform-image-choice-sm-width":233,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile.jpg","gform-image-choice-md-width":311,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/WildHorse_Mobile.jpg","gform-image-choice-lg-width":466,"gform-image-choice-lg-height":600}},"biz_map_use_custom_map_link":false,"biz_admission":"<p>La entrada para uso diario al \u00c1rea Recreativa Estatal Wild Horse cuesta $5 para residentes de Nevada y $10 para veh\u00edculos de otros estados. Los ciclistas pagan $2. El lanzamiento de embarcaciones cuesta $15 para los residentes de Nevada y $20 para los no residentes. \u00a0 Los sitios para acampar cuestan $15 por noche para residentes de Nevada y $20 por noche para veh\u00edculos de otros estados. Acampar con un bote cuesta $20 por noche para residentes de Nevada y $25 por noche para veh\u00edculos de otros estados. Las caba\u00f1as cuestan $90 por noche para residentes de Nevada y $95 por noche para veh\u00edculos de otros estados.<\/p>\n","biz_hours":"<p>El \u00e1rea de recreaci\u00f3n estatal Wild Horse est\u00e1 abierta las 24 horas del d\u00eda, los 365 d\u00edas del a\u00f1o.<\/p>\n","biz_attached_media":[{"ID":121966,"id":121966,"title":"wild-horse-state-park.jpg","filename":"lass-id-original-1563312808-5d2e42a827f9f.jpg","filesize":379538,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563312808-5d2e42a827f9f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312808-5d2e42a827f9f-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-04 23:56:22","modified":"2020-05-04 23:56:22","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":121980,"id":121980,"title":"wild-horse-reservoir-nevada.jpg","filename":"lass-id-original-1563312822-5d2e42b664645.jpg","filesize":213111,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563312822-5d2e42b664645-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312822-5d2e42b664645-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-04 23:56:28","modified":"2020-05-04 23:56:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":121982,"id":121982,"title":"wild-horse-reservoir-camping.jpg","filename":"lass-id-original-1563312825-5d2e42b9afb8c.jpg","filesize":304642,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563312825-5d2e42b9afb8c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312825-5d2e42b9afb8c-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-04 23:56:30","modified":"2020-05-04 23:56:30","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":850,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c-300x170.jpg","medium-width":300,"medium-height":170,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c-768x435.jpg","medium_large-width":768,"medium_large-height":435,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c-1024x580.jpg","large-width":1024,"large-height":580,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","1536x1536-width":1500,"1536x1536-height":850,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","2048x2048-width":1500,"2048x2048-height":850,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":170,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":227,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":340}},{"ID":121974,"id":121974,"title":"wild-horse-reservoir.jpg","filename":"lass-id-original-1563312818-5d2e42b25cfae.jpg","filesize":446074,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563312818-5d2e42b25cfae-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312818-5d2e42b25cfae-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-04 23:56:25","modified":"2020-05-04 23:56:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312818-5d2e42b25cfae.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":121970,"id":121970,"title":"wild-horse-park.jpg","filename":"lass-id-original-1563312839-5d2e42c7c8d7c.jpg","filesize":265495,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563312839-5d2e42c7c8d7c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312839-5d2e42c7c8d7c-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-04 23:56:23","modified":"2020-05-04 23:56:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312839-5d2e42c7c8d7c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}}],"biz_image_link":{"title":"","url":"","target":"","0":""}},"categories":[546,549,552,550,558,570,561,599,557],"tn-amenities":[],"tn-regions":[209],"silos":[641],"class_list":["post-163008","business","type-business","status-publish","has-post-thumbnail","hentry","category-actividades-en-familia","category-atracciones","category-deportes-de-invierno","category-diversion-al-aire-libre","category-donde-acampar","category-parques-estatales-y-nacionales","category-parques-y-areas-recreativas","category-pesca","category-senderismo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c1rea Recreativa Estatal Wild Horse | Embalse Wild Horse<\/title>\n<meta name=\"description\" content=\"El \u00e1rea recreativa estatal Wild Horse es un parque estatal remoto y verdaderamente extraordinario en el alto desierto que ofrece incre\u00edbles oportunidades de pesca en el hielo, campamentos y observaci\u00f3n de vida silvestre durante todo el a\u00f1o. Visite Wild Horse Reservoir en primavera o verano para ver hermosas flores silvestres respaldadas por imponentes picos nevados.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1rea Recreativa Estatal Wild Horse | Embalse Wild Horse\" \/>\n<meta property=\"og:description\" content=\"El \u00e1rea recreativa estatal Wild Horse es un parque estatal remoto y verdaderamente extraordinario en el alto desierto que ofrece incre\u00edbles oportunidades de pesca en el hielo, campamentos y observaci\u00f3n de vida silvestre durante todo el a\u00f1o. Visite Wild Horse Reservoir en primavera o verano para ver hermosas flores silvestres respaldadas por imponentes picos nevados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T17:51:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/live-travel-nevada.pantheonsite.io\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c1rea Recreativa Estatal Wild Horse | Embalse Wild Horse","description":"El \u00e1rea recreativa estatal Wild Horse es un parque estatal remoto y verdaderamente extraordinario en el alto desierto que ofrece incre\u00edbles oportunidades de pesca en el hielo, campamentos y observaci\u00f3n de vida silvestre durante todo el a\u00f1o. Visite Wild Horse Reservoir en primavera o verano para ver hermosas flores silvestres respaldadas por imponentes picos nevados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/","og_locale":"es_ES","og_type":"article","og_title":"\u00c1rea Recreativa Estatal Wild Horse | Embalse Wild Horse","og_description":"El \u00e1rea recreativa estatal Wild Horse es un parque estatal remoto y verdaderamente extraordinario en el alto desierto que ofrece incre\u00edbles oportunidades de pesca en el hielo, campamentos y observaci\u00f3n de vida silvestre durante todo el a\u00f1o. Visite Wild Horse Reservoir en primavera o verano para ver hermosas flores silvestres respaldadas por imponentes picos nevados.","og_url":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","article_modified_time":"2025-08-11T17:51:22+00:00","og_image":[{"width":1500,"height":844,"url":"http:\/\/live-travel-nevada.pantheonsite.io\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/","url":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/","name":"\u00c1rea Recreativa Estatal Wild Horse | Embalse Wild Horse","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","datePublished":"2014-04-04T06:09:41+00:00","dateModified":"2025-08-11T17:51:22+00:00","description":"El \u00e1rea recreativa estatal Wild Horse es un parque estatal remoto y verdaderamente extraordinario en el alto desierto que ofrece incre\u00edbles oportunidades de pesca en el hielo, campamentos y observaci\u00f3n de vida silvestre durante todo el a\u00f1o. Visite Wild Horse Reservoir en primavera o verano para ver hermosas flores silvestres respaldadas por imponentes picos nevados.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/pesca\/area-recreativa-estatal-wild-horse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00c1rea recreativa estatal Wild Horse"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"photos":[{"ID":121966,"id":121966,"title":"wild-horse-state-park.jpg","filename":"lass-id-original-1563312808-5d2e42a827f9f.jpg","filesize":379538,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563312808-5d2e42a827f9f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312808-5d2e42a827f9f-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-04 23:56:22","modified":"2020-05-04 23:56:22","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312808-5d2e42a827f9f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":121980,"id":121980,"title":"wild-horse-reservoir-nevada.jpg","filename":"lass-id-original-1563312822-5d2e42b664645.jpg","filesize":213111,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563312822-5d2e42b664645-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312822-5d2e42b664645-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-04 23:56:28","modified":"2020-05-04 23:56:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":844,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","1536x1536-width":1500,"1536x1536-height":844,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","2048x2048-width":1500,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312822-5d2e42b664645.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},{"ID":121982,"id":121982,"title":"wild-horse-reservoir-camping.jpg","filename":"lass-id-original-1563312825-5d2e42b9afb8c.jpg","filesize":304642,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","link":"https:\/\/travelnevada.com\/es\/lass-id-original-1563312825-5d2e42b9afb8c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"lass-id-original-1563312825-5d2e42b9afb8c-jpg-2","status":"inherit","uploaded_to":0,"date":"2020-05-04 23:56:30","modified":"2020-05-04 23:56:30","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/travelnevada.com\/wp-includes\/images\/media\/default.png","width":1500,"height":850,"sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c-300x170.jpg","medium-width":300,"medium-height":170,"medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c-768x435.jpg","medium_large-width":768,"medium_large-height":435,"large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c-1024x580.jpg","large-width":1024,"large-height":580,"1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","1536x1536-width":1500,"1536x1536-height":850,"2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","2048x2048-width":1500,"2048x2048-height":850,"gform-image-choice-sm":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":170,"gform-image-choice-md":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":227,"gform-image-choice-lg":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312825-5d2e42b9afb8c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":340}}],"primary_category":{"term_id":570,"name":"Parques estatales y nacionales","slug":"parques-estatales-y-nacionales","term_group":0,"term_taxonomy_id":570,"taxonomy":"category","description":"","parent":541,"count":39,"filter":"raw"},"silo_name":"Pesca","is_rural":"true","category_slugs":"actividades-en-familia,atracciones,deportes-de-invierno,diversion-al-aire-libre,donde-acampar,parques-estatales-y-nacionales,parques-y-areas-recreativas,pesca,senderismo","featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/lass-id-original-1563312830-5d2e42be50509.jpg"},"featured_image_alt":"","friendly_post_date":"April 03, 2014","selected_region":[{"term_id":209,"name":"Elko","slug":"elko","term_group":0,"term_taxonomy_id":209,"taxonomy":"tn-regions","description":"","parent":12,"count":184,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/163008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/business"}],"version-history":[{"count":1,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/163008\/revisions"}],"predecessor-version":[{"id":163014,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/business\/163008\/revisions\/163014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/121978"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=163008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=163008"},{"taxonomy":"tn-amenities","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-amenities?post=163008"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=163008"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=163008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}