{"id":159475,"date":"2020-09-01T17:25:31","date_gmt":"2020-09-02T00:25:31","guid":{"rendered":"https:\/\/travelnevada.com\/ciudad-de-virginia-escapadas-de-una-noche\/"},"modified":"2025-07-31T12:16:12","modified_gmt":"2025-07-31T19:16:12","slug":"ciudad-de-virginia-escapadas-de-una-noche","status":"publish","type":"post","link":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/","title":{"rendered":"Ciudad de Virginia: Escapadas de una noche"},"content":{"rendered":"\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns alignwide has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" style=\"background-color:#f5f5f5\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Inf\u00f3rmate antes de viajar<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/travelnevada.com\/es\/diviertete-con-responsabilidad\/\">Recrear responsablemente<\/a>\u00a0\u2013\u00a0Ya sea que est\u00e9s viajando por la carretera o por caminos secundarios, obt\u00e9n informaci\u00f3n exclusiva sobre c\u00f3mo explorar el Estado de Plata de manera segura y respetuosa.<\/li>\n\n\n\n<li>\u00bfVas a salir a la carretera? Ponte al d\u00eda con los conocimientos de Nevada\u00a0<a href=\"https:\/\/travelnevada.com\/ghost-town\/beyond-the-asphalt-19-ways-to-live-by-the-dirt-road-code\/\">C\u00f3digo de caminos de tierra<\/a>\u00a0para garantizar que est\u00e9 preparado para una aventura fuera del pavimento y todo lo que conlleva.<\/li>\n\n\n\n<li><a href=\"https:\/\/travelnevada.com\/nevada-covid-19-restrictions-travel-advisories\/\">Alertas de viaje de Nevada<\/a>\u00a0\u2013\u00a0Desde cierres temporales de parques y carreteras hasta circunstancias ambientales inusuales, si sabemos de algo que pueda afectar su visita, lo encontrar\u00e1 aqu\u00ed, junto con enlaces a m\u00e1s recursos para obtener m\u00e1s informaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading is-style-heading-level-4\">Obtenga el itinerario completo<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/travelnevada.com\/discover-your-nevada\/email-itinerary-virginia-city\/\">Env\u00edame un correo electr\u00f3nico<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2022\/03\/24horas-VirginiaCity-2022.pdf\">Descargar ahora<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"highlights --highlights\">\n    <div class=\"highlights__background-text --silver\"><\/div>\n    <div class=\"star-divider --blue\">\n        <div class=\"side\"><\/div>\n        <div class=\"star\"><\/div>\n        <div class=\"side\"><\/div>\n    <\/div>\n    <p class=\"screen-reader-text\">Destacados<\/p>\n    <div class=\"highlights__content --silver-header\"><ul id=\"block-d2643cf1-8824-44a6-b6be-919fcc98f31e\" class=\"block-editor-rich-text__editable block-editor-block-list__block wp-block is-selected rich-text\">\n<li>Recorra minas y molinos de plata aut\u00e9ntica, a pie o <a href=\"https:\/\/travelnevada.com\/trains-railroads\/virginia-truckee-railroad\/\">en tren<\/a><\/li>\n<li>Realice un paseo fantasmal nocturno en algunos de los lugares favoritos de Travel Channel y SyFy<\/li>\n<li>Comer, beber y dormir en <a href=\"https:\/\/travelnevada.com\/hotels\/gold-hill-hotel-saloon\/\">El hotel m\u00e1s antiguo de Nevada<\/a><\/li>\n<\/ul>\n<\/div>\n    <\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n<\/div>\n\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"is-style-body-large\">Como habitante de Reno, probablemente hayas visitado Virginia City. Quiz\u00e1s incluso unas cuantas veces. \u00bfPero lo has hecho? <em>en realidad <\/em>\u00bfHas experimentado el lugar? Si bien esta hist\u00f3rica ciudad ubicada justo en la monta\u00f1a desde Reno es conocida por sus alocados eventos anuales (<a href=\"https:\/\/travelnevada.com\/events\/international-camel-ostrich-races\/\">Camello internacional&amp; Carreras de avestruces<\/a>, <a href=\"https:\/\/travelnevada.com\/events\/virginia-city-rocky-mountain-oyster-fry\/\">Ostras fritas de las Monta\u00f1as Rocosas<\/a>, o <a href=\"https:\/\/travelnevada.com\/events\/world-championship-outhouse-races\/\">Campeonato Mundial de Carreras de Letrinas en Virginia City<\/a>, \u00bfalguien?), hasta que no hayas cazado fantasmas en el bar, bailado con lugare\u00f1os vestidos con trajes victorianos, uniformes de caballer\u00eda y otros atuendos occidentales de anta\u00f1o, o explorado una o dos minas subterr\u00e1neas (y realmente pasado la noche), en realidad solo has ara\u00f1ado la superficie del viejo VC.<\/p>\n<\/div>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGeiger-Grade-1024x575.jpg\" alt=\"Carretera de grado Geiger a Virginia City desde Reno, Nevada\" class=\"wp-image-34576\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGeiger-Grade-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGeiger-Grade-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGeiger-Grade-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGeiger-Grade.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Grado Geiger<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Sube y haz la calificaci\u00f3n (Geiger)<\/h2>\n\n<p>\u00a1Arriba y a por ellos! T\u00f3mese un caf\u00e9 en su cafeter\u00eda favorita de Reno para disfrutar durante su viaje de 30 minutos hacia el sur hasta Virginia City. (\u00daltimamente, nos encantan los innovadores vertidos de Reno Coffee Co., los caf\u00e9s fr\u00edos con nitr\u00f3geno de Old World Coffee Lab y los lattes de chai con vainilla de Lighthouse Coffee).<\/p>\n\n<div class=\"pro-tip --pro-tip\">\n    <div class=\"pro-tip__container\">\n        <div class=\"pro-tip__highlight-container\">\n                            <div class=\"pro-tip__background-text --spanish\"><\/div>\n                <p class=\"screen-reader-text\">Consejo experto de Travel Nevada<\/p>\n                \n            \n        <\/div>\n        <div class=\"pro-tip__star-divider star-divider --blue\">\n            <div class=\"side\"><\/div>\n            <div class=\"star\"><\/div>\n            <div class=\"side\"><\/div>\n        <\/div>\n        <div class=\"pro-tip__content-container\">\n            <div class=\"pro-tip__content\"><p>Prep\u00e1rese para un espresso extra esta ma\u00f1ana. Tienes un d\u00eda muy ocupado por delante. <\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n            <div class=\"pro-tip__star star1\"><\/div>\n            <div class=\"pro-tip__star star2\"><\/div>\n            <div class=\"pro-tip__star star3\"><\/div>\n            <div class=\"pro-tip__star star4\"><\/div>\n    <\/div>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVisitors-Center-1024x575.jpg\" alt=\"Centro de visitantes de Virginia City\" class=\"wp-image-34604\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVisitors-Center-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVisitors-Center-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVisitors-Center-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVisitors-Center.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/visitors-centers-travel-services\/virginia-city-visitor-center\/\">Centro de visitantes de Virginia City<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Visita el Centro de Visitantes para obtener pases, paquetes y otros descuentos.<\/h2>\n\n<p>\u00bfPorque a qui\u00e9n no le gusta un buen trato? Cuando llegues a la ciudad, ve directo a la <a href=\"https:\/\/travelnevada.com\/visitors-centers-travel-services\/virginia-city-visitor-center\/\">Centro de visitantes<\/a>\u2014ubicado en un antiguo y elegante edificio en el coraz\u00f3n de la hist\u00f3rica C Street\u2014consigue algunos boletos dorados y prep\u00e1rate para ahorrar algo de dinero. \u00bfC\u00f3mo? M\u00e1s de una manera. <\/p>\n\n<p>La buena gente de la Comisi\u00f3n de Turismo de Virginia City ha preparado cuatro eventos tem\u00e1ticos \u00fanicos. <a href=\"https:\/\/travelnevada.com\/visitors-centers-travel-services\/virginia-city-visitor-center\/\">Pases de aventura de Comstock<\/a>, cada uno bueno para diferentes paquetes de atracciones, museos y actividades similares. Elige tu favorito (o favoritos) y ahorra algo de dinero mientras disfrutas de la historia que rebosa los museos, el ferrocarril y mucho m\u00e1s de esta ciudad.<\/p>\n\n<p>Para endulzar el trato, pide el nuevo. <em>Todos somos locales<\/em> calcoman\u00eda, busca la calcoman\u00eda correspondiente en las ventanas de los comercios participantes en toda la ciudad y prep\u00e1rate para otro descuento o especial en cada uno de ellos. <\/p>\n\n<p>Antes de abandonar el impresionante edificio, aseg\u00farese de observar los elegantes objetos ef\u00edmeros del Viejo Oeste que adornan sus paredes. (Dudo que alguna vez hayas visto un reloj tan \u201cmisterioso\u201d\u2026)<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/ChollarMine9_SM-1024x576.jpg\" alt=\"Entrada a los recorridos por la mina Chollar\" class=\"wp-image-34136\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/ChollarMine9_SM-1024x576.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/ChollarMine9_SM-300x169.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/ChollarMine9_SM-768x432.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/ChollarMine9_SM.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/mines-prospecting\/chollar-mine-tours\/\">Visitas a la mina Chollar<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Haz un recorrido por la mina o te quedar\u00e1s en tierra<\/h2>\n\n<p>No puedes considerarte un veterano de Virginia City si no has visitado las minas que crearon el lugar. Es una regla. \u00bfPor qu\u00e9? Nos alegra mucho que lo preguntes. All\u00e1 por el a\u00f1o 1859, se descubri\u00f3 un enorme dep\u00f3sito de plata (ya sabe, el que dio lugar a uno de los mayores descubrimientos de plata de la historia), lo que catapult\u00f3 la existencia de Virginia City pr\u00e1cticamente de la noche a la ma\u00f1ana. Este yacimiento de plata, conocido como <a href=\"https:\/\/travelnevada.com\/history-heritage\/nevada-history-heritage\/\">Veta Comstock<\/a>, desenterr\u00f3 una riqueza inimaginable. Estamos hablando de cientos de millones de d\u00f3lares.<em>miles de millones<\/em> en el dinero de hoy\u2014que cubri\u00f3 los gastos de algunos desarrollos importantes en la Costa Oeste en su conjunto. <\/p>\n\n<p><strong>Dato curioso:<\/strong> \u00bfConoces esa ciudad al oeste conocida como la Ciudad de la Bah\u00eda? El capital de riesgo ayud\u00f3 a construir el lugar\u2014<em>dos veces<\/em>.  Imag\u00ednense: sin Virginia City, tal vez no tendr\u00edamos los placeres del pan de masa madre, del chocolate Ghirardelli o incluso de los 49ers (bueno, al menos, los deportivos).\u00a0<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/Slammer19_SM-1024x576.jpg\" alt=\"mineros de Comstock\" class=\"wp-image-34135\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/Slammer19_SM-1024x576.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/Slammer19_SM-300x169.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/Slammer19_SM-768x432.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/Slammer19_SM.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/history-heritage\/nevada-history-heritage\/\">Mineros de Comstock<\/a><\/figcaption><\/figure>\n\n<p>De todos modos. Hoy en d\u00eda, puedes visitar algunas de las minas que hicieron posible todo esto, y con muchos menos dolores de cabeza que quienes las excavaron. En s\u00f3lo 25 minutos, el <a href=\"https:\/\/travelnevada.com\/mines-prospecting\/ponderosa-saloon-mine-tour\/\">Recorrido por la mina Ponderosa<\/a> Le muestra el funcionamiento completo de la mina subterr\u00e1nea: t\u00faneles, cortes transversales, galer\u00edas y pozos, adem\u00e1s de m\u00e1s de 300 piezas de equipo de miner\u00eda antiguo. Subiendo por la carretera en el <a href=\"https:\/\/travelnevada.com\/mines-prospecting\/chollar-mine-tours\/\">Mina Chollar<\/a>, donde los mineros extrajeron alrededor de 17 millones de d\u00f3lares en oro y plata, una visita guiada de 30 minutos lleva a los visitantes en una caminata nivelada de 400 pies para ver la estructura original de madera cuadrada, el mineral de plata y m\u00e1s.\u00a0<\/p>\n\n<p>De vuelta en la superficie, si todav\u00eda te interesa, echa un vistazo a <a href=\"https:\/\/travelnevada.com\/mines-prospecting\/comstock-gold-mill\/\">Molino de oro Comstock<\/a> y obtener una \u201cfibra\u201d de c\u00f3mo se proces\u00f3 el oro desde el mineral hasta su recuperaci\u00f3n. Despu\u00e9s de todos estos a\u00f1os, toda esa maquinaria de madera y metal sigue en pleno funcionamiento. Y cr\u00e9anos, no olvidar\u00e1 pronto la banda sonora de este lugar ni tampoco los personajes que lo dirigen.\u00a0\u00a0<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCCourthouse-Slammer-1024x575.jpg\" alt=\"Afuera del museo de la c&#xE1;rcel del juzgado\" class=\"wp-image-34575\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCCourthouse-Slammer-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCCourthouse-Slammer-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCCourthouse-Slammer-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCCourthouse-Slammer.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/museums\/courthouse-slammer-county-museum\/\">Museo del Juzgado Slammer<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Locura de museos<\/h2>\n\n<p>En un lugar donde el Servicio de Parques Nacionales ha designado el <em>toda la ciudad<\/em> Un Monumento Hist\u00f3rico Nacional, por lo que se esperar\u00eda encontrar algo de actividad muse\u00edstica alrededor. Tendr\u00eda raz\u00f3n, pues existen alrededor de 17 instituciones de ese tipo. Si has estado en VC para un fin de semana de eventos locos, te perdonaremos que no hayas podido pasar una tarde explorando con atenci\u00f3n; sin embargo, si vives cerca de estos lugares incre\u00edbles y <em>a\u00fan<\/em> Nunca lo hagamos, simplemente no podemos. A continuaci\u00f3n se muestran algunas opciones favoritas para leer a \u00faltima hora de la ma\u00f1ana.<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VC4th-Ward-1024x575.jpg\" alt=\"Dentro del museo escolar del cuarto distrito\" class=\"wp-image-34572\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VC4th-Ward-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VC4th-Ward-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VC4th-Ward-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VC4th-Ward.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/museums\/historic-fourth-ward-school-museum-archives\/\">Museo Escolar del Cuarto Distrito&amp; Archivo<\/a><\/figcaption><\/figure>\n\n<p>\u00bfConoc\u00edas a Mark Twain? <a href=\"https:\/\/travelnevada.com\/shows\/forget-what-you-heard-nevada-is-the-true-birthplace-of-mark-twain\/\">\u201cnaci\u00f3\u201d aqu\u00ed<\/a>?  Ese famoso nevadense dio lo que muchos consideran su primer espect\u00e1culo en vivo en <a href=\"https:\/\/travelnevada.com\/performing-arts\/pipers-opera-house\/\">\u00d3pera de Piper<\/a>, que tambi\u00e9n recibi\u00f3 a Buffalo Bill, Al Jolson y a un sinn\u00famero de otros artistas famosos en su sala ahora apta para giras. A los ni\u00f1os de todas las edades les encanta el <a href=\"https:\/\/travelnevada.com\/museums\/liberty-engine-company-1-state-firemens-museum\/\">Museo Estatal de Bomberos<\/a> por su equipo original y veh\u00edculos antiguos, as\u00ed como por su colecci\u00f3n de artefactos. <a href=\"https:\/\/travelnevada.com\/museums\/the-way-it-was-museum\/\">El museo como era<\/a>.  Mientras tanto, la historia y el arte contempor\u00e1neo chocan en siete galer\u00edas rotativas en el antiguo hospital convertido en galer\u00eda conocido como <a href=\"https:\/\/travelnevada.com\/art-galleries\/st-marys-art-center\/\">Centro de Arte de Santa Mar\u00eda<\/a>.  Y si los ni\u00f1os se portan mal, as\u00fastalos para que se enderecen (y ens\u00e9\u00f1ales una cosa o dos) en el cine rico en fotograf\u00edas. <a href=\"https:\/\/travelnevada.com\/museums\/courthouse-slammer-county-museum\/\">Prisi\u00f3n del juzgado&amp; Museo del Condado<\/a>.\u00a0<\/p>\n\n<div class=\"pro-tip --pro-tip\">\n    <div class=\"pro-tip__container\">\n        <div class=\"pro-tip__highlight-container\">\n                            <div class=\"pro-tip__background-text --spanish\"><\/div>\n                <p class=\"screen-reader-text\">Consejo experto de Travel Nevada<\/p>\n                \n            \n        <\/div>\n        <div class=\"pro-tip__star-divider star-divider --blue\">\n            <div class=\"side\"><\/div>\n            <div class=\"star\"><\/div>\n            <div class=\"side\"><\/div>\n        <\/div>\n        <div class=\"pro-tip__content-container\">\n            <div class=\"pro-tip__content\"><p>Gracias a su amplio y hermoso sal\u00f3n, Piper&#8217;s Opera House a\u00fan puede albergar eventos divertidos, seguros y socialmente distanciados, adem\u00e1s de sus visitas autoguiadas todos los fines de semana. Revise su calendario, asista a un espect\u00e1culo y experimente para qu\u00e9 se cre\u00f3 esa joya hist\u00f3rica y ornamentada.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n            <div class=\"pro-tip__star star1\"><\/div>\n            <div class=\"pro-tip__star star2\"><\/div>\n            <div class=\"pro-tip__star star3\"><\/div>\n            <div class=\"pro-tip__star star4\"><\/div>\n    <\/div>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCBoardwalk-1024x575.jpg\" alt=\"Paseo mar&#xED;timo de Virginia City, Nevada\" class=\"wp-image-34573\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCBoardwalk-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCBoardwalk-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCBoardwalk-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCBoardwalk.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/historical-interests\/historic-c-street\/\">Tiendas hist\u00f3ricas de la calle C<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Antig\u00fcedades, boutiques y el estilo del Viejo Oeste<\/h2>\n\n<p>Mientras navega entre las atracciones, simplemente no puede recorrer los paseos de madera de Virginia City sin ser transportado por un tractor a una vieja tienda. Busque todo tipo de objetos antiguos en varias tiendas de antig\u00fcedades, explore las gemas y otras joyas extra\u00eddas de Nevada o pasee por las docenas de comerciantes que ofrecen sus tesoros de Comstock. Y escucha, si has estado en VC qui\u00e9n sabe cu\u00e1ntas veces y <em>a\u00fan<\/em> No te hagas el turista y te regales una foto a la antigua usanza, simplemente hazlo. Probarse toda la ropa vintage es la mitad de la diversi\u00f3n, y t\u00fa, tu familia y tus amigos dir\u00e1n mucho m\u00e1s que mil palabras sobre el retrato grupal resultante. (Simplemente traten de no pelear sobre qui\u00e9n se va a poner el barril).<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGrandmas-Fudge-1024x575.jpg\" alt=\"F&#xE1;brica de dulce de leche de la abuela en Virginia City, Nevada\" class=\"wp-image-34577\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGrandmas-Fudge-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGrandmas-Fudge-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGrandmas-Fudge-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGrandmas-Fudge.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La f\u00e1brica de dulce de az\u00facar de la abuela<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Dulce vs. Salado: \u00bfQu\u00e9 tal ambos?<\/h2>\n\n<p>Para el almuerzo, no hay nada m\u00e1s hist\u00f3rico que el <a href=\"https:\/\/thedeltasaloon.com\/\">Sal\u00f3n Delta <\/a>(uno de los lugares nocturnos favoritos de Mark Twain), que abri\u00f3 sus puertas originalmente en 1865, lo que lo convierte en una de las propiedades m\u00e1s antiguas e hist\u00f3ricas de la ciudad. Mantenga la distancia social en espacios interiores y exteriores. <a href=\"https:\/\/visitvirginiacitynv.com\/virginia-city-restaurants\/\">Parrilla y sal\u00f3n Firehouse<\/a> y del\u00e9itese con jugosas hamburguesas preparadas a pedido, s\u00e1ndwiches de cerdo desmenuzado y costillas de cerdo al estilo casero. Si tiene ganas de hacer un picnic, dir\u00edjase al extremo sur de la ciudad, donde le esperan asientos al aire libre y sombra entre pinos, junto con (si tiene suerte) los sonidos de una banda local de western.\u00a0<\/p>\n\n<p>\u00bfTienes un gusto por lo dulce? Satisfacer ese impulso en <a href=\"http:\/\/redscandies.com\/merch\/specials.htm\">Dulces antiguos de Red<\/a> con deliciosos dulces, crocantes y chocolates; o pasear por <a href=\"https:\/\/www.grandmasfudgefactory.com\/\">La f\u00e1brica de dulce de az\u00facar de la abuela<\/a>, donde los fabricantes de dulces siguen elaborando dulce de az\u00facar a la antigua usanza, a menudo ante tus ojos.\u00a0<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/VT-1024x576.jpg\" alt=\"v&amp; ferrocarril t\" class=\"wp-image-34147\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/VT-1024x576.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/VT-300x169.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/VT-768x432.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/VT.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/trains-railroads\/virginia-truckee-railroad\/\">V&amp; Ferrocarril T<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Deja que tu d\u00eda transcurra <em>En<\/em> Los rieles<\/h2>\n\n<p>Hay algo en un tren que te transporta a la infancia. Y si no lo crees, s\u00fabete a este viaje realmente fascinante y sabemos que lo entender\u00e1s. En pocas palabras, la <a href=\"https:\/\/travelnevada.com\/trains-railroads\/virginia-truckee-railroad\/\">Virginia&amp; Ferrocarril Truckee<\/a> Es el m\u00e1s famoso de todos los ferrocarriles de l\u00ednea corta estadounidenses. (S\u00ed, \u00a1trek-trek en ese!) La construcci\u00f3n comenz\u00f3 en 1869 y durante los siguientes 74 a\u00f1os, este activo ferrocarril transport\u00f3 millones de d\u00f3lares en oro y plata desde las minas ubicadas en las profundidades de la ciudad, a trav\u00e9s de t\u00faneles brillantemente construidos, y monta\u00f1a abajo. Hoy, puedes subir a bordo de vagones de pasajeros abiertos y cerrados, adornados y centenarios, para realizar un recorrido verdaderamente pintoresco hasta la vecina Gold Hill y de regreso, atravesando 17 sitios mineros hist\u00f3ricos en el camino. Para conocer los horarios de trenes, visite <a href=\"https:\/\/www.virginiatruckee.com\/\">VirginiaTruckee.com<\/a>.\u00a0<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/WashoeClub1_SM-1024x576.jpg\" alt=\"el club washoe&amp; museo embrujado\" class=\"wp-image-34154\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/WashoeClub1_SM-1024x576.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/WashoeClub1_SM-300x169.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/WashoeClub1_SM-768x432.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/WashoeClub1_SM.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/museums\/the-washoe-club-haunted-museum\/\">El Club Washoe&amp; Museo Embrujado<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Sum\u00e9rgete en el esp\u00edritu de Virginia City siendo un ghosting<\/h2>\n\n<p>En un lugar con tanta tradici\u00f3n del Viejo Oeste, se podr\u00eda suponer que esta ciudad seguramente tendr\u00e1 algunos esqueletos en sus armarios. De hecho, Virginia City est\u00e1 tan llena de&#8230; <a href=\"https:\/\/travelnevada.com\/haunted-history\/a-haunting-on-the-comstock\/\">lugares embrujados<\/a> Se considera una especie de Shangri-La paranormal para los cazadores de fantasmas y otros buscadores de esp\u00edritus de todo el mundo. Ya sea que simplemente est\u00e9s interesado en lo inexplicable o est\u00e9s buscando una noche emocionante que te ponga los pelos de punta, est\u00e1s en el lugar correcto. Reserva un recorrido de fantasmas para escuchar la historia embrujada mientras te deslizas por los edificios donde ocurrieron los eventos. Los recorridos a pie \u201cMurci\u00e9lagos en el campanario\u201d de Virginia City Ghost Tours exploran una variedad de puntos de inter\u00e9s con una narrativa que te helar\u00e1 hasta los huesos.\u00a0<\/p>\n\n<p>O ponlo en marcha con una visita al <a href=\"https:\/\/travelnevada.com\/museums\/the-washoe-club-haunted-museum\/\">Club Washoe<\/a>, un imponente edificio de ladrillos en el coraz\u00f3n de la bulliciosa e hist\u00f3rica C Street, que se cree que es uno de los lugares m\u00e1s embrujados del Oeste. La propiedad ha aparecido ampliamente en muchos programas de televisi\u00f3n de caza de fantasmas, incluidos Ghost Adventures de Travel Channel y Ghost Hunters de SyFy. Una cripta y un museo leg\u00edtimamente espeluznantes dedicados al misterio del edificio otorgan una gran credibilidad a las afirmaciones fantasmales de la propiedad.\u00a0<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCRed-Dog-1024x575.jpg\" alt=\"saloon perro rojo\" class=\"wp-image-34578\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCRed-Dog-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCRed-Dog-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCRed-Dog-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCRed-Dog.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/bars\/red-dog-saloon\/\">Saloon Red Dog<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Sube la marcha y come<\/h2>\n\n<p>Independientemente de si un poltergeist te hizo perder el almuerzo o no, probablemente tendr\u00e1s apetito a la hora de la cena. \u00bfTienes antojo de pizza? (\u00bfQui\u00e9n no?) Al <a href=\"https:\/\/travelnevada.com\/bars\/red-dog-saloon\/\">Saloon Red Dog<\/a>, toma una silla y disfruta de una porci\u00f3n al estilo de Chicago (y tal vez algo de m\u00fasica en vivo) dentro de un sal\u00f3n que se remonta al apogeo de Virginia City, y que luego se rob\u00f3 el espect\u00e1culo como lugar de reuni\u00f3n para Grateful Dead, Janis Joplin y otros \u00edconos de la escena del rock psicod\u00e9lico de fines de los a\u00f1os 60. O navegue hasta <a href=\"https:\/\/travelnevada.com\/bed-breakfasts\/edith-palmers-country-inn-cider-factory\/\">La Sidrer\u00eda<\/a>, ubicado dentro del Edith Palmer&#8217;s Country Inn, para disfrutar de una cena al aire libre cuando el clima de la noche es sumamente agradable. <\/p>\n\n<div class=\"pro-tip --pro-tip\">\n    <div class=\"pro-tip__container\">\n        <div class=\"pro-tip__highlight-container\">\n                            <div class=\"pro-tip__background-text --spanish\"><\/div>\n                <p class=\"screen-reader-text\">Consejo experto de Travel Nevada<\/p>\n                \n            \n        <\/div>\n        <div class=\"pro-tip__star-divider star-divider --blue\">\n            <div class=\"side\"><\/div>\n            <div class=\"star\"><\/div>\n            <div class=\"side\"><\/div>\n        <\/div>\n        <div class=\"pro-tip__content-container\">\n            <div class=\"pro-tip__content\"><p>Aseg\u00farate de sumergirte en el otro &quot;esp\u00edritu&quot; de Virginia City con un c\u00f3ctel elaborado con la ginebra Cemetery Gin propia de la ciudad. Si te gusta tanto como a nosotros, puedes volver a pasar por el Centro de Visitantes por la ma\u00f1ana y coger una botella o tres para llevarlas cuesta abajo.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n            <div class=\"pro-tip__star star1\"><\/div>\n            <div class=\"pro-tip__star star2\"><\/div>\n            <div class=\"pro-tip__star star3\"><\/div>\n            <div class=\"pro-tip__star star4\"><\/div>\n    <\/div>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGold-Hill-1024x575.jpg\" alt=\"Hotel y sal&#xF3;n Gold Hill\" class=\"wp-image-34582\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGold-Hill-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGold-Hill-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGold-Hill-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCGold-Hill.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/travelnevada.com\/hotels\/gold-hill-hotel-saloon\/\">Hotel Gold Hill&amp; Sal\u00f3n<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Acostarse para pasar la noche<\/h2>\n\n<p>No mucha gente puede decir que pas\u00f3 la noche en uno de los lugares m\u00e1s ricos de Occidente. Con 227 habitaciones que abarcan hoteles, moteles y alojamientos.&amp; Desayunos\u2014desde pintorescas habitaciones en el <a href=\"https:\/\/travelnevada.com\/motels\/sugarloaf-mountain-motel\/\">Motel Sugarloaf Mountain<\/a> a hermosas habitaciones de \u00e9poca en el hist\u00f3rico <a href=\"https:\/\/travelnevada.com\/bed-breakfasts\/cobb-mansion-bed-breakfast\/\">Mansi\u00f3n Cobb B&amp; B<\/a>, o alojamientos m\u00e1s modernos en el <a href=\"https:\/\/travelnevada.com\/hotels\/silverland-inn\/\">Posada Silverland<\/a> (ba\u00f1eras de hidromasaje incluidas) \u2014disfrute de una buena noche de descanso en Virginia City. As\u00ed como tambi\u00e9n justo bajando la colina en el <a href=\"https:\/\/travelnevada.com\/hotels\/gold-hill-hotel-saloon\/\">Hotel Gold Hill&amp; Sal\u00f3n<\/a>, el hotel m\u00e1s antiguo de todo Nevada, que tambi\u00e9n se jacta de ser uno de los salones m\u00e1s aut\u00e9nticos que existen y de ofrecer comida fant\u00e1stica (desde filetes Angus hasta pollo marsala) en su restaurante Crown Point del hotel.\u00a0\u00a0<\/p>\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVC-Overview-1024x575.jpg\" alt=\"Mirador de Virginia City, Nevada\" class=\"wp-image-34579\" srcset=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVC-Overview-1024x575.jpg 1024w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVC-Overview-300x168.jpg 300w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVC-Overview-768x431.jpg 768w, https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryImage-VCVC-Overview.jpg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Mirador de Virginia City<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Antes de rebotar<\/h2>\n\n<p>Antes de ese viaje de regreso de 30 minutos cuesta abajo, haga una parada en Canvas Caf\u00e9 para tomar unos huevos benedictinos o un pastel casero. \u00bfAlguna de las piezas de arte colgadas en la pared te llama la atenci\u00f3n mientras comes? Todo est\u00e1 hecho por artistas locales y est\u00e1 disponible para su compra. Y para mantener esas conversaciones con cafe\u00edna durante todo el camino a casa, ll\u00e9nese de bebidas espresso, delicias sin gluten y caf\u00e9 tostado en casa, apropiadamente, <a href=\"https:\/\/travelnevada.com\/coffee\/the-roasting-house\/\">La casa de asado<\/a>, que cuenta con una hermosa terraza trasera que es perfecta para disfrutar de la famosa &amp;quot;Vista de las cien millas&amp;quot; de Virginia City mientras recuerda el momento en que realmente descubri\u00f3 esa peque\u00f1a y famosa ciudad en la monta\u00f1a.\u00a0<\/p>\n\n<p class=\"has-text-align-left is-style-script-large\">\u00bfQuieres seguir disfrutando de ese viaje por carretera cerca de casa y &amp;quot;casi en vacaciones&amp;quot;? Obtenga m\u00e1s planes para actividades cercanas y destinos donde puede pasar la noche, como el Capital Classic. <a href=\"https:\/\/travelnevada.com\/discover-your-nevada\/carson-city-your-next-near-cataion\/\">Ciudad Carson<\/a> y lo suave a lo salvaje <a href=\"https:\/\/travelnevada.com\/es\/valle-de-carson-suave-a-salvaje-durante-la-noche\/\">Valle de Carson<\/a>! <\/p>\n<section class=\"business-listing-feed alignfull --theme-sand\">\n    <div class=\"business-listing-feed__star-divider-container --wide-size\">\n        <div class=\"business-listing-feed__star-divider star-divider --gray\">\n            <div class=\"side\"><\/div>\n            <div class=\"star\"><\/div>\n            <div class=\"side\"><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"business-listing-feed__header container\">\n        <div class=\"business-listing-feed__header-content\">\n                            <p class=\"business-listing-feed__title\">Aspectos destacados del negocio<\/p>\n                                <\/div>\n        <div class=\"business-listing-feed__header-action\">\n                    <\/div>\n    <\/div>\n            <div class=\"business-listing-feed__cards --wide-size\">\n                            <div class=\"business-card --theme-tangerine\">\n                    <picture class=\"business-card__image-container\">\n                        <img decoding=\"async\" class=\"business-card__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/04\/lass-id-original-1540326985-5bcf8649245e6-300x171.jpg\" alt=\"Visitas a la mina Chollar\">\n                    <\/picture>\n                    <div class=\"business-card__info\">\n                        <p class=\"business-card__title\">Visitas a la mina Chollar<\/p>\n                        <p class=\"business-card__location\">Virginia City<\/p>\n                    <\/div>\n                    <a class=\"business-card__link\" href=\"https:\/\/travelnevada.com\/es\/minas-prospeccion\/visitas-a-la-mina-chollar\/\" aria-label=\"Visitas a la mina Chollar\"><\/a>\n                <\/div>\n                            <div class=\"business-card --theme-tangerine\">\n                    <picture class=\"business-card__image-container\">\n                        <img decoding=\"async\" class=\"business-card__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/gold-hill-hotel-and-bar-300x168.jpg\" alt=\"Hotel Gold Hill&#038; Sal\u00f3n\">\n                    <\/picture>\n                    <div class=\"business-card__info\">\n                        <p class=\"business-card__title\">Hotel Gold Hill&#038; Sal\u00f3n<\/p>\n                        <p class=\"business-card__location\">Virginia City<\/p>\n                    <\/div>\n                    <a class=\"business-card__link\" href=\"https:\/\/travelnevada.com\/es\/hoteles\/estadias-sin-igual\/hotel-gold-hill-salon\/\" aria-label=\"Hotel Gold Hill&#038; Sal\u00f3n\"><\/a>\n                <\/div>\n                            <div class=\"business-card --theme-tangerine\">\n                    <picture class=\"business-card__image-container\">\n                        <img decoding=\"async\" class=\"business-card__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/12\/washoe-club-alex-featured-300x169.jpg\" alt=\"El Club Washoe&#038; Museo Embrujado\">\n                    <\/picture>\n                    <div class=\"business-card__info\">\n                        <p class=\"business-card__title\">El Club Washoe&#038; Museo Embrujado<\/p>\n                        <p class=\"business-card__location\">Virginia City<\/p>\n                    <\/div>\n                    <a class=\"business-card__link\" href=\"https:\/\/travelnevada.com\/es\/museos\/el-club-washoe-museo-embrujado\/\" aria-label=\"El Club Washoe&#038; Museo Embrujado\"><\/a>\n                <\/div>\n                            <div class=\"business-card --theme-tangerine\">\n                    <picture class=\"business-card__image-container\">\n                        <img decoding=\"async\" class=\"business-card__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2014\/04\/fourth-ward-school-museum-300x168.jpg\" alt=\"Museo Hist\u00f3rico de la Escuela del Cuarto Distrito\">\n                    <\/picture>\n                    <div class=\"business-card__info\">\n                        <p class=\"business-card__title\">Museo Hist\u00f3rico de la Escuela del Cuarto Distrito<\/p>\n                        <p class=\"business-card__location\">Virginia City<\/p>\n                    <\/div>\n                    <a class=\"business-card__link\" href=\"https:\/\/travelnevada.com\/es\/museos\/museo-historico-de-la-escuela-del-cuarto-distrito\/\" aria-label=\"Museo Hist\u00f3rico de la Escuela del Cuarto Distrito\"><\/a>\n                <\/div>\n                    <\/div>\n    <\/section>\n","protected":false},"excerpt":{"rendered":"<p>La mayor\u00eda de los habitantes de Reno han visitado Virginia City. Pero \u00bfrealmente has experimentado el lugar? Si bien es posible que hayas asistido a algunos eventos anuales salvajes, hasta que hayas cazado fantasmas de bar, bailado un jig con lugare\u00f1os vestidos con atuendos victorianos o explorado una o dos minas subterr\u00e1neas.<\/p>\n","protected":false},"author":6,"featured_media":129715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_ecp_custom_30":"","_ecp_custom_31":"","_ecp_custom_32":"","_ecp_custom_33":"","_ecp_custom_34":"","_ecp_custom_35":"","_ecp_custom_36":"","footnotes":""},"categories":[220,230],"tags":[],"tn-regions":[122],"silos":[543],"class_list":["post-159475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-discover-your-nevada","category-itineraries"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>24 horas en Virginia City | Escapada r\u00e1pida cerca de Reno | Viajes por Nevada<\/title>\n<meta name=\"description\" content=\"Como habitante de Reno, probablemente hayas visitado Virginia City. Pero \u00bfrealmente has experimentado el lugar? Si bien es posible que hayas asistido a algunos eventos anuales salvajes, hasta que hayas cazado fantasmas de bar, bailado con lugare\u00f1os vestidos con atuendos victorianos o explorado una o dos minas subterr\u00e1neas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24 horas en Virginia City | Escapada r\u00e1pida cerca de Reno | Viajes por Nevada\" \/>\n<meta property=\"og:description\" content=\"Como habitante de Reno, probablemente hayas visitado Virginia City. Pero \u00bfrealmente has experimentado el lugar? Si bien es posible que hayas asistido a algunos eventos anuales salvajes, hasta que hayas cazado fantasmas de bar, bailado con lugare\u00f1os vestidos con atuendos victorianos o explorado una o dos minas subterr\u00e1neas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-02T00:25:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T19:16:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Susan Michelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@travelnevada\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"24 horas en Virginia City | Escapada r\u00e1pida cerca de Reno | Viajes por Nevada","description":"Como habitante de Reno, probablemente hayas visitado Virginia City. Pero \u00bfrealmente has experimentado el lugar? Si bien es posible que hayas asistido a algunos eventos anuales salvajes, hasta que hayas cazado fantasmas de bar, bailado con lugare\u00f1os vestidos con atuendos victorianos o explorado una o dos minas subterr\u00e1neas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/","og_locale":"es_ES","og_type":"article","og_title":"24 horas en Virginia City | Escapada r\u00e1pida cerca de Reno | Viajes por Nevada","og_description":"Como habitante de Reno, probablemente hayas visitado Virginia City. Pero \u00bfrealmente has experimentado el lugar? Si bien es posible que hayas asistido a algunos eventos anuales salvajes, hasta que hayas cazado fantasmas de bar, bailado con lugare\u00f1os vestidos con atuendos victorianos o explorado una o dos minas subterr\u00e1neas.","og_url":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","article_published_time":"2020-09-02T00:25:31+00:00","article_modified_time":"2025-07-31T19:16:12+00:00","og_image":[{"width":1140,"height":640,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg","type":"image\/jpeg"}],"author":"Susan Michelle","twitter_card":"summary_large_image","twitter_creator":"@travelnevada","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/#article","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/"},"author":{"name":"Susan Michelle","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/person\/75754fbf96139d1e9651eaf4dc439ed0"},"headline":"Ciudad de Virginia: Escapadas de una noche","datePublished":"2020-09-02T00:25:31+00:00","dateModified":"2025-07-31T19:16:12+00:00","mainEntityOfPage":{"@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/"},"wordCount":2433,"publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"image":{"@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg","articleSection":["Discover Your Nevada","Itineraries"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/","url":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/","name":"24 horas en Virginia City | Escapada r\u00e1pida cerca de Reno | Viajes por Nevada","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg","datePublished":"2020-09-02T00:25:31+00:00","dateModified":"2025-07-31T19:16:12+00:00","description":"Como habitante de Reno, probablemente hayas visitado Virginia City. Pero \u00bfrealmente has experimentado el lugar? Si bien es posible que hayas asistido a algunos eventos anuales salvajes, hasta que hayas cazado fantasmas de bar, bailado con lugare\u00f1os vestidos con atuendos victorianos o explorado una o dos minas subterr\u00e1neas.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg","width":1140,"height":640,"caption":"Comstock Gold Mill, Virginia City, Nevada"},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/ciudad-de-virginia-escapadas-de-una-noche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ciudad de Virginia: Escapadas de una noche"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]},{"@type":"Person","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/person\/75754fbf96139d1e9651eaf4dc439ed0","name":"Susan Michelle","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d371b28029dda53ef25014483401155b453d966d19d9758ce99e7fa76836f674?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d371b28029dda53ef25014483401155b453d966d19d9758ce99e7fa76836f674?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d371b28029dda53ef25014483401155b453d966d19d9758ce99e7fa76836f674?s=96&d=mm&r=g","caption":"Susan Michelle"}}]}},"featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top-300x168.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top-768x431.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top-1024x575.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/TN_StoryBusinessDetail_Top-Image-VCstory-business-detail-top.jpg"},"featured_image_alt":"","friendly_post_date":"September 01, 2020","primary_category":"Discover Your Nevada","primary_region":"Virginia City","_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/posts\/159475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/comments?post=159475"}],"version-history":[{"count":1,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/posts\/159475\/revisions"}],"predecessor-version":[{"id":159490,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/posts\/159475\/revisions\/159490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/129715"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=159475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=159475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tags?post=159475"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=159475"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=159475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}