{"id":159486,"date":"2017-07-10T14:35:28","date_gmt":"2017-07-10T21:35:28","guid":{"rendered":"https:\/\/travelnevada.com\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/"},"modified":"2025-07-31T12:16:09","modified_gmt":"2025-07-31T19:16:09","slug":"no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra","status":"publish","type":"post","link":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/","title":{"rendered":"NO LO CONVIERTAS EN UNO: El pino longevo es el \u00e1rbol m\u00e1s nudoso de la Tierra"},"content":{"rendered":"\n<p>Cuando se trata de atracciones, el Estado de Plata es el hogar de todo tipo de intrigantes recuerdos del pasado, desde pueblos fantasmas y salones del Viejo Oeste hasta f\u00f3siles y fen\u00f3menos geol\u00f3gicos. Pero en la parte superior de nuestra lista, encontrar\u00e1 el <em>Los seres vivos m\u00e1s antiguos del planeta<\/em>\u2014los fascinantes y resistentes pinos longevos de la Gran Cuenca, que desaf\u00edan los elementos. <\/p>\n\n<p>La mayor\u00eda de estos \u00e1rboles (literalmente) nudosos han estado vivos entre 3.000 y 5.000 a\u00f1os. Imag\u00ednenselos aferr\u00e1ndose a las rocas cuando los romanos estaban en su apogeo. S\u00ed, las pi\u00f1as longevas ya estaban vivas hace 1.500 a\u00f1os en ese entonces. \u00bfEl reinado de Cleopatra y la construcci\u00f3n de las pir\u00e1mides? Ya llevaban 2.000 a\u00f1os creciendo silenciosamente. La finalizaci\u00f3n de la Gran Muralla China, el desarrollo de la imprenta, el &amp;quot;descubrimiento&amp;quot; del Nuevo Mundo&#8230; la lista contin\u00faa. Estos chicos malos ya estaban dirigi\u00e9ndose hacia el cielo cuando todas esas cosas sucedieron. Y hoy, puedes caminar hasta ellos en las pistas de lo que ahora es <a href=\"https:\/\/travelnevada.com\/adventures\/32935\/13-reasons-great-basin-is-the-actual-worst\">Parque Nacional de la Gran Cuenca<\/a>. <\/p>\n\n<p>\u00bfEst\u00e1s buscando expandirte a nuevos territorios de viajes? Examine esta lista de datos curiosos, consejos e historia; luego venga a encontrarse cara a cara con una flora inusual que floreci\u00f3 al menos unos miles de a\u00f1os antes que usted.<\/p>\n\n<div\n    class=\"listicle-slider --theme-sand alignwide\">\n    <div class=\"listicle-slider__slider js-listicle-slider\">\n        <div class=\"listicle-slider__slider-wrapper swiper-wrapper\">\n            <!-- Slides -->\n                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecones15_SM-1024x576.jpg\"\n                                 alt=\"El pino longevo de la Gran Cuenca: el \u00e1rbol vivo m\u00e1s antiguo del planeta Tierra.\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone39_SM-1024x576.jpg\"\n                                 alt=\"El Parque Nacional Great Basin fue donde descubrimos por primera vez lo viejos que pod\u00edan ser estos chicos malos.\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/adventure-32975-original-1500665166-5972554ecf821.jpg\"\n                                 alt=\"La leyenda de Prometeo \">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/adventure-32975-original-1500660174-597241ce492f9-1024x576.jpg\"\n                                 alt=\"Puedes conocer a Prometeo t\u00fa mismo\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/09\/Bristlecones10_SM-1024x576.jpg\"\n                                 alt=\"Entonces \u00bfcu\u00e1l es su secreto? \u00bfC\u00f3mo han sobrevivido estas antiguas bellezas durante todo este tiempo?\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/adventure-32975-original-1500664796-597253dc79eae-scaled-1-1024x609.jpg\"\n                                 alt=\"El Mighty Wheeler Peak crea el escenario ambiental perfecto\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecones7_SM-1024x576.jpg\"\n                                 alt=\"\u00bfC\u00f3mo reconoces una pi\u00f1a longa cuando la ves?\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone29_SM-1024x576.jpg\"\n                                 alt=\"Espera, \u00bfpor qu\u00e9 este pino se llama &quot;pino longevo&quot;?\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone33_SM-1024x576.jpg\"\n                                 alt=\"Vayamos a la ra\u00edz del asunto.\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/adventure-32975-original-1500659656-59723fc81656d-1024x576.jpg\"\n                                 alt=\"Creciendo cent\u00edmetro a cent\u00edmetro, siglo a siglo\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone22_SM-1024x576.jpg\"\n                                 alt=\"Una carrera contra el cambio clim\u00e1tico\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone41_SM-1024x576.jpg\"\n                                 alt=\"\u00bfD\u00f3nde puedes ver con tus propios ojos antiguas pi\u00f1as longas?\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/adventure-32975-original-1500660174-597241ce5f773-1024x576.jpg\"\n                                 alt=\"En el Parque Nacional Great Basin, &quot;La mitad del parque est\u00e1 al anochecer&quot;\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/adventure-32975-original-1500659725-5972400d9a137-1024x576.jpg\"\n                                 alt=\"Nuestra \u00e9poca favorita para visitarnos\">\n                        <\/picture>\n                    <\/div>\n                                                                                <div class=\"listicle-slider__slide swiper-slide 21\">\n                        <picture class=\"listicle-slider__image-container\">\n                            <img decoding=\"async\" class=\"listicle-slider__image\" src=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/adventure-32975-original-1500659772-5972403c88e81.jpg\"\n                                 alt=\"\u00bfNo puedes llegar al Parque Nacional Great Basin? Las Vegas al rescate\u2026\">\n                        <\/picture>\n                    <\/div>\n                                    <\/div>\n    <\/div>\n\n    <div class=\"listicle-slider__intro-pane js-intro-pane\">\n        <div class=\"listicle-slider__slide-number\"><span class=\"js-current-slide\">1<\/span>\/<span class=\"js-slide-count\">1<\/span>\n        <\/div>\n        <button class=\"listicle-slider__start-button js-start-slideshow\">Ver presentacin<\/button>\n    <\/div>\n\n    <div class=\"listicle-slider__more-pane --theme-tangerine js-more-pane\">\n        <div class=\"listicle-slider__content\">\n            <!-- Content, one per slide -->\n                                            <div class=\"listicle-slider__slide-content --active js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">El pino longevo de la Gran Cuenca: el \u00e1rbol vivo m\u00e1s antiguo del planeta Tierra.<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>Con hasta 5.000 a\u00f1os de edad (y en ocasiones m\u00e1s de ellos), la mayor\u00eda de los cient\u00edficos consideran que el pino longevo es el organismo vivo m\u00e1s antiguo de la Tierra. En los \u00faltimos a\u00f1os, sin duda ha habido algunos conflictos serios que involucran a ciertos organismos menos &quot;precisamente mensurables&quot;, como las cianobacterias. Sin embargo, como es el &quot;organismo no clonal&quot; m\u00e1s antiguo de nuestro planeta, al menos es seguro decir que el \u00e1rbol longevo de la Gran Cuenca es la especie de \u00e1rbol viva m\u00e1s antigua. Lo tomaremos.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">El Parque Nacional Great Basin fue donde descubrimos por primera vez lo viejos que pod\u00edan ser estos chicos malos.<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>El Parque Nacional Great Basin fue donde se descubri\u00f3 originalmente la antig\u00fcedad del pino longevo, con un ejemplar que un cient\u00edfico que estudiaba la glaciolog\u00eda de la Edad de Hielo determin\u00f3 que ten\u00eda casi 4.900 a\u00f1os. (El parque alberga el \u00faltimo glaciar activo de Nevada). M\u00e1s tarde, en las Monta\u00f1as Blancas, que se extienden a lo largo de la frontera entre Nevada y California, por encima de Dyer (NV) y Bishop (California), se determin\u00f3 que otro ejemplar ten\u00eda unos 5.066 a\u00f1os de antig\u00fcedad. Dicho esto, Nevada todav\u00eda puede jactarse de ser el lugar donde se realiz\u00f3 el estudio innovador titulado simplemente &quot;El pino longevo es el \u00e1rbol m\u00e1s antiguo del mundo&quot;.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\"><\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">La leyenda de Prometeo <\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p><!-- wp:paragraph --><\/p>\n<p>Est\u00e1 Prometeo, el tit\u00e1n mitol\u00f3gico, que rob\u00f3 el fuego a Zeus y se lo devolvi\u00f3 a la humanidad, desencadenando nuestro desarrollo tecnol\u00f3gico. Y luego est\u00e1 Prometeo, el pino longevo, que ya era un \u00e1rbol maduro cuando Hes\u00edodo escribi\u00f3 por primera vez su primer poema a finales del siglo VIII a. C. En 1964, el glaci\u00f3logo Donald Currey lleg\u00f3 a Great Basin. Para ganar algo de impulso en su investigaci\u00f3n sobre la Edad de Hielo, se le concedi\u00f3 permiso para tomar muestras de n\u00facleos de pinos longevos, que se consideran &amp;quot;b\u00f3vedas clim\u00e1ticas&amp;quot; por los miles de a\u00f1os de datos meteorol\u00f3gicos &amp;quot;almacenados&amp;quot; dentro de sus anillos. Las cosas empezaron a ir mal cuando la pieza de su instrumento se rompi\u00f3 en el tronco de un \u00e1rbol y los guardabosques le permitieron recuperarla talando el \u00e1rbol. Cuando observaron sus anillos (los 4.862 que componen su estructura) de repente se dieron cuenta de que acababan de descubrir y matar simult\u00e1neamente al \u00e1rbol m\u00e1s antiguo conocido en la Tierra. (De hecho, como los \u00e1rboles no forman anillos en a\u00f1os excepcionalmente fr\u00edos, calcularon que ten\u00eda m\u00e1s bien 4.900 a\u00f1os). El \u00e1rbol fue bautizado como Prometeo, en honor al Tit\u00e1n, quien, despu\u00e9s de todo, tal vez se arrepinti\u00f3 de habernos devuelto ese fuego.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">Puedes conocer a Prometeo t\u00fa mismo<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>El hecho de que el \u00e1rbol m\u00e1s antiguo del mundo haya sido talado por motivos cient\u00edficos sigue siendo motivo de controversia para muchos. Sin embargo, la verdad es que, sin ese estudio, tal vez nunca hubi\u00e9ramos conocido la incre\u00edble verdad sobre los pinos longevos. (Algunas personas realmente asumieron que ya estaban muertos.)<\/p>\n<p>Despu\u00e9s de que sacaron a Prometeo de la monta\u00f1a, lo dividieron en pedazos para estudiarlo m\u00e1s a fondo. En la actualidad, un trozo de su tronco (al que los cient\u00edficos llaman &quot;galleta&quot;) se puede encontrar y apreciar en el Centro de Visitantes del Parque Nacional Great Basin.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Centro de visitantes de la Gran Cuenca<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">Entonces \u00bfcu\u00e1l es su secreto? \u00bfC\u00f3mo han sobrevivido estas antiguas bellezas durante todo este tiempo?<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>El pino longevo se encuentra exclusivamente en entornos de gran altitud, donde los inviernos fr\u00edos y duros se encuentran con veranos soleados y ventosos, y la mayor\u00eda de las arboledas encuentran su punto \u00f3ptimo a partir de los 5600 pies y se extienden hasta los 11 200, a menudo justo en el borde de la l\u00ednea de \u00e1rboles de otras especies de \u00e1rboles.<\/p>\n<p>De hecho, cuanto m\u00e1s elevada es la altitud en la que viven (y cuanto m\u00e1s duro es el clima que soportan), m\u00e1s adquieren sus ramas esas formas ic\u00f3nicamente retorcidas. Cuando finalmente mueren, en lugar de pudrirse como otros \u00e1rboles, la madera expuesta se desgasta lentamente y parece erosionarse, retorci\u00e9ndose en formas inusuales.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">El Mighty Wheeler Peak crea el escenario ambiental perfecto<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>Si visita el Parque Nacional Great Basin (mejor durante el verano y el oto\u00f1o), no puede perderse el Wheeler Peak, que roza el cielo con una altitud de 13.065 pies (la segunda m\u00e1s alta de Nevada) y se eleva 7.562 pies por encima de las estepas del alto desierto que se encuentran debajo. Elev\u00e1ndose sobre relucientes lagos alpinos, circos glaciares y algunos de los mejores lugares para acampar y hacer senderismo en Nevada, Wheeler es en realidad el pico m\u00e1s alto de una de las cadenas monta\u00f1osas m\u00e1s prominentes del estado m\u00e1s monta\u00f1oso de los 48 estados inferiores, as\u00ed como un h\u00e1bitat ideal para el pino longevo.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/hiking\/rutas-de-senderismo-de-great-basin\/\"\n                                   target=\"\">Pico Wheeler<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">\u00bfC\u00f3mo reconoces una pi\u00f1a longa cuando la ves?<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>El hecho de que la pi\u00f1a longa parezca estar muerta (pero no lo est\u00e1) es sorprendente en s\u00ed mismo. Muchos de estos \u00e1rboles tienen troncos muy elegantes que parecen desnudos y sin corteza, como si fueran otro tipo de pino que hubiera sido alcanzado por un rayo o que simplemente hubiera vivido una existencia hueca durante alg\u00fan tiempo. No se deje enga\u00f1ar, est\u00e9 atento a las peque\u00f1as ramitas de plumas que parecen cepillos de botella. Incluso si solo hay un peque\u00f1o grupo en la parte superior, esa cosa est\u00e1 muy viva y es id\u00e9ntica a un pino longevo vivo de la Gran Cuenca.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">Espera, \u00bfpor qu\u00e9 este pino se llama &quot;pino longevo&quot;?<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>Como la mayor\u00eda de los \u00e1rboles con\u00edferos, incluidos los de la variedad pino, el pino longevo produce pi\u00f1as aut\u00e9nticas. Los conos femeninos tienen puntas escamosas y espinosas, rematadas con cerdas similares a garras. Cerda + cono\u2026boom. Guarda esto en tu bolsillo trasero para tu pr\u00f3xima noche de trivia. (Quiz\u00e1s no literalmente, porque \u00a1ay!) De cualquier manera, eres bienvenido.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">Vayamos a la ra\u00edz del asunto.<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>Muchos pinos dependen de una sola ra\u00edz pivotante y utilizan ra\u00edces poco profundas justo debajo de la superficie para perseguir grietas en el suelo y detectar manchas de agua para enviar nutrientes hacia arriba. Las pi\u00f1as longas tambi\u00e9n hacen esto, s\u00f3lo que lo hacen de una manera m\u00e1s resistente y en un suelo mucho m\u00e1s duro. Incluso despu\u00e9s de una vida de resistencia, pueden comenzar lentamente a cerrar el flujo hacia las extremidades externas y aferrarse al tejido vivo m\u00e1s viable, durante siglos y siglos, lo que es parte de la raz\u00f3n por la que se erosionan en las formas salvajes por las que son conocidos, y pueden continuar haci\u00e9ndolo, despu\u00e9s de que realmente mueren.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">Creciendo cent\u00edmetro a cent\u00edmetro, siglo a siglo<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p><!-- wp:paragraph --><\/p>\n<p>Otra clave para la longevidad del pino longevo es su crecimiento lento y constante, que se puede atribuir a la combinaci\u00f3n de condiciones dif\u00edciles de su entorno, especialmente temperaturas g\u00e9lidas, suelos secos, vientos fuertes y temporadas de crecimiento cortas. Incluso los grupos de agujas del pino longevo pueden permanecer en el \u00e1rbol durante nada menos que 40 a\u00f1os (en comparaci\u00f3n con los 2 o 3 que duran la mayor\u00eda de los pinos). Esta lenta tasa de crecimiento tambi\u00e9n act\u00faa como una especie de mecanismo de defensa, ya que hace que la madera sea densa y pesada, lo que ayuda a protegerla de insectos, hongos, podredumbre y erosi\u00f3n.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">Una carrera contra el cambio clim\u00e1tico<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>Aunque una tasa de crecimiento lenta (resultado de eones de adaptaci\u00f3n) ha sido una ventaja para los conos longevos de la Gran Cuenca durante decenas de miles de a\u00f1os, puede que no siempre lo sea. Gracias al cambio clim\u00e1tico, los factores clim\u00e1ticos estacionales han cambiado de forma precipitada en los \u00faltimos 150 a\u00f1os; para estos antiguos organismos, apenas un momento, es poco probable que aprendan a acelerar su ritmo en un futuro pr\u00f3ximo. Aunque los cient\u00edficos a\u00fan tienen que clasificarlo m\u00e1s all\u00e1 de un riesgo de bajo nivel, se est\u00e1n siguiendo de cerca para asegurarse de que la disminuci\u00f3n de las poblaciones de los \u00e1rboles no se acelere antes de que estos \u00e1rboles puedan descubrir qu\u00e9 los afect\u00f3.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">\u00bfD\u00f3nde puedes ver con tus propios ojos antiguas pi\u00f1as longas?<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p><!-- wp:paragraph --><\/p>\n<p>El Parque Nacional Great Basin alberga m\u00faltiples arboledas de pino longevo. El m\u00e1s accesible es Bristlecone Grove, al que se llega en una caminata de ida y vuelta de 2,8 millas con calificaci\u00f3n moderada desde el incre\u00edble Wheeler Peak Campground. Durante los meses de verano, los guardabosques dirigen caminatas interpretativas; sin embargo, en cualquier momento en que el sendero est\u00e9 accesible, encontrar\u00e1 se\u00f1alizaci\u00f3n que le ayudar\u00e1 a descubrir cu\u00e1n especiales son estos \u00e1rboles. Mientras tanto, Mount Washington Grove y Eagle Peak Grove ofrecen grandes grupos de estas bellezas erosionadas por el clima, dos grandes recompensas para los excursionistas intr\u00e9pidos dispuestos a afrontar terrenos empinados y dif\u00edciles en senderos sin mantenimiento para ver bellezas antiguas de hasta 40 pies de altura.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parks-recreational-areas\/great-basin-national-park\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">En el Parque Nacional Great Basin, &quot;La mitad del parque est\u00e1 al anochecer&quot;<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>La falta de contaminaci\u00f3n lum\u00ednica del Parque Nacional Great Basin es tan reconocida que, en 2016, DarkSky lo design\u00f3 Parque Internacional de Cielo Oscuro. Es el hogar de uno de los \u00faltimos verdaderos &quot;entornos de cielo oscuro&quot; del pa\u00eds, que los cient\u00edficos consideran un recurso en peligro de extinci\u00f3n.<\/p>\n<p>Esta codiciada oscuridad va de la mano con el brillo de los cielos (en los que se pueden ver a simple vista planetas, constelaciones completas, la V\u00eda L\u00e1ctea e incluso galaxias enteras), as\u00ed como con la tranquilidad. Todos estos son factores de los que depende una amplia variedad de vida silvestre, incluido el pino longevo.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/observaci\u00f3n-de-estrellas\/observaci\u00f3n-de-estrellas-en-nevada\/\"\n                                   target=\"\">Observaci\u00f3n de estrellas en la Gran Cuenca<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">Nuestra \u00e9poca favorita para visitarnos<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>Realmente no puedes equivocarte siempre que el parque no est\u00e9 cubierto de nieve (desde el verano hasta el oto\u00f1o). Sin embargo, somos grandes fan\u00e1ticos de septiembre, cuando el follaje de hoja caduca (los \u00e1lamos son abundantes aqu\u00ed) explota con vitalidad y las temperaturas est\u00e1n en ese punto m\u00e1gico entre d\u00edas no demasiado calurosos y noches no demasiado fr\u00edas.<\/p>\n<p>Lo mejor de todo es que, a fines de septiembre, el parque organiza el Festival de Astronom\u00eda de la Gran Cuenca, gratuito, durante el cual guardabosques y profesionales de la astronom\u00eda comparten sus conocimientos y utilizan telescopios enormes y de alta potencia que, despu\u00e9s de un d\u00eda paseando entre \u00e1rboles antiguos que te hacen sentir joven, lo agravan todo con miradas de cerca al universo que te har\u00e1n sentir peque\u00f1o.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/viajes-en-carretera\/circuito-de-lake-tahoe\/\"\n                                   target=\"\">Parque Nacional Great Basin<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                                            <div class=\"listicle-slider__slide-content  js-slide-content\">\n                                            <p class=\"listicle-slider__slide-title\">\u00bfNo puedes llegar al Parque Nacional Great Basin? Las Vegas al rescate\u2026<\/p>\n                    \n                                            <div class=\"listicle-slider__slide-text-content --wizzy-headings\">\n                            <!-- WYSIWYG content -->\n                            <p>El Parque Nacional Great Basin puede ser el destino m\u00e1s conocido para observar pinos longevos. Sin embargo, adem\u00e1s de las arboledas que se encuentran en las cordilleras vecinas, las mencionadas Monta\u00f1as Blancas (donde reside el esp\u00e9cimen m\u00e1s antiguo conocido) y algunos lugares alrededor de Utah, la m\u00e1s grande de la Tierra se encuentra (cr\u00e9alo o no) justo en las afueras de la Capital Mundial del Entretenimiento. En las monta\u00f1as Spring, a lo largo de las laderas del Monte Charleston, el pico m\u00e1s prominente de Nevada, estos viejos y retorcidos animales est\u00e1n a la vista en todas partes, a lo largo de 18.000 acres de \u00e1rea silvestre.<\/p>\n\n                                                            <a class=\"listicle-slider__slide-cta\" href=\"https:\/\/travelnevada.com\/parques-y-areas-recreativas\/spring-mountains-and-the-mt-charleston-wilderness-area\/\"\n                                   target=\"\">\u00c1rea Recreativa Nacional de Spring Mountain<\/a>\n                                                    <\/div>\n                                                                                                    <\/div>\n                    <\/div>\n        <div class=\"listicle-slider__controls swiper-controls\">\n            <div class=\"swiper-button swiper-button-prev\">\n                <svg class=\"carat-icon\" viewBox=\"0 0 260 400\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path\n                        d=\"M176.338 269.424c-3.027 52.67-55.599 55.843-85.619 81.519-18.892 13.423-25.969 45.346-59.796 39.39-13.423-11.714-2.832-16.556 6.784-21.145-1.268-2.782-1.66-6.492-5.418-6.833-7.467 2.05-6.003 1.571-13.57 3.525-8.249-3.956-14.449-10.935-13.57-18.99.879-8.542 13.423-13.716 18.989-20.403.928-1.074-.734-4.198 0-5.418 2.098-3.516 9.664-8.104 14.936-13.62 8.64-8.884 13.619-17.377 24.505-21.722 4.149-.976 4.929 1.368 8.152 1.368 15.912-15.914 26.602-33.535 44.81-47.594 17.377-13.324 21.673-33.387 38.025-48.863-7.664-8.882-21.185-15.13-33.926-14.983-7.223-16.596-21.233-28.849-32.654-46.178-8.69-13.229-14.84-28.75-25.774-40.759-13.374-14.644-46.665-32.51-29.923-57.062 15.67-10.056 11.554-3.711 21.805 0 4.686-9.324-9.454-10.35 6.75-21.77C77.1 5.345 84.52 17.939 89.353 28.922c17.915 5.662 26.359 20.794 44.86 25.821.291 16.45 8.98 24.555 17.67 32.607 32.118 4.102 63.31 80.005 97.723 93.088 22.356 13.374-30.996 52.182-33.485 59.211-11.178 7.369-30.46 20.55-39.782 29.775z\"\n                        fill=\"#357387\" fill-rule=\"evenodd\"\/>\n                <\/svg>\n            <\/div>\n            <p class=\"listicle-slider__slide-number\"><span class=\"js-current-slide\">1<\/span>\/<span\n                    class=\"js-slide-count\">1<\/span><\/p>\n            <div class=\"swiper-button swiper-button-next\">\n                <svg class=\"carat-icon\" viewBox=\"0 0 260 400\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path\n                        d=\"M176.338 269.424c-3.027 52.67-55.599 55.843-85.619 81.519-18.892 13.423-25.969 45.346-59.796 39.39-13.423-11.714-2.832-16.556 6.784-21.145-1.268-2.782-1.66-6.492-5.418-6.833-7.467 2.05-6.003 1.571-13.57 3.525-8.249-3.956-14.449-10.935-13.57-18.99.879-8.542 13.423-13.716 18.989-20.403.928-1.074-.734-4.198 0-5.418 2.098-3.516 9.664-8.104 14.936-13.62 8.64-8.884 13.619-17.377 24.505-21.722 4.149-.976 4.929 1.368 8.152 1.368 15.912-15.914 26.602-33.535 44.81-47.594 17.377-13.324 21.673-33.387 38.025-48.863-7.664-8.882-21.185-15.13-33.926-14.983-7.223-16.596-21.233-28.849-32.654-46.178-8.69-13.229-14.84-28.75-25.774-40.759-13.374-14.644-46.665-32.51-29.923-57.062 15.67-10.056 11.554-3.711 21.805 0 4.686-9.324-9.454-10.35 6.75-21.77C77.1 5.345 84.52 17.939 89.353 28.922c17.915 5.662 26.359 20.794 44.86 25.821.291 16.45 8.98 24.555 17.67 32.607 32.118 4.102 63.31 80.005 97.723 93.088 22.356 13.374-30.996 52.182-33.485 59.211-11.178 7.369-30.46 20.55-39.782 29.775z\"\n                        fill=\"#357387\" fill-rule=\"evenodd\"\/>\n                <\/svg>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nevada es el hogar de la especie de \u00e1rbol viva m\u00e1s antigua del planeta. Ven a conocer cara a cara algunas especies de flora que florecieron cuatro o cinco mil a\u00f1os antes que t\u00fa.<\/p>\n","protected":false},"author":6,"featured_media":140249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_ecp_custom_30":"","_ecp_custom_31":"","_ecp_custom_32":"","_ecp_custom_33":"","_ecp_custom_34":"","_ecp_custom_35":"","_ecp_custom_36":"","footnotes":""},"categories":[243,13],"tags":[],"tn-regions":[36,16],"silos":[562],"class_list":["post-159486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-state-national-parks","category-hiking"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15 datos interesantes sobre el pino longevo | Bristlecone, Nevada<\/title>\n<meta name=\"description\" content=\"Nevada es el hogar de la especie de \u00e1rbol viva m\u00e1s antigua del planeta. Ven a conocer cara a cara algunas especies de flora que florecieron cuatro o cinco mil a\u00f1os antes que t\u00fa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 datos interesantes sobre el pino longevo | Bristlecone, Nevada\" \/>\n<meta property=\"og:description\" content=\"Nevada es el hogar de la especie de \u00e1rbol viva m\u00e1s antigua del planeta. Ven a conocer cara a cara algunas especies de flora que florecieron cuatro o cinco mil a\u00f1os antes que t\u00fa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-10T21:35:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T19:16:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Susan Michelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@travelnevada\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 datos interesantes sobre el pino longevo | Bristlecone, Nevada","description":"Nevada es el hogar de la especie de \u00e1rbol viva m\u00e1s antigua del planeta. Ven a conocer cara a cara algunas especies de flora que florecieron cuatro o cinco mil a\u00f1os antes que t\u00fa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/","og_locale":"es_ES","og_type":"article","og_title":"15 datos interesantes sobre el pino longevo | Bristlecone, Nevada","og_description":"Nevada es el hogar de la especie de \u00e1rbol viva m\u00e1s antigua del planeta. Ven a conocer cara a cara algunas especies de flora que florecieron cuatro o cinco mil a\u00f1os antes que t\u00fa.","og_url":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","article_published_time":"2017-07-10T21:35:28+00:00","article_modified_time":"2025-07-31T19:16:09+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg","type":"image\/jpeg"}],"author":"Susan Michelle","twitter_card":"summary_large_image","twitter_creator":"@travelnevada","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/#article","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/"},"author":{"name":"Susan Michelle","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/person\/75754fbf96139d1e9651eaf4dc439ed0"},"headline":"NO LO CONVIERTAS EN UNO: El pino longevo es el \u00e1rbol m\u00e1s nudoso de la Tierra","datePublished":"2017-07-10T21:35:28+00:00","dateModified":"2025-07-31T19:16:09+00:00","mainEntityOfPage":{"@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/"},"wordCount":249,"publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"image":{"@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg","articleSection":["State &amp; National Parks","Hiking"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/","url":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/","name":"15 datos interesantes sobre el pino longevo | Bristlecone, Nevada","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg","datePublished":"2017-07-10T21:35:28+00:00","dateModified":"2025-07-31T19:16:09+00:00","description":"Nevada es el hogar de la especie de \u00e1rbol viva m\u00e1s antigua del planeta. Ven a conocer cara a cara algunas especies de flora que florecieron cuatro o cinco mil a\u00f1os antes que t\u00fa.","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/no-lo-conviertas-en-uno-el-pino-longevo-es-el-arbol-mas-nudoso-de-la-tierra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"NO LO CONVIERTAS EN UNO: El pino longevo es el \u00e1rbol m\u00e1s nudoso de la Tierra"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]},{"@type":"Person","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/person\/75754fbf96139d1e9651eaf4dc439ed0","name":"Susan Michelle","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d371b28029dda53ef25014483401155b453d966d19d9758ce99e7fa76836f674?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d371b28029dda53ef25014483401155b453d966d19d9758ce99e7fa76836f674?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d371b28029dda53ef25014483401155b453d966d19d9758ce99e7fa76836f674?s=96&d=mm&r=g","caption":"Susan Michelle"}}]}},"featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM-300x169.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM-768x432.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM-1024x576.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2017\/07\/Bristlecone34_SM.jpg"},"featured_image_alt":"","friendly_post_date":"July 10, 2017","primary_category":"State &amp; National Parks","primary_region":"Baker","_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/posts\/159486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/comments?post=159486"}],"version-history":[{"count":1,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/posts\/159486\/revisions"}],"predecessor-version":[{"id":159498,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/posts\/159486\/revisions\/159498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/140249"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=159486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/categories?post=159486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tags?post=159486"},{"taxonomy":"tn-regions","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tn-regions?post=159486"},{"taxonomy":"silos","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/silos?post=159486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}