{"id":158850,"date":"2020-05-04T16:50:04","date_gmt":"2020-05-04T23:50:04","guid":{"rendered":"https:\/\/travelnevada.com\/event\/octane-fest\/"},"modified":"2025-07-31T10:45:33","modified_gmt":"2025-07-31T17:45:33","slug":"octane-fest","status":"publish","type":"tribe_events","link":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/","title":{"rendered":"Octane Fest"},"content":{"rendered":"\n<p>\u00a1Arranquen sus motores! Como uno de los eventos de carreras m\u00e1s emocionantes del a\u00f1o en Nevada, no hay mejor manera de sentir la emoci\u00f3n de los deportes de motor de calibre NHRA que el Octane Fest de Fallon. A una hora de Reno por la <a href=\"https:\/\/travelnevada.com\/road-trips\/loneliest-road-in-america\/\">La carretera m\u00e1s solitaria de Estados Unidos<\/a> Los amantes de los motores de todo Nevada y del Oeste se dirigen a The Oasis of Nevada para disfrutar de dos d\u00edas repletos de acci\u00f3n con carreras de aceleraci\u00f3n, camiones todoterreno, derbis de demolici\u00f3n y de polvo, motocross, carreras de figura en ocho con V6, concursos de quema de gases y mucho m\u00e1s.<\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00bfNecesitas velocidad extrema? No hay mejor manera de aumentar la adrenalina con una carrera de aceleraci\u00f3n, un derbi de demolici\u00f3n y un concurso de quema de neum\u00e1ticos a la vez que con este evento de carreras aprobado por la NHRA en <a href=\"https:\/\/travelnevada.com\/cities\/fallon\/\">El oasis de Nevada<\/a>. <\/p><\/blockquote><\/figure>\n\n<p>Para dar inicio a las c\u00e1lidas noches de verano de Fallon, el Octane Fest se celebra generalmente a mediados de junio de cada a\u00f1o en el Rattlesnake Raceway, en las afueras de Fallon, organizado por la Lahontan Auto Racing Association. El evento comienza con una programaci\u00f3n repleta de acci\u00f3n el viernes que contin\u00faa hasta el s\u00e1bado, presentando todo tipo de carreras de deportes de motor de alta potencia en dirt rack, como carreras de arrancones de demolici\u00f3n y m\u00e1s. Si no est\u00e1s al volante de tu propio coche, compra la entrada al estadio o consigue un pase de boxes. Entre carreras, dir\u00edgete al recinto ferial del condado de Churchill para disfrutar a\u00fan m\u00e1s de la diversi\u00f3n de los deportes de motor, como un concurso de camiones y tractores, un espect\u00e1culo de saltos de motocross estilo libre, camiones monstruo, el RatFest Rumble Car Show, la coronaci\u00f3n de Miss Octane, todo tipo de excelentes vendedores de comida y bebida y m\u00fasica en vivo que dura hasta la noche.<\/p>\n\n<p>Para obtener m\u00e1s informaci\u00f3n sobre Octane Fest, incluida una lista completa de eventos e informaci\u00f3n sobre los proveedores, visite <a href=\"https:\/\/www.rattlesnakeraceway.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">su sitio web<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfNecesitas velocidad extrema? No hay mejor manera de aumentar la adrenalina con una carrera de aceleraci\u00f3n, un derbi de demolici\u00f3n y un concurso de quema de neum\u00e1ticos a la vez que con este evento de carreras aprobado por la NHRA en el Oasis de Nevada.<\/p>\n","protected":false},"author":3,"featured_media":146359,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"Yoast SEO Relevanssi index exclude","inline_featured_image":false,"_EventAllDay":false,"_EventTimezone":"America\/Los_Angeles","_EventStartDate":"2023-06-09 18:00:00","_EventEndDate":"2023-06-10 19:00:00","_EventStartDateUTC":"2023-06-10 01:00:00","_EventEndDateUTC":"2023-06-11 02:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"https:\/\/www.facebook.com\/Octane-Fest-113064530441608\/","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[0],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_ecp_custom_30":"","_ecp_custom_31":"","_ecp_custom_32":"","_ecp_custom_33":"","_ecp_custom_34":"","_ecp_custom_35":"","_ecp_custom_36":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"adventure-level":[],"tribe_events_cat":[583,584],"class_list":["post-158850","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-eventos-al-aire-libre","tribe_events_cat-razas-deportes-para-espectadores","cat_eventos-al-aire-libre","cat_razas-deportes-para-espectadores"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Octane Fest | Eventos de carreras en Nevada | Rattlesnake Raceway<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Octane Fest | Eventos de carreras en Nevada | Rattlesnake Raceway\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita Nevada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelnevada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T17:45:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"632\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnevada\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Octane Fest | Eventos de carreras en Nevada | Rattlesnake Raceway","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Octane Fest | Eventos de carreras en Nevada | Rattlesnake Raceway","og_url":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/","og_site_name":"Visita Nevada","article_publisher":"https:\/\/www.facebook.com\/travelnevada","article_modified_time":"2025-07-31T17:45:33+00:00","og_image":[{"width":960,"height":632,"url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@travelnevada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/","url":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/","name":"Octane Fest | Eventos de carreras en Nevada | Rattlesnake Raceway","isPartOf":{"@id":"https:\/\/travelnevada.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/#primaryimage"},"image":{"@id":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/#primaryimage"},"thumbnailUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg","datePublished":"2020-05-04T23:50:04+00:00","dateModified":"2025-07-31T17:45:33+00:00","breadcrumb":{"@id":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelnevada.com\/es\/evento\/octane-fest\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/#primaryimage","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg","width":960,"height":632},{"@type":"BreadcrumbList","@id":"https:\/\/travelnevada.com\/es\/evento\/octane-fest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Visita Nevada","item":"https:\/\/travelnevada.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/travelnevada.com\/es\/eventos-tribales\/"},{"@type":"ListItem","position":3,"name":"Eventos al aire libre","item":"https:\/\/travelnevada.com\/es\/eventos-tribales\/category\/eventos-al-aire-libre\/"},{"@type":"ListItem","position":4,"name":"Octane Fest"}]},{"@type":"WebSite","@id":"https:\/\/travelnevada.com\/es\/#website","url":"https:\/\/travelnevada.com\/es\/","name":"Visita Nevada","description":"Vacaciones, hoteles y eventos en Nevada y Atracciones","publisher":{"@id":"https:\/\/travelnevada.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelnevada.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/travelnevada.com\/es\/#organization","name":"Visita Nevada","url":"https:\/\/travelnevada.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","contentUrl":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/travel-nevada-logo.jpg","width":225,"height":225,"caption":"Visita Nevada"},"image":{"@id":"https:\/\/travelnevada.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelnevada","https:\/\/x.com\/travelnevada","https:\/\/www.instagram.com\/travelnevada\/","https:\/\/www.linkedin.com\/company\/nevada-commission-on-tourism\/","https:\/\/www.pinterest.com\/TravelNV\/","https:\/\/www.youtube.com\/user\/TravelNevada"]}]}},"featured_image_url":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg","featured_image_url_sizes":{"thumbnail":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1-150x150.jpg","medium":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1-300x198.jpg","medium_large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1-768x506.jpg","large":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg","1536x1536":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg","2048x2048":"https:\/\/travelnevada.com\/wp-content\/uploads\/2020\/05\/9b5241f0e5ff435c989aec31b0291f08-1.jpg"},"featured_image_alt":"","friendly_post_date":"May 04, 2020","_links":{"self":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tribe_events\/158850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tribe_events\/158850\/revisions"}],"predecessor-version":[{"id":158855,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tribe_events\/158850\/revisions\/158855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media\/146359"}],"wp:attachment":[{"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/media?parent=158850"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tags?post=158850"},{"taxonomy":"adventure-level","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/adventure-level?post=158850"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/travelnevada.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=158850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}